{"id":314,"date":"2014-11-25T09:38:18","date_gmt":"2014-11-25T09:38:18","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=314"},"modified":"2014-11-25T09:38:18","modified_gmt":"2014-11-25T09:38:18","slug":"prueba-cdi","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2014\/11\/25\/prueba-cdi\/","title":{"rendered":"PRUEBA CDI"},"content":{"rendered":"<p><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">Informaci\u00f3n y modelos sobre las pruebas de Conocimientos y Destrezas Indispensables (CDI) realizadas en 6\u00ba de Educaci\u00f3n Primaria en los Centros Educativos de la Comunidad de Madrid.<\/span><\/p>\n<p><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">Pinchar sobre el enlace:<\/span><\/p>\n<p><a href=\"http:\/\/www.educa2.madrid.org\/web\/cdi\/pruebas-cdi\">http:\/\/www.educa2.madrid.org\/web\/cdi\/pruebas-cdi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n y modelos sobre las pruebas de Conocimientos y Destrezas Indispensables (CDI) realizadas en 6\u00ba de Educaci\u00f3n Primaria en los Centros Educativos de la Comunidad de Madrid. Pinchar sobre el enlace: http:\/\/www.educa2.madrid.org\/web\/cdi\/pruebas-cdi<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-314","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Informaci\u00f3n y modelos sobre las pruebas de Conocimientos y Destrezas Indispensables (CDI) realizadas en 6\u00ba de Educaci\u00f3n Primaria en los Centros Educativos de la Comunidad de Madrid. Pinchar sobre el enlace: http:\/\/www.educa2.madrid.org\/web\/cdi\/pruebas-cdi","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=314"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/314\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=314"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}