{"id":3144,"date":"2020-01-24T13:52:24","date_gmt":"2020-01-24T13:52:24","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/informacion-disfraz-carnaval-4-anos\/"},"modified":"2020-01-24T13:52:24","modified_gmt":"2020-01-24T13:52:24","slug":"informacion-disfraz-carnaval-4-anos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/01\/24\/informacion-disfraz-carnaval-4-anos\/","title":{"rendered":"INFORMACI\u00d3N DISFRAZ CARNAVAL 4 A\u00d1OS"},"content":{"rendered":"<div>Queridas familias:<\/div>\n<div>Os comunicamos que este a\u00f1o para la actividad de centro de carnaval iremos disfrazados de \u00abVaqueros de Rodeo\u00bb.<\/div>\n<div>La base del disfraz ser\u00e1:<\/div>\n<ul>\n<li>\n<div>Pantal\u00f3n vaquero<\/div>\n<\/li>\n<li>\n<div>Camisa de cuadros o camiseta blanca de manga larga.<\/div>\n<\/li>\n<li>\n<div>Botas o cubrebotas marr\u00f3n o negro.<\/div>\n<\/li>\n<\/ul>\n<div>Tened en cuenta que, si el d\u00eda de carnaval (21 de febrero) es un d\u00eda fr\u00edo, deber\u00e9is poner a los ni\u00f1os\/as ropa que abrigue debajo de la camisa y el pantal\u00f3n (camiseta t\u00e9rmica, forro polar, leotardos, etc&#8230;).<\/div>\n<div>\u00a0<\/div>\n<div>Se os facilitar\u00e1 un trozo de tela para realizar el chaleco y los zahones, as\u00ed como un patr\u00f3n. Una vez elaborado, os pediremos que lo traig\u00e1is para decorarlo con los ni\u00f1os en los talleres. En dichos talleres tambi\u00e9n confeccionaremos los sombreros.<\/div>\n<div>\u00a0<\/div>\n<div>Atentamente.<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Tutores de 4 a\u00f1os.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Queridas familias: Os comunicamos que este a\u00f1o para la actividad de centro de carnaval iremos disfrazados de \u00abVaqueros de Rodeo\u00bb. La base del disfraz ser\u00e1: Pantal\u00f3n vaquero Camisa de cuadros o camiseta blanca de manga larga. Botas o cubrebotas marr\u00f3n o negro. Tened en cuenta que, si el d\u00eda de carnaval (21 de febrero) es &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/01\/24\/informacion-disfraz-carnaval-4-anos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abINFORMACI\u00d3N DISFRAZ CARNAVAL 4 A\u00d1OS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"post_folder":[],"class_list":["post-3144","post","type-post","status-publish","format-standard","hentry","category-4-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/4-anos\/\" rel=\"category tag\">4 A\u00f1os<\/a>","rttpg_excerpt":"Queridas familias: Os comunicamos que este a\u00f1o para la actividad de centro de carnaval iremos disfrazados de \u00abVaqueros de Rodeo\u00bb. La base del disfraz ser\u00e1: Pantal\u00f3n vaquero Camisa de cuadros o camiseta blanca de manga larga. Botas o cubrebotas marr\u00f3n o negro. Tened en cuenta que, si el d\u00eda de carnaval (21 de febrero) es&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3144"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3144\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3144"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}