{"id":3173,"date":"2020-02-05T05:42:41","date_gmt":"2020-02-05T05:42:41","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/equipos-de-atletismo-del-colegio-de-3-4-5-y-6-de-primaria\/"},"modified":"2020-02-05T05:42:41","modified_gmt":"2020-02-05T05:42:41","slug":"equipos-de-atletismo-del-colegio-de-3-4-5-y-6-de-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/02\/05\/equipos-de-atletismo-del-colegio-de-3-4-5-y-6-de-primaria\/","title":{"rendered":"EQUIPOS DE ATLETISMO DEL COLEGIO DE 3\u00ba, 4\u00ba, 5\u00ba Y 6\u00ba DE PRIMARIA"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Todos los martes, a la hora del recreo<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">, nuestro monitor deportivo, Samuel, entrenar\u00e1 en el pabell\u00f3n a los alumnos\/as de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria para el Campeonato de Atletismo Escolar.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EP1-qbxXUAEAYV0?format=jpg&amp;name=medium\" alt=\"Imagen\" \/><\/span><\/p>\n<p>\u00a0<\/p>\n<p>Para saber m\u00e1s informaci\u00f3n sobre el evento deportivo organizado por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pincha en el siguiente art\u00edculo:<\/p>\n<p><a href=\"http:\/\/www.colegiocarlosiii.es\/deportes-destacado\/3158-campeonato-escolar-de-atletismo-2019-2020\" target=\"_blank\" rel=\"alternate noopener noreferrer\">http:\/\/www.colegiocarlosiii.es\/deportes-destacado\/3158-campeonato-escolar-de-atletismo-2019-2020<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los martes, a la hora del recreo, nuestro monitor deportivo, Samuel, entrenar\u00e1 en el pabell\u00f3n a los alumnos\/as de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria para el Campeonato de Atletismo Escolar. \u00a0 Para saber m\u00e1s informaci\u00f3n sobre el evento deportivo organizado por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pincha en el &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/02\/05\/equipos-de-atletismo-del-colegio-de-3-4-5-y-6-de-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEQUIPOS DE ATLETISMO DEL COLEGIO DE 3\u00ba, 4\u00ba, 5\u00ba Y 6\u00ba DE PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-3173","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Todos los martes, a la hora del recreo, nuestro monitor deportivo, Samuel, entrenar\u00e1 en el pabell\u00f3n a los alumnos\/as de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria para el Campeonato de Atletismo Escolar. \u00a0 Para saber m\u00e1s informaci\u00f3n sobre el evento deportivo organizado por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez pincha en el&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3173"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3173\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3173"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}