{"id":3200,"date":"2020-02-27T12:55:22","date_gmt":"2020-02-27T12:55:22","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/coronavirus-sars-cov-y-recomendaciones\/"},"modified":"2020-02-27T12:55:22","modified_gmt":"2020-02-27T12:55:22","slug":"coronavirus-sars-cov-y-recomendaciones","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/02\/27\/coronavirus-sars-cov-y-recomendaciones\/","title":{"rendered":"COMUNICADO CONSEJER\u00cdA DE EDUCACI\u00d3N Y JUVENTUD"},"content":{"rendered":"<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 14pt;\">Estimadas familias:<\/span><\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 14pt;\">En el d\u00eda de hoy hemos recibido un comunicado de la Consejer\u00eda de Educaci\u00f3n para que sea transmitido a toda la comunidad educativa. En el archivo adjunto pod\u00e9is verlo.<\/span><\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 14pt;\">Rogamos se sigan las recomendaciones que en el se aconsejan y que se utilicen los cauces de informaci\u00f3n facilitados en dicho comunicado, enlaces web que permitir\u00e1n una actualizaci\u00f3n permanente de las informaciones.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/ESTUkg_XkAI_F9U?format=jpg&amp;name=large\" alt=\"Imagen\" width=\"748\" height=\"1064\" \/><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<span style=\"font-family: comic sans ms,sans-serif; font-size: 14pt;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 EQUIPO DIRECTIVO<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: En el d\u00eda de hoy hemos recibido un comunicado de la Consejer\u00eda de Educaci\u00f3n para que sea transmitido a toda la comunidad educativa. En el archivo adjunto pod\u00e9is verlo. Rogamos se sigan las recomendaciones que en el se aconsejan y que se utilicen los cauces de informaci\u00f3n facilitados en dicho comunicado, enlaces web &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/02\/27\/coronavirus-sars-cov-y-recomendaciones\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO CONSEJER\u00cdA DE EDUCACI\u00d3N Y JUVENTUD\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-3200","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Estimadas familias: En el d\u00eda de hoy hemos recibido un comunicado de la Consejer\u00eda de Educaci\u00f3n para que sea transmitido a toda la comunidad educativa. En el archivo adjunto pod\u00e9is verlo. Rogamos se sigan las recomendaciones que en el se aconsejan y que se utilicen los cauces de informaci\u00f3n facilitados en dicho comunicado, enlaces web&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3200"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3200\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3200"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}