{"id":337,"date":"2014-12-05T13:21:45","date_gmt":"2014-12-05T13:21:45","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=337"},"modified":"2014-12-05T13:21:45","modified_gmt":"2014-12-05T13:21:45","slug":"dia-internacional-de-la-discapacidad","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2014\/12\/05\/dia-internacional-de-la-discapacidad\/","title":{"rendered":"D\u00cdA INTERNACIONAL DE LA DISCAPACIDAD"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">Durante la ma\u00f1ana del 5 de diciembre, los alumnos y alumnas de 6\u00ba de Primaria, han realizado distintas actividades con los siguientes objetivos:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Sensibilizar a los alumnos\/as para conocer mejor la realidad que les rodea y adquieran una mayor comprensi\u00f3n y respeto hacia las personas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Promover la toma de conciencia respecto a las capacidades y aportaciones de las personas con discapacidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Luchar contra los estereotipos y los prejuicios que tenemos sobre algunos grupos de personas, fomentando el respeto a la diversidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Experimentar en su propia piel, los problemas con los que se encuentran algunas seres humanos en su d\u00eda a d\u00eda.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">La actividad ha constado de dos partes; una primera pr\u00e1ctica, con juegos y actividades adaptadas (juegos de las sillas musicales y del pa\u00f1uelo con los ojos tapados, deportes sin posibilidad de desplazarte).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3287\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg\" alt=\"\" width=\"384\" height=\"288\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg 1280w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-768x576.jpg 768w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3288\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0006.jpg\" alt=\"\" width=\"381\" height=\"288\" \/><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">La segunda ha consistido en una charla de Juan Luis (miembro de la O.N.C.E.), sobre el sentido de la vista, deficiencias visuales, situaciones cotidianas de las personas con una discapacidad visual, el sistema de escritura para personas ciegas \u00abBraille\u00bb, &#8230;. nos ha ense\u00f1ado el funcionamiento de una m\u00e1quina de escribir para personas ciegas (una Perkins), un libro de texto de una alumno de 1\u00ba ESO escrito en Braille.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3289\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0005.jpg\" alt=\"\" width=\"268\" height=\"200\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0005.jpg 1280w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0005-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0005-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0005-768x576.jpg 768w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3290\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/BRAILLE.jpg\" alt=\"\" width=\"243\" height=\"197\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/BRAILLE.jpg 778w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/BRAILLE-300x244.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/BRAILLE-768x624.jpg 768w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3291\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0009.jpg\" alt=\"\" width=\"263\" height=\"198\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0009.jpg 1280w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0009-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0009-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0009-768x576.jpg 768w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">Juan Luis, ante el inter\u00e9s y las preguntas de los ni\u00f1os\/as, nos comunica que seguir\u00e1 trayendo material, para que conozcamos mejor posible el mundo de las personas con discapacidad y nos ense\u00f1ar\u00e1 a escribir y leer en el sistema Braille.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">Durante la ma\u00f1ana del 5 de diciembre, los alumnos y alumnas de 6\u00ba de Primaria, han realizado distintas actividades con los siguientes objetivos:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Sensibilizar a los alumnos\/as para conocer mejor la realidad que les rodea y adquieran una mayor comprensi\u00f3n y respeto hacia las personas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Promover la toma de conciencia respecto a las capacidades y aportaciones de las personas con discapacidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0&#8211; Luchar contra los estereotipos y los prejuicios que tenemos sobre algunos grupos de personas, fomentando el respeto a la diversidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: 'comic sans ms', sans-serif;\">\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Experimentar en su propia piel, los problemas con los que se encuentran algunas seres humanos en su d\u00eda a d\u00eda.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"author":3,"featured_media":3287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-300x225.jpg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-1024x768.jpg",525,394,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2014\/12\/IMG-20141205-WA0010.jpg",1280,960,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Durante la ma\u00f1ana del 5 de diciembre, los alumnos y alumnas de 6\u00ba de Primaria, han realizado distintas actividades con los siguientes objetivos: \u00a0 \u00a0 \u00a0- Sensibilizar a los alumnos\/as para conocer mejor la realidad que les rodea y adquieran una mayor comprensi\u00f3n y respeto hacia las personas. \u00a0 \u00a0 \u00a0- Promover la toma de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=337"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3287"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=337"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}