{"id":477,"date":"2015-03-24T12:19:08","date_gmt":"2015-03-24T12:19:08","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=477"},"modified":"2015-03-24T12:19:08","modified_gmt":"2015-03-24T12:19:08","slug":"iii-concurso-de-cuento-relato-corto-y-otros-estilos-literarios-el-comic","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/03\/24\/iii-concurso-de-cuento-relato-corto-y-otros-estilos-literarios-el-comic\/","title":{"rendered":"III CONCURSO DE CUENTO, RELATO CORTO Y OTROS ESTILOS LITERARIOS"},"content":{"rendered":"<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'comic sans ms', sans-serif;\"><span style=\"font-size: 18pt;\"><strong>Bases III Concurso \u00a0Literario<\/strong><\/span><span style=\"font-size: 18pt;\"><strong>\u00a0<span style=\"font-size: 24pt;\">\u201cEl c\u00f3mic\u201d.<\/span><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>CURSO: 2014- 2015<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p>1.- <strong>PARTICIPANTES<\/strong>:<\/p>\n<p>Puede participar todo el alumnado del Centro, desde E. Infantil (3 a\u00f1os) a los de 6\u00ba de Primaria.<\/p>\n<p>2.- <strong>FORMATO<\/strong>:<\/p>\n<p>Se adaptar\u00e1, seg\u00fan las edades del alumnado, a distintas t\u00e9cnicas pict\u00f3ricas y distintos tipos de vi\u00f1etas. Se presentar\u00e1n en tama\u00f1o folio.<\/p>\n<ul>\n<li>3, 4, 5 A\u00d1OS 1\u00ba, 2\u00ba y 3\u00ba de PRIMARIA\u00a0 <strong>hasta 5 folios<\/strong><\/li>\n<li>4\u00ba, 5\u00ba Y 6\u00ba <strong>hasta 3 folios incluida la portada<\/strong><\/li>\n<\/ul>\n<p>3.- <strong>PORTADA<\/strong>:<\/p>\n<p>Para evitar confusiones, en la portada se pondr\u00e1 el T\u00cdTULO del c\u00f3mic,\u00a0 el N\u00daMERO DE LISTA D EL ALUMNO-A, Y EL CURSO AL QUE PERTENECE.<\/p>\n<p>El tutor-a guardar\u00e1 escrupulosamente estas normas y recoger\u00e1 a su vez en un folio, el t\u00edtulo del c\u00f3mic y el nombre del alumno-a.<\/p>\n<p>4.- <strong>TEMA<\/strong>:<\/p>\n<p>Tema para 6\u00ba, 5\u00ba y 4\u00ba Primaria: <strong>LA M\u00daSICA<\/strong> (seg\u00fan las instrucciones dadas en aula a los alumnos).<\/p>\n<p>Tema para 3\u00ba, 2\u00ba y 1\u00ba de Primaria y para 5, 4 y 3 a\u00f1os: <strong>LIBRE.<\/strong><\/p>\n<p>5.- <strong>ENTREGA DE TRABAJOS:<\/strong><\/p>\n<p>Se har\u00e1 entrega de los trabajos al tutor-a dentro del plazo marcado. NO SE RECOGER\u00c1N DESPU\u00c9S DE LA FECHA MARCADA COMO L\u00cdMITE DE ENTREGA.<\/p>\n<p>\u00a0<\/p>\n<p>6.- <strong>PLAZO DE PRESENTACI\u00d3N: <\/strong>Terminar\u00e1 el d\u00eda\u00a0 <strong>16 de abril.<\/strong><\/p>\n<p>7.- Cada alumno deber\u00e1 presentar UNA \u00daNICA OBRA IN\u00c9DITA, escrita a mano y en castellano.<\/p>\n<p>8.- El JURADO estar\u00e1 compuesto por maestros no adscritos al ciclo o tramo en los que fallen los premios. Se adjudicar\u00e1n premios en todas las categor\u00edas.<\/p>\n<p>9.- <strong>FALLO DEL JURADO<\/strong>: Se dar\u00e1 a conocer el 23 de abril, d\u00eda del libro<\/p>\n<p>10.- <strong>VALORACI\u00d3N<\/strong>:<\/p>\n<p>Se valorar\u00e1:<\/p>\n<p>&#8211; Inter\u00e9s del tema tratado<\/p>\n<p>&#8211; Creatividad y expresi\u00f3n de la imagen<\/p>\n<p>&#8211; Legibilidad de la letra<\/p>\n<p>11.- Los trabajos presentados quedar\u00e1n a disposici\u00f3n de la Biblioteca Escolar del colegio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Bases III Concurso \u00a0Literario\u00a0\u201cEl c\u00f3mic\u201d. CURSO: 2014- 2015 \u00a0 1.- PARTICIPANTES: Puede participar todo el alumnado del Centro, desde E. Infantil (3 a\u00f1os) a los de 6\u00ba de Primaria. 2.- FORMATO: Se adaptar\u00e1, seg\u00fan las edades del alumnado, a distintas t\u00e9cnicas pict\u00f3ricas y distintos tipos de vi\u00f1etas. Se presentar\u00e1n en tama\u00f1o folio. 3, 4, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/03\/24\/iii-concurso-de-cuento-relato-corto-y-otros-estilos-literarios-el-comic\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abIII CONCURSO DE CUENTO, RELATO CORTO Y OTROS ESTILOS LITERARIOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-477","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"\u00a0 Bases III Concurso \u00a0Literario\u00a0\u201cEl c\u00f3mic\u201d. CURSO: 2014- 2015 \u00a0 1.- PARTICIPANTES: Puede participar todo el alumnado del Centro, desde E. Infantil (3 a\u00f1os) a los de 6\u00ba de Primaria. 2.- FORMATO: Se adaptar\u00e1, seg\u00fan las edades del alumnado, a distintas t\u00e9cnicas pict\u00f3ricas y distintos tipos de vi\u00f1etas. Se presentar\u00e1n en tama\u00f1o folio. 3, 4,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=477"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}