{"id":536,"date":"2015-05-06T09:59:51","date_gmt":"2015-05-06T09:59:51","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=536"},"modified":"2015-05-06T09:59:51","modified_gmt":"2015-05-06T09:59:51","slug":"las-tablets-en-4","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/05\/06\/las-tablets-en-4\/","title":{"rendered":"LAS TABLETS SON GENIALES"},"content":{"rendered":"<p>las tablets son geniales. Hay juegos y actividades de lengua, matem\u00e1ticas, ingl\u00e9s,&#8230; Son una forma m\u00e1s divertida de aprender. Los ni\u00f1os estamos contentos porque nos gustan m\u00e1s escribir en una pantalla con un tec\u00f1ado digital, que tener que escribir con un l\u00e1piz o un boli en un papel.<\/p>\n<p>Los 3 cursos de 4\u00ba, compartimos las tablets. Entramos en Snappet y elegimos las actividades que queremos hacer. Si fallamos al hacer el ejercicio, en la pantalla de la profe nos pone una cruz roja y se\u00f1ala que est\u00e1 mal; si aciertas te pone un tic verde y sigues.\u00a0<\/p>\n<p>Esta actividad emepz\u00f3 el 30 de abril de 2015, ha sido una gran idea, bueno eso es todo.<\/p>\n<p>Jaime (4\u00baA)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad.xx.fbcdn.net\/hphotos-xtp1\/v\/t1.0-9\/11041633_913214808736203_924493452121037546_n.jpg?oh=e5745d776dad9ec0dda95ebbfc5ec6d8&amp;oe=55DA4530\" alt=\"\" width=\"284\" height=\"189\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/11188391_913214785402872_3600962180318685560_n.jpg?oh=20ca3a68bebdd512e12282b414a1acec&amp;oe=55C00A43\" alt=\"\" width=\"287\" height=\"191\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad.xx.fbcdn.net\/hphotos-xat1\/v\/t1.0-9\/11193347_913214825402868_4577338443161478672_n.jpg?oh=512c979e2a63f16453a2e662fe1e4a00&amp;oe=55C4B637\" alt=\"\" width=\"314\" height=\"209\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad.xx.fbcdn.net\/hphotos-xpt1\/v\/t1.0-9\/11193347_913214742069543_1255321989429236450_n.jpg?oh=34bb4b4764b2f247e746b62c792886af&amp;oe=55D2350D\" alt=\"\" width=\"315\" height=\"209\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad.xx.fbcdn.net\/hphotos-xpf1\/v\/t1.0-9\/11196247_913214698736214_8283397918365466089_n.jpg?oh=2370f97f343ef48bf951186fcd0d8417&amp;oe=55C36A75\" alt=\"\" width=\"321\" height=\"213\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>las tablets son geniales. Hay juegos y actividades de lengua, matem\u00e1ticas, ingl\u00e9s,&#8230; Son una forma m\u00e1s divertida de aprender. Los ni\u00f1os estamos contentos porque nos gustan m\u00e1s escribir en una pantalla con un tec\u00f1ado digital, que tener que escribir con un l\u00e1piz o un boli en un papel. Los 3 cursos de 4\u00ba, compartimos las &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/05\/06\/las-tablets-en-4\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLAS TABLETS SON GENIALES\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-536","post","type-post","status-publish","format-standard","hentry","category-4-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/4-primaria\/\" rel=\"category tag\">4\u00ba Primaria<\/a>","rttpg_excerpt":"las tablets son geniales. Hay juegos y actividades de lengua, matem\u00e1ticas, ingl\u00e9s,&#8230; Son una forma m\u00e1s divertida de aprender. Los ni\u00f1os estamos contentos porque nos gustan m\u00e1s escribir en una pantalla con un tec\u00f1ado digital, que tener que escribir con un l\u00e1piz o un boli en un papel. Los 3 cursos de 4\u00ba, compartimos las&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=536"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}