{"id":548,"date":"2015-05-18T10:01:37","date_gmt":"2015-05-18T10:01:37","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=548"},"modified":"2015-05-18T10:01:37","modified_gmt":"2015-05-18T10:01:37","slug":"resultado-cross-litterator-alumnos-del-colegio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/05\/18\/resultado-cross-litterator-alumnos-del-colegio\/","title":{"rendered":"RESULTADO CROSS LITTERATOR ALUMNOS DEL COLEGIO"},"content":{"rendered":"<p>A continuaci\u00f3n y gracias a Jos\u00e9 \u00c1ngel (Diario Deportivo Ribere\u00f1o CAmpeones) os presentamos a los atletas del colegio que quedaron entre los tres primeros de su prueba en el Cross del Colegio Litterator, celebrado el domingo 17 de mayo de 2015.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-6YJ9IikbyB4\/VVjZJtpyFAI\/AAAAAAABmHw\/GgEK76zDnUk\/s400\/Alev%C3%ADn%2BFem%2B(FILEminimizer).JPG\" alt=\"\" width=\"356\" height=\"533\" \/><\/p>\n<p>Categor\u00eda Alev\u00edn Femenino: Irene Romero 3\u00aa<\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-7zfvdz90A8A\/VVjZcngaLUI\/AAAAAAABmJo\/3VViPOz4Z6w\/s400\/Renacuajo%2BCom%2BMas%2B(FILEminimizer).JPG\" alt=\"\" width=\"356\" height=\"533\" \/><\/p>\n<p>Categor\u00eda Renacuajo Competici\u00f3n Masculino: Daniel Mateo 2\u00ba<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-E-cMruP8Sn0\/VVjZO8iJC1I\/AAAAAAABmIU\/F_rbBh3yydg\/s400\/Renacuajo%2BIni%2BMas%2B(FILEminimizer).JPG\" alt=\"\" width=\"355\" height=\"532\" \/><\/p>\n<p>Categor\u00eda Renacuajo Iniciaci\u00f3n Masculino: Alejandro Mateo 2\u00ba<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-O93IB6wEDl8\/VVjZUqcUyyI\/AAAAAAABmJM\/x9QC3M6FmWY\/s400\/Litteratillo%2BFem%2B(FILEminimizer).JPG\" alt=\"\" width=\"354\" height=\"530\" \/><\/p>\n<p>Categor\u00eda Litteratillos Femenino (3 A\u00d1OS): In\u00e9s Guardiola 2\u00ba<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-1A84ldfypzc\/VVjZUq9KdHI\/AAAAAAABmI8\/ShMRzx_SgDs\/s400\/Litteratillo%2BMas%2B(FILEminimizer).JPG\" alt=\"\" width=\"352\" height=\"527\" \/><\/p>\n<p>Categor\u00eda Litteratillos Masculino (3 A\u00d1OS): Lucas Rubio 1\u00ba y Dar\u00edo Mengue 2\u00ba\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n y gracias a Jos\u00e9 \u00c1ngel (Diario Deportivo Ribere\u00f1o CAmpeones) os presentamos a los atletas del colegio que quedaron entre los tres primeros de su prueba en el Cross del Colegio Litterator, celebrado el domingo 17 de mayo de 2015.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-6YJ9IikbyB4\/VVjZJtpyFAI\/AAAAAAABmHw\/GgEK76zDnUk\/s400\/Alev%C3%ADn%2BFem%2B(FILEminimizer).JPG\" alt=\"\" width=\"356\" height=\"533\" \/><\/p>\n<p>Categor\u00eda Alev\u00edn Femenino: Irene Romero 3\u00aa<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-548","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"A continuaci\u00f3n y gracias a Jos\u00e9 \u00c1ngel (Diario Deportivo Ribere\u00f1o CAmpeones) os presentamos a los atletas del colegio que quedaron entre los tres primeros de su prueba en el Cross del Colegio Litterator, celebrado el domingo 17 de mayo de 2015. Categor\u00eda Alev\u00edn Femenino: Irene Romero 3\u00aa","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=548"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}