{"id":560,"date":"2015-05-25T09:40:37","date_gmt":"2015-05-25T09:40:37","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=560"},"modified":"2015-05-25T09:40:37","modified_gmt":"2015-05-25T09:40:37","slug":"hoy-no-somos-los-mas-pequenos-del-colegio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/05\/25\/hoy-no-somos-los-mas-pequenos-del-colegio\/","title":{"rendered":"HOY LOS DE 3 A\u00d1OS, NO SOMOS LOS M\u00c1S PEQUE\u00d1OS DEL COLEGIO"},"content":{"rendered":"<p>Los alumnos y alumnas de 3 a\u00f1os han recibido la visita de los ni\u00f1os y ni\u00f1as de 2 a\u00f1os de la EEI Jardines de Aranjuez, un total de 60 ni\u00f1os y ni\u00f1as de la Escuela Infantil han compartido con nuestros grupos de 3 a\u00f1os sus aulas; con el fin de adaptarse de cara al curso que viene (algunos de estos peque\u00f1os visitantes en septiembre comenzar\u00e1 su vida escolar en nuestros cole).<\/p>\n<p>Adem\u00e1s de ense\u00f1arles sus aulas, con sus rincones, han estado jugando en el patio, cantando y bailando canciones juntos, elaborando un mural conjuntamente y participando en la asamblea.\u00a0<\/p>\n<p>A continuaci\u00f3n os presentamos algunas fotos de la visita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xat1\/v\/t1.0-9\/11221906_922405914483759_8841429707600750168_n.jpg?oh=dbeb3845edaa5fd11f3b8947222da1dd&amp;oe=55C8312E\" alt=\"\" width=\"369\" height=\"247\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xfa1\/v\/l\/t1.0-9\/10403305_922405934483757_1617434389218842439_n.jpg?oh=239281b98af2badecf11cee5c172889e&amp;oe=55C30ABA\" alt=\"\" width=\"371\" height=\"246\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-xtp1\/v\/t1.0-9\/11265627_922406034483747_5984383786074316821_n.jpg?oh=ecebd88f211266d5bda575d73e251a0b&amp;oe=56057066&amp;__gda__=1443243856_34681e115046983ae7c66c3f85973342\" alt=\"\" width=\"741\" height=\"493\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>HASTA EL CURSO QUE VIENE<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos y alumnas de 3 a\u00f1os han recibido la visita de los ni\u00f1os y ni\u00f1as de 2 a\u00f1os de la EEI Jardines de Aranjuez, un total de 60 ni\u00f1os y ni\u00f1as de la Escuela Infantil han compartido con nuestros grupos de 3 a\u00f1os sus aulas; con el fin de adaptarse de cara al curso &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/05\/25\/hoy-no-somos-los-mas-pequenos-del-colegio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abHOY LOS DE 3 A\u00d1OS, NO SOMOS LOS M\u00c1S PEQUE\u00d1OS DEL COLEGIO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"post_folder":[],"class_list":["post-560","post","type-post","status-publish","format-standard","hentry","category-3-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/3-anos\/\" rel=\"category tag\">3 A\u00f1os<\/a>","rttpg_excerpt":"Los alumnos y alumnas de 3 a\u00f1os han recibido la visita de los ni\u00f1os y ni\u00f1as de 2 a\u00f1os de la EEI Jardines de Aranjuez, un total de 60 ni\u00f1os y ni\u00f1as de la Escuela Infantil han compartido con nuestros grupos de 3 a\u00f1os sus aulas; con el fin de adaptarse de cara al curso&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=560"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/560\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=560"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}