{"id":587,"date":"2015-06-08T09:04:00","date_gmt":"2015-06-08T09:04:00","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=587"},"modified":"2015-06-08T09:04:00","modified_gmt":"2015-06-08T09:04:00","slug":"el-zoo-de-5-anos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/06\/08\/el-zoo-de-5-anos\/","title":{"rendered":"EL ZOO DE 5 A\u00d1OS"},"content":{"rendered":"<p>Desde las 10:30 nuestros reci\u00e9n graduados, de 5 a\u00f1os, ya est\u00e1n en el ZOO.<\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xta1\/v\/t1.0-9\/r270\/11401087_928841960506821_3866858583051187861_n.jpg?oh=31d6f7618a75f02737d4c5ee4d6897dc&amp;oe=55F58811\" alt=\"\" width=\"754\" height=\"424\" \/><\/p>\n<p>Aqu\u00ed ten\u00e9is otra foto de la excursi\u00f3n al Zoo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xta1\/v\/t1.0-9\/11390031_928936933830657_5426705407372626306_n.jpg?oh=cc8c20bc20047b17842d2b8a4997d44b&amp;oe=55EBEBB4\" alt=\"\" width=\"753\" height=\"423\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde las 10:30 nuestros reci\u00e9n graduados, de 5 a\u00f1os, ya est\u00e1n en el ZOO. \u00a0 Aqu\u00ed ten\u00e9is otra foto de la excursi\u00f3n al Zoo.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-587","post","type-post","status-publish","format-standard","hentry","category-5-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/5-anos\/\" rel=\"category tag\">5 A\u00f1os<\/a>","rttpg_excerpt":"Desde las 10:30 nuestros reci\u00e9n graduados, de 5 a\u00f1os, ya est\u00e1n en el ZOO. \u00a0 Aqu\u00ed ten\u00e9is otra foto de la excursi\u00f3n al Zoo.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/587\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=587"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}