{"id":612,"date":"2015-06-24T11:24:43","date_gmt":"2015-06-24T11:24:43","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=612"},"modified":"2015-06-24T11:24:43","modified_gmt":"2015-06-24T11:24:43","slug":"videos-y-fotos-de-la-4-promocion-bilinguee-del-colegio-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/06\/24\/videos-y-fotos-de-la-4-promocion-bilinguee-del-colegio-carlos-iii\/","title":{"rendered":"V\u00cdDEOS Y FOTOS DE LA 4\u00aa PROMOCI\u00d3N BILING\u00dcE DEL COLEGIO CARLOS III"},"content":{"rendered":"<p>A la atenci\u00f3n de los padres y madres de 6\u00ba de Primaria, ya tenemos a disposici\u00f3n de todas las familias de los alumnos\/as graduados de 6\u00ba de Primaria, el v\u00eddeo de la graduaci\u00f3n y numerosas fotos, de los diferentes eventos y actividades extraescolares y complementarias que se han efectuado durante los cursos escolares 2013\/14 y 2014\/15. Para descargarlas necesit\u00e1is traer un pen-drive con al menos 5 Gb disponibles.<\/p>\n<p>HORARIO: jueves 25 de junio de 2015, viernes 26 de junio de 2015 y lunes 29 de \u00a0junio de 2015 de 12:00 a 13:00.<\/p>\n<p>LUGAR: sala de ordenadores.<\/p>\n<p>Con el fin de agilizar el proceso os sugerimos que hag\u00e1is una cadena de trasmisi\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>Muchas gracias, tutoras de 6\u00ba de Primaria.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la atenci\u00f3n de los padres y madres de 6\u00ba de Primaria, ya tenemos a disposici\u00f3n de todas las familias de los alumnos\/as graduados de 6\u00ba de Primaria, el v\u00eddeo de la graduaci\u00f3n y numerosas fotos, de los diferentes eventos y actividades extraescolares y complementarias que se han efectuado durante los cursos escolares 2013\/14 y &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/06\/24\/videos-y-fotos-de-la-4-promocion-bilinguee-del-colegio-carlos-iii\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abV\u00cdDEOS Y FOTOS DE LA 4\u00aa PROMOCI\u00d3N BILING\u00dcE DEL COLEGIO CARLOS III\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-612","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"A la atenci\u00f3n de los padres y madres de 6\u00ba de Primaria, ya tenemos a disposici\u00f3n de todas las familias de los alumnos\/as graduados de 6\u00ba de Primaria, el v\u00eddeo de la graduaci\u00f3n y numerosas fotos, de los diferentes eventos y actividades extraescolares y complementarias que se han efectuado durante los cursos escolares 2013\/14 y&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/612\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=612"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}