{"id":619,"date":"2015-07-19T09:32:34","date_gmt":"2015-07-19T09:32:34","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=619"},"modified":"2015-07-19T09:32:34","modified_gmt":"2015-07-19T09:32:34","slug":"videos-explicativos-de-las-actividades-extraescolares-curso-2015-16","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/07\/19\/videos-explicativos-de-las-actividades-extraescolares-curso-2015-16\/","title":{"rendered":"V\u00cdDEOS EXPLICATIVOS DE LAS ACTIVIDADES EXTRAESCOLARES CURSO 2015\/16"},"content":{"rendered":"<p>A continuaci\u00f3n os presentamos un v\u00eddeo explicativo de la propuesta de actividades extraescolares de cara al curso 2015\/16.<\/p>\n<p>CINEDUCA: creaci\u00f3n de un corto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0KANGOO POWER<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/9Sh3995RAME\" width=\"329\" height=\"270\"><\/iframe><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/OI0WcqTYij8\" width=\"328\" height=\"270\"><\/iframe><\/p>\n<p>JANINE\u00b4S DRAMA CLUB \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0PEQUEINGENIEROS<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/8eKC296B7rA\" width=\"331\" height=\"272\"><\/iframe><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/vH9rvZJrwic\" width=\"328\" height=\"271\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/L03GJ9ijZTw\" width=\"330\" height=\"271\"><\/iframe><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n os presentamos un v\u00eddeo explicativo de la propuesta de actividades extraescolares de cara al curso 2015\/16. CINEDUCA: creaci\u00f3n de un corto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0KANGOO POWER JANINE\u00b4S DRAMA CLUB &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/07\/19\/videos-explicativos-de-las-actividades-extraescolares-curso-2015-16\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abV\u00cdDEOS EXPLICATIVOS DE LAS ACTIVIDADES EXTRAESCOLARES CURSO 2015\/16\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-619","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"A continuaci\u00f3n os presentamos un v\u00eddeo explicativo de la propuesta de actividades extraescolares de cara al curso 2015\/16. CINEDUCA: creaci\u00f3n de un corto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0KANGOO POWER JANINE\u00b4S DRAMA CLUB&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=619"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/619\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=619"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}