{"id":714,"date":"2015-11-08T06:03:09","date_gmt":"2015-11-08T06:03:09","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=714"},"modified":"2015-11-08T06:03:09","modified_gmt":"2015-11-08T06:03:09","slug":"wales-day","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/11\/08\/wales-day\/","title":{"rendered":"PREPARANDO \u00abWALES DAY\u00bb"},"content":{"rendered":"<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/12234986_1006488539408829_6087503437056987330_n.jpg?oh=b30faeb7a6fda0d31857deca6aa6b39f&amp;oe=56B7DB04\" alt=\"\" width=\"338\" height=\"253\" \/><\/span><\/p>\n<p>Durante todo esta semana, todo el centro est\u00e1 adentr\u00e1ndose en Gales (su cultura, sus tradiciones, sus emblemas, su deporte, sus canciones: Tom Jones, su greograf\u00eda, su idioma, &#8230;..).<\/p>\n<p>En las siguientes im\u00e1genes pod\u00e9is ver una muestra de todo lo que est\u00e1n aprendiendo y haciendo.<\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fbcdn-sphotos-c-a.akamaihd.net\/hphotos-ak-xtf1\/v\/t1.0-9\/12065947_1005273559530327_7164414287971949779_n.jpg?oh=ac0e3cebe9507ec65f42728228bc9675&amp;oe=56AD35C5&amp;__gda__=1458481005_e7cc7d73b0075610b299999f50cdee28\" alt=\"\" width=\"295\" height=\"196\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xaf1\/v\/t1.0-9\/12208273_1005273949530288_2360840588759241378_n.jpg?oh=e8d2f7b3ec17099973710d45b168c86e&amp;oe=56AFB3CA\" alt=\"\" width=\"291\" height=\"193\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xap1\/v\/t1.0-9\/12219405_1005274689530214_9195716692882363142_n.jpg?oh=9986d5846b0df6ec6568bb87a91de8bf&amp;oe=56F4D8E7\" alt=\"\" width=\"290\" height=\"193\" \/><\/span><\/p>\n<p>\u00a0<\/p>\n<p>Gareth y Chris, auxiliares de conversaci\u00f3n del centro, est\u00e1n ense\u00f1ando a los chicos\/as el deporte del rugby: sus reglas, su t\u00e1ctica y sobre todo sus valores (un deporte donde prima el respeto al rival, el \u00e1rbitro y el compa\u00f1erismo).\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xap1\/v\/t1.0-9\/12239503_1005674799490203_6282194514143090774_n.jpg?oh=fe61a6e367df551cceb6e5d2b1f91923&amp;oe=56B5FDB1\" alt=\"\" width=\"280\" height=\"157\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpf1\/v\/t1.0-9\/12227631_1005686969488986_8238556818047056657_n.jpg?oh=d9b6f512fba345635f714afe609eea34&amp;oe=56B06054\" alt=\"\" width=\"233\" height=\"155\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpt1\/v\/t1.0-9\/12196086_1005687039488979_5821245678602206321_n.jpg?oh=27661c4f427db58e005b3a0ad6ff546a&amp;oe=56C1A82C\" alt=\"\" width=\"233\" height=\"155\" \/><\/p>\n<p>Las profesoras Boney y Lola Pinto, con alumnos\/as voluntarios de 6\u00ba de Primaria est\u00e1n creando una coreograf\u00eda, de la canci\u00f3n It\u00b4s not unusual del cantante gal\u00e9s Tom Jones.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Los pasillos y las aulas del centro, se est\u00e1n ti\u00f1endo de rojo, verde y blanco, el colegio se est\u00e1 llenando de dragones, narcisos y ovejas para celebrar el viernes 13 de noviembre: \u00abWales Day\u00bb\u00a0<\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0<\/span><\/p>\n<p>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/12208375_1005678602823156_3346492949205243806_n.jpg?oh=bb937855dc4e0e3bab069d29c4e64898&amp;oe=56EDA41C\" alt=\"\" width=\"395\" height=\"222\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xfa1\/v\/t1.0-9\/12241471_1005678629489820_5845597263709408669_n.jpg?oh=799f711ac2586445d1da1fcb47450108&amp;oe=56F363AC\" alt=\"\" width=\"334\" height=\"222\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtp1\/v\/t1.0-9\/12115445_1006101306114219_1566457131818082384_n.jpg?oh=dfff48b1c5144d0c7f406fa41b39d89e&amp;oe=56EEE2B3\" alt=\"\" width=\"384\" height=\"255\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xfa1\/v\/t1.0-9\/12239905_1006101352780881_2463571481063226826_n.jpg?oh=eef0a6dc57d53bd6735e22614b9c9575&amp;oe=56B79477\" alt=\"\" width=\"453\" height=\"255\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">En el Archivo adjunto informamos de los objetivos del d\u00eda de Gales or WALES DAY.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante todo esta semana, todo el centro est\u00e1 adentr\u00e1ndose en Gales (su cultura, sus tradiciones, sus emblemas, su deporte, sus canciones: Tom Jones, su greograf\u00eda, su idioma, &#8230;..). En las siguientes im\u00e1genes pod\u00e9is ver una muestra de todo lo que est\u00e1n aprendiendo y haciendo. \u00a0 Gareth y Chris, auxiliares de conversaci\u00f3n del centro, est\u00e1n ense\u00f1ando &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/11\/08\/wales-day\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPREPARANDO \u00abWALES DAY\u00bb\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"post_folder":[],"class_list":["post-714","post","type-post","status-publish","format-standard","hentry","category-proyecto-bilinguee"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/bilingueismo\/proyecto-bilinguee\/\" rel=\"category tag\">Proyecto Biling\u00fce<\/a>","rttpg_excerpt":"Durante todo esta semana, todo el centro est\u00e1 adentr\u00e1ndose en Gales (su cultura, sus tradiciones, sus emblemas, su deporte, sus canciones: Tom Jones, su greograf\u00eda, su idioma, &#8230;..). En las siguientes im\u00e1genes pod\u00e9is ver una muestra de todo lo que est\u00e1n aprendiendo y haciendo. \u00a0 Gareth y Chris, auxiliares de conversaci\u00f3n del centro, est\u00e1n ense\u00f1ando&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/714\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=714"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}