{"id":725,"date":"2015-11-19T17:10:05","date_gmt":"2015-11-19T17:10:05","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=725"},"modified":"2015-11-19T17:10:05","modified_gmt":"2015-11-19T17:10:05","slug":"wales-day-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/11\/19\/wales-day-2\/","title":{"rendered":"WALES DAY"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/12234986_1006488539408829_6087503437056987330_n.jpg?oh=b30faeb7a6fda0d31857deca6aa6b39f&amp;oe=56B7DB04\" alt=\"\" width=\"338\" height=\"253\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xlp1\/v\/t1.0-9\/12243004_1011297522261264_1769973929630697650_n.jpg?oh=33bd0c58577cdc037920aac76c5c211f&amp;oe=56F59CCB\" alt=\"\" width=\"377\" height=\"250\" \/><\/p>\n<p>La festividad de Gales comenz\u00f3 con unos talleres sobre Gales: presentaciones en v\u00eddeos, trabajos manuales, canciones galesas, juegos t\u00edpicas &#8230; durante los talleres a todos los ni\u00f1os y ni\u00f1as del Colegio, se les pintaba la cara con los colores de Gales y se les presentaba a su drag\u00f3n.<\/p>\n<p>Tras el recreo, todo el colegio, nos juntamos en la pista para continuar la fiesta. Tras la bienvenida, de Gareth, escuchamos el himno del pa\u00eds, para luego continuar con una exhibici\u00f3n de rugby (deporte nacional), a cargo de alumnos voluntarios\/as de 6\u00ba de Primaria, el partido se fue narrando, para explicar a todos los alumnos\/as las normas b\u00e1sicas y conceptos del juego (durante toda la semana Gareth y Cris ense\u00f1aron a todos los alumnos de Primaria, la idea b\u00e1sica sobre el juego).\u00a0<\/p>\n<p>Despu\u00e9s tambi\u00e9n todos juntos bailamos una canci\u00f3n de un artista Gales, Tom Jones, la canci\u00f3n era It\u00b4s not unusual, otro grupos de voluntarios\/as de 6\u00ba, con la profesoras Boney y Lola P. preparando una coreograf\u00eda, que nos ense\u00f1aron en este momento.<\/p>\n<p>Para concluir el d\u00eda festivo, apareci\u00f3 la bandera de Gales, que durante toda la semana, elaboramos conjuntamente todas las clases del Centro.<\/p>\n<p>\u00a0<\/p>\n<p>A continuaci\u00f3n pod\u00e9is ver algunas fotos representativas de esta festividad.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpt1\/v\/t1.0-9\/12234994_1009239482467068_7193897615549015466_n.jpg?oh=7fba20c252480f0bae516622d1e59ecb&amp;oe=56EDB452\" alt=\"\" width=\"806\" height=\"453\" \/><\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xaf1\/v\/t1.0-9\/12239953_1009239809133702_8200090305494900235_n.jpg?oh=3a915dd5ffd16c6691d47524105739b0&amp;oe=56F0CBD1\" alt=\"\" width=\"269\" height=\"152\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtf1\/v\/t1.0-9\/12240125_1009239935800356_9056421168694938054_n.jpg?oh=61c19983315c848f9690c737d4388742&amp;oe=56EF1B8B\" alt=\"\" width=\"270\" height=\"152\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtf1\/v\/t1.0-9\/12240076_1009239852467031_5037511724119783035_n.jpg?oh=072f32d69fe37044220e224532d4973f&amp;oe=56E8134C\" alt=\"\" width=\"267\" height=\"150\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xaf1\/v\/t1.0-9\/12278786_1011298375594512_625067345008389987_n.jpg?oh=27502cf688398a132c7948b66ddc0903&amp;oe=56E4E157\" alt=\"\" width=\"808\" height=\"537\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xaf1\/v\/t1.0-9\/12243579_1011299528927730_5046827294611429861_n.jpg?oh=02d0ab3f130b84b8646ea3b1523c0a4d&amp;oe=56E33FCD\" alt=\"\" width=\"808\" height=\"537\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtp1\/v\/t1.0-9\/12241586_1011299358927747_9032802864629064602_n.jpg?oh=aa9e2fce9e82b6b0e724de4ee976035a&amp;oe=56E9FF60\" alt=\"\" width=\"807\" height=\"536\" \/><\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xft1\/v\/t1.0-9\/12249902_1009239969133686_8897205355546125112_n.jpg?oh=6d616ee31dda38a5ab3cc944b53ba9f5&amp;oe=56E5E1E4\" alt=\"\" width=\"399\" height=\"299\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpt1\/v\/t1.0-9\/12227006_1009239625800387_107123525461780363_n.jpg?oh=ccaa48223442a47fbf264a44cab10e49&amp;oe=56EB9199\" alt=\"\" width=\"399\" height=\"299\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtf1\/v\/t1.0-9\/12249723_1009238999133783_55736557840169229_n.jpg?oh=0d8a4b8f9a09e7510d10b1d1d643ff76&amp;oe=56B10E73\" alt=\"\" width=\"258\" height=\"145\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xfp1\/v\/t1.0-9\/12247139_1009239212467095_3777713571907308069_n.jpg?oh=ddab38046b63941889102b2e311bafe7&amp;oe=56EE36F9\" alt=\"\" width=\"258\" height=\"145\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xap1\/v\/t1.0-9\/12241667_1011298775594472_7953869662668182759_n.jpg?oh=8373369226c0f8eac04c717c27c4a933&amp;oe=56E9649E\" alt=\"\" width=\"217\" height=\"144\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fbcdn-sphotos-e-a.akamaihd.net\/hphotos-ak-xfa1\/v\/t1.0-9\/12250087_1011299695594380_4254423655102601733_n.jpg?oh=62eb25498cb494b3038740f5303d0d40&amp;oe=56E6EE03&amp;__gda__=1458391944_e35d83eed5024b7de3e32a63c223c88f\" alt=\"\" width=\"404\" height=\"269\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xtf1\/v\/t1.0-9\/12241545_1011300092261007_7457665956052646021_n.jpg?oh=411337c024cb3187e9d959a66b3832ca&amp;oe=56E36BC8\" alt=\"\" width=\"407\" height=\"270\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpl1\/v\/t1.0-9\/12241532_1011300015594348_4467528090532045210_n.jpg?oh=bd80e818a20918f92af7773fb9ebe187&amp;oe=56AE1602\" alt=\"\" width=\"410\" height=\"273\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xfa1\/v\/t1.0-9\/12249719_1011300198927663_6379247907899655363_n.jpg?oh=28f3c87260dc4587789bd6870f5dc280&amp;oe=56DF4BCF\" alt=\"\" width=\"406\" height=\"270\" \/><\/p>\n<p>Tras las fotos, os presentamos un v\u00eddeo resumen de la fiesta de Gales:<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/Ow4D1nzsr7A\" width=\"425\" height=\"350\"><\/iframe><\/p>\n<p>Y por \u00faltimo adjuntamos unas redacciones, elaboradas por alumnos\/as del centro, sobre la festividad de Gales\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/12234986_1006488539408829_6087503437056987330_n.jpg?oh=b30faeb7a6fda0d31857deca6aa6b39f&amp;oe=56B7DB04\" alt=\"\" width=\"338\" height=\"253\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xlp1\/v\/t1.0-9\/12243004_1011297522261264_1769973929630697650_n.jpg?oh=33bd0c58577cdc037920aac76c5c211f&amp;oe=56F59CCB\" alt=\"\" width=\"377\" height=\"250\" \/><\/p>\n<p>La festividad de Gales comenz\u00f3 con unos talleres sobre Gales: presentaciones en v\u00eddeos, trabajos manuales, canciones galesas, juegos t\u00edpicas &#8230; durante los talleres a todos los ni\u00f1os y ni\u00f1as del Colegio, se les pintaba la cara con los colores de Gales y se les presentaba a su drag\u00f3n.<\/p>\n<p>Tras el recreo, todo el colegio, nos juntamos en la pista para continuar la fiesta. Tras la bienvenida, de Gareth, escuchamos el himno del pa\u00eds, para luego continuar con una exhibici\u00f3n de rugby (deporte nacional), a cargo de alumnos voluntarios\/as de 6\u00ba de Primaria, el partido se fue narrando, para explicar a todos los alumnos\/as las normas b\u00e1sicas y conceptos del juego (durante toda la semana Gareth y Cris ense\u00f1aron a todos los alumnos de Primaria, la idea b\u00e1sica sobre el juego).\u00a0<\/p>\n<p>Despu\u00e9s tambi\u00e9n todos juntos bailamos una canci\u00f3n de un artista Gales, Tom Jones, la canci\u00f3n era It\u00b4s not unusual, otro grupos de voluntarios\/as de 6\u00ba, con la profesoras Boney y Lola P. preparando una coreograf\u00eda, que nos ense\u00f1aron en este momento.<\/p>\n<p>Para concluir el d\u00eda festivo, apareci\u00f3 la bandera de Gales, que durante toda la semana, elaboramos conjuntamente todas las clases del Centro.<\/p>\n<p>\u00a0<\/p>\n<p>A continuaci\u00f3n pod\u00e9is ver algunas fotos representativas de esta festividad.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/hphotos-xpt1\/v\/t1.0-9\/12234994_1009239482467068_7193897615549015466_n.jpg?oh=7fba20c252480f0bae516622d1e59ecb&amp;oe=56EDB452\" alt=\"\" width=\"806\" height=\"453\" \/><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-725","post","type-post","status-publish","format-standard","hentry","category-centro"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a>","rttpg_excerpt":"La festividad de Gales comenz\u00f3 con unos talleres sobre Gales: presentaciones en v\u00eddeos, trabajos manuales, canciones galesas, juegos t\u00edpicas ... durante los talleres a todos los ni\u00f1os y ni\u00f1as del Colegio, se les pintaba la cara con los colores de Gales y se les presentaba a su drag\u00f3n. Tras el recreo, todo el colegio, nos&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=725"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/725\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=725"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}