{"id":7316,"date":"2020-03-05T00:03:19","date_gmt":"2020-03-05T00:03:19","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/actividades-de-la-biblioteca-escolar-por-el-8-de-marzo\/"},"modified":"2020-03-05T00:03:19","modified_gmt":"2020-03-05T00:03:19","slug":"actividades-de-la-biblioteca-escolar-por-el-8-de-marzo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/03\/05\/actividades-de-la-biblioteca-escolar-por-el-8-de-marzo\/","title":{"rendered":"ACTIVIDADES DE LA BIBLIOTECA ESCOLAR POR EL 8 DE MARZO"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Para conmemorar el D\u00eda Internacional de la Mujer\u00a0<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">nuestras Supermamis Bibliotecarias\u00a0<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">van a realizar varias actividades: <\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">&#8211; Exposici\u00f3n de libros sobre Coeducaci\u00f3n.<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">\u00a0<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">&#8211; Cuentacuentos para el fomento de la lectura y la Convivencia Escolar.<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/ESQ2dvXXYAAdITB?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/ESQ2fm0WkAAATRx?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"317\" height=\"258\" \/><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/ESQ2gnGX0AAJAV5?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"427\" height=\"307\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/ESQ2ehkXcAEXlP7?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"251\" height=\"308\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para conmemorar el D\u00eda Internacional de la Mujer\u00a0nuestras Supermamis Bibliotecarias\u00a0van a realizar varias actividades: &#8211; Exposici\u00f3n de libros sobre Coeducaci\u00f3n.\u00a0 &#8211; Cuentacuentos para el fomento de la lectura y la Convivencia Escolar.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-7316","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Para conmemorar el D\u00eda Internacional de la Mujer\u00a0nuestras Supermamis Bibliotecarias\u00a0van a realizar varias actividades: &#8211; Exposici\u00f3n de libros sobre Coeducaci\u00f3n.\u00a0 &#8211; Cuentacuentos para el fomento de la lectura y la Convivencia Escolar.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=7316"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7316\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=7316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=7316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=7316"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=7316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}