{"id":756,"date":"2015-12-06T07:52:15","date_gmt":"2015-12-06T07:52:15","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=756"},"modified":"2015-12-06T07:52:15","modified_gmt":"2015-12-06T07:52:15","slug":"rifa-pro-viaje-de-fin-de-etapa-6-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/12\/06\/rifa-pro-viaje-de-fin-de-etapa-6-primaria\/","title":{"rendered":"RIFA PRO VIAJE DE FIN DE ETAPA 6\u00ba PRIMARIA"},"content":{"rendered":"<p>Los alumnos de 6\u00ba, con el fin de recaudar su dinero para su viaje de fin de curso, han organizado una rifa, de una Fabulosa Cesta Navide\u00f1a; las papeletas de la rifa valen 1 \u20ac y ya est\u00e1n a la venta. El sorteo se celebrar\u00e1 el d\u00eda 19 de diciembre de 2015, durante el Mercadillo de Navidad del Colegio. Los premios ser\u00e1n canjeables SOLO el d\u00eda del sorteo, si la persona no est\u00e1 presente en ese momento con la papeleta premiada, se volver\u00e1 a sortear otro n\u00famero.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de 6\u00ba, con el fin de recaudar su dinero para su viaje de fin de curso, han organizado una rifa, de una Fabulosa Cesta Navide\u00f1a; las papeletas de la rifa valen 1 \u20ac y ya est\u00e1n a la venta. El sorteo se celebrar\u00e1 el d\u00eda 19 de diciembre de 2015, durante el Mercadillo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/12\/06\/rifa-pro-viaje-de-fin-de-etapa-6-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRIFA PRO VIAJE DE FIN DE ETAPA 6\u00ba PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-756","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Los alumnos de 6\u00ba, con el fin de recaudar su dinero para su viaje de fin de curso, han organizado una rifa, de una Fabulosa Cesta Navide\u00f1a; las papeletas de la rifa valen 1 \u20ac y ya est\u00e1n a la venta. El sorteo se celebrar\u00e1 el d\u00eda 19 de diciembre de 2015, durante el Mercadillo&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=756"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/756\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=756"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}