{"id":760,"date":"2015-12-14T12:32:49","date_gmt":"2015-12-14T12:32:49","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=760"},"modified":"2015-12-14T12:32:49","modified_gmt":"2015-12-14T12:32:49","slug":"acta-6-asamblea-de-los-pitufos-11-de-diciembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2015\/12\/14\/acta-6-asamblea-de-los-pitufos-11-de-diciembre\/","title":{"rendered":"ACTA 6\u00aa ASAMBLEA DE LOS PITUFOS (11 DE DICIEMBRE)"},"content":{"rendered":"<p>Falta los representantes de 3\u00baC y 4\u00baC<\/p>\n<p>TEMAS TRATADOS<\/p>\n<ul>\n<li>Lemas y dibujos de limpieza y orden (votaci\u00f3n)<\/li>\n<\/ul>\n<p>Se hacen dos categor\u00edas, lemas y dibujos, se hace varias votaciones, hasta que nos quedamos con un n\u00famero de opciones bajo.<\/p>\n<p>Elegimos 4 dibujos y 3 lemas, para concienciar a la comunidad educativa, sobre el orden y limpieza del centro, se pondr\u00e1n por los pasillos y patios.<\/p>\n<ul>\n<li>Marcador de clases<\/li>\n<\/ul>\n<p>Se dice iniciar esta actividad, se ir\u00e1 concretando; se elaborar\u00e1 un marcador para cada clase. La idea es valorar tambi\u00e9n los logros que la clase hace cada d\u00eda, semana,\u2026.<\/p>\n<p>El tutor elige el premio y el n\u00famero de stickers, para \u00e9l.<\/p>\n<p>Cada clase tiene un color o un dibujo asignado; para que no haya posibles robos, aunque habr\u00e1 un marcador general en secretar\u00eda.<\/p>\n<p>Se propone que la pegatina sea de Charlie, mascota del centro.<\/p>\n<p>Idea para la primera pegatina: Operaci\u00f3n Kilo, poner una cantidad de kilos para conseguir un premio, m\u00e1s tiempo de patio (est\u00e1 iniciativa se hizo el a\u00f1o pasado y resulto muy positiva y motivadora), se habla que puede realizarse sin que exista el marcador.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>Ligas<\/li>\n<\/ul>\n<p>Algunas clases comentan, que no han recibido la informaci\u00f3n a tiempo. Se decide que entreguen las hojas a los los encargados de las ligas (Diego 6\u00baB, Clara 6\u00baA y Guillermo 6\u00baD). La semana que viene est\u00e1 comisi\u00f3n deportiva, elaborar\u00e1 un calendario, para comenzar en enero.<\/p>\n<ul>\n<li>Propuestas novedosas para Navidad<\/li>\n<\/ul>\n<p>Se recuerdan las ideas de la asamblea pasada:<\/p>\n<p>En clase de Art hacer decoraci\u00f3n navide\u00f1a.<\/p>\n<p>Amigo Invisible por clases o cursos.<\/p>\n<p>\u00c1rbol de Navidad Gigante entre todos los alumnos\/as del colegio, similar a lo que se hizo con la bandera de Gales.<\/p>\n<p>Concurso de adornos navide\u00f1os originales elaborados por los alumnos.<\/p>\n<p>Concurso de villancicos en el patio (cada curso elige un villancico y vemos cual nos gusta m\u00e1s).<\/p>\n<p>Venir vestidos de calle.<\/p>\n<p>Campanadas con lacasitos (fiesta de fin de a\u00f1o, que realizaron otros cursos).<\/p>\n<p>T\u00fa si que vales, concurso de talentos.<\/p>\n<p>Concurso de adorno de puertas (se hizo hace 2 a\u00f1os).<\/p>\n<p>Grabar un v\u00eddeo de un Villancico del colegio, creado para la ocasi\u00f3n.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Una vez refrescadas las ideas damos pie a ideas nuevas<\/p>\n<p>Fiesta en clase, con bebida y comida (envasada o cada uno se come lo suyo)<\/p>\n<p>Hacer un Bel\u00e9n Gigante<\/p>\n<p>Disfraces de Navidad<\/p>\n<p>Teatro de Navidad, surge la idea de hablar con Janine y los compa\u00f1eros de Drama, para que representen la obra que representar\u00e1n la semana que viene por la tarde (lunes 14 Infantil, martes 15 1\u00ba, 2\u00ba y 3\u00ba y mi\u00e9rcoles 16 4\u00ba, 5\u00ba y 6\u00ba)<\/p>\n<p>Que venga tambi\u00e9n Papa Noel, adem\u00e1s de los Reyes Magos<\/p>\n<p>Construir un Bel\u00e9n de Lego y de Playmobil<\/p>\n<p>\u00a0<\/p>\n<p>Todas estas ideas se llevar\u00e1n a la Comisi\u00f3n de Festejos (formada por profesores de todos los ciclos\/tramos) para proponer y organizar los d\u00edas previos a la vacaciones de navidad.<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>Idea de temas para otras asambleas<\/li>\n<\/ul>\n<p>Limpieza<\/p>\n<p>Ligas deportivas<\/p>\n<p>Marcadores<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>Calendario de asambleas ordinarias<\/li>\n<\/ul>\n<p>Cada dos semanas, pr\u00f3xima asamblea 8 de enero.<\/p>\n<p>Tambi\u00e9n se habla de asambleas ordinarias y extraordinarias, y se les comunicada que cuando tenga un tema que consideren que no puede esperar, se puede convocar la asamblea.<\/p>\n<ul>\n<li>Ruegos y preguntas<\/li>\n<\/ul>\n<p>En otros sitios de Aranjuez tambi\u00e9n se est\u00e1 recogiendo comida.<\/p>\n<p>Inicio de la m\u00fasica, se va a poner un tabl\u00f3n para que las clases o la gente a\u00f1ade canciones, se informa, que Sarah (5\u00ba) es la encargada de asignar a cada d\u00eda una canci\u00f3n, no s\u00f3lo teniendo en cuenta los gustos musicales, tambi\u00e9n los d\u00edas internacionales y fechas significativas.<\/p>\n<p>Exhibici\u00f3n de Rob\u00f3tica con Lego (se hablar\u00e1 con la empresa Pequeingeieros y los tutores para realizar un taller pr\u00e1ctico de rob\u00f3tica)<\/p>\n<p>Hay una ni\u00f1a enferma se pide que se le grabe un v\u00eddeo de actividades y cosas que hacemos en el colegio; se le remite a la p\u00e1gina web del centro.<\/p>\n<p>\u00a0<\/p>\n<p>Temas para la pr\u00f3xima asamblea (8 de enero)<\/p>\n<p>\u00bfQu\u00e9 valoramos para el marcador?<\/p>\n<p>Manifiesto de las ligas deportivas<\/p>\n<p>Carta a las autoridades y cargos<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falta los representantes de 3\u00baC y 4\u00baC<\/p>\n<p>TEMAS TRATADOS<\/p>\n<ul>\n<li>Lemas y dibujos de limpieza y orden (votaci\u00f3n)<\/li>\n<\/ul>\n<p>Se hacen dos categor\u00edas, lemas y dibujos, se hace varias votaciones, hasta que nos quedamos con un n\u00famero de opciones bajo.<\/p>\n<p>Elegimos 4 dibujos y 3 lemas, para concienciar a la comunidad educativa, sobre el orden y limpieza del centro, se pondr\u00e1n por los pasillos y patios.<\/p>\n<ul>\n<li>Marcador de clases<\/li>\n<\/ul>\n<p>Se dice iniciar esta actividad, se ir\u00e1 concretando; se elaborar\u00e1 un marcador para cada clase. La idea es valorar tambi\u00e9n los logros que la clase hace cada d\u00eda, semana,\u2026.<\/p>\n<p>El tutor elige el premio y el n\u00famero de stickers, para \u00e9l.<\/p>\n<p>Cada clase tiene un color o un dibujo asignado; para que no haya posibles robos, aunque habr\u00e1 un marcador general en secretar\u00eda.<\/p>\n<p>Se propone que la pegatina sea de Charlie, mascota del centro.<\/p>\n<p>Idea para la primera pegatina: Operaci\u00f3n Kilo, poner una cantidad de kilos para conseguir un premio, m\u00e1s tiempo de patio (est\u00e1 iniciativa se hizo el a\u00f1o pasado y resulto muy positiva y motivadora), se habla que puede realizarse sin que exista el marcador.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-760","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"Falta los representantes de 3\u00baC y 4\u00baC TEMAS TRATADOS Lemas y dibujos de limpieza y orden (votaci\u00f3n) Se hacen dos categor\u00edas, lemas y dibujos, se hace varias votaciones, hasta que nos quedamos con un n\u00famero de opciones bajo. Elegimos 4 dibujos y 3 lemas, para concienciar a la comunidad educativa, sobre el orden y limpieza&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=760"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}