{"id":7631,"date":"2020-06-05T10:01:37","date_gmt":"2020-06-05T10:01:37","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=7631"},"modified":"2020-06-05T10:01:37","modified_gmt":"2020-06-05T10:01:37","slug":"nota-informativa-final-del-curso-2019-2020","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/06\/05\/nota-informativa-final-del-curso-2019-2020\/","title":{"rendered":"NOTA INFORMATIVA FINAL DEL CURSO 2019-2020"},"content":{"rendered":"<p>Aranjuez, 5 de junio de 2020.<\/p>\n<p>NOTA INFORMATIVA FINAL DE CURSO<\/p>\n<p>Estimadas familias:<\/p>\n<p>Una vez publicada la Resoluci\u00f3n Conjunta de las Viceconsejer\u00edas de Pol\u00edtica Educativa y Organizaci\u00f3n Educativa del d\u00eda 27 de mayo, donde se dictan las Instrucciones complementarias para el desarrollo del Tercer Trimestre y Final del Curso 2019 \/ 2020, y ante las numerosas, y a veces algo confusas, informaciones que van apareciendo a diario a ra\u00edz de dicha publicaci\u00f3n, los Centros P\u00fablicos de Infantil y Primaria de Aranjuez queremos aclarar que:<\/p>\n<p>1. En lo que se refiere a la etapa de Educaci\u00f3n Infantil, en ning\u00fan caso se volver\u00e1 al Centro durante el presente curso.<\/p>\n<p>2. Respecto a la Etapa de Educaci\u00f3n Primaria, y como consecuencia de la valoraci\u00f3n de las medidas puestas en marcha con los alumnos objeto de refuerzo educativo derivados del COVID y las condiciones de seguridad sanitaria exigidas en la propia Resoluci\u00f3n, informamos que los Centros continuaremos con la atenci\u00f3n educativa a distancia a tod@s los alumn@s, salvo en aquellos casos en los que el Equipo Docente considere imprescindible el refuerzo presencial. Cada Centro contactar\u00e1 con las familias correspondientes, que podr\u00e1n acudir de forma voluntaria, en el horario que se les indique.<\/p>\n<p>Agradeciendo todo vuestro trabajo y esfuerzo por superar los inconvenientes vividos como consecuencia de la actual crisis sanitaria, os mandamos nuestro \u00e1nimo para enfrentar esta recta final del curso.<\/p>\n<p>Un cordial saludo<\/p>\n<p>LOS CENTROS P\u00daBLICOS DE EDUCACI\u00d3N INFANTIL Y PRIMARIA DE ARANJUEZ<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/06\/NOTA-INFORMATIVA-FINAL-DE-CURSO.pdf\">NOTA INFORMATIVA FINAL DE CURSO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 5 de junio de 2020. NOTA INFORMATIVA FINAL DE CURSO Estimadas familias: Una vez publicada la Resoluci\u00f3n Conjunta de las Viceconsejer\u00edas de Pol\u00edtica Educativa y Organizaci\u00f3n Educativa del d\u00eda 27 de mayo, donde se dictan las Instrucciones complementarias para el desarrollo del Tercer Trimestre y Final del Curso 2019 \/ 2020, y ante las &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/06\/05\/nota-informativa-final-del-curso-2019-2020\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNOTA INFORMATIVA FINAL DEL CURSO 2019-2020\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,41],"tags":[],"post_folder":[],"class_list":["post-7631","post","type-post","status-publish","format-standard","hentry","category-noticias","category-secretaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/secretaria\/\" rel=\"category tag\">Secretar\u00eda<\/a>","rttpg_excerpt":"Aranjuez, 5 de junio de 2020. NOTA INFORMATIVA FINAL DE CURSO Estimadas familias: Una vez publicada la Resoluci\u00f3n Conjunta de las Viceconsejer\u00edas de Pol\u00edtica Educativa y Organizaci\u00f3n Educativa del d\u00eda 27 de mayo, donde se dictan las Instrucciones complementarias para el desarrollo del Tercer Trimestre y Final del Curso 2019 \/ 2020, y ante las&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=7631"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7631\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=7631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=7631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=7631"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=7631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}