{"id":784,"date":"2016-01-11T08:58:09","date_gmt":"2016-01-11T08:58:09","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=784"},"modified":"2016-01-11T08:58:09","modified_gmt":"2016-01-11T08:58:09","slug":"escuelas-sostenibles-residuos-y-consumo-responsable","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/01\/11\/escuelas-sostenibles-residuos-y-consumo-responsable\/","title":{"rendered":"ESCUELAS SOSTENIBLES: RESIDUOS Y CONSUMO RESPONSABLE"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.naturdelsigloxxi.com\/modificacion%202013\/foto07.jpg\" alt=\"\" \/><\/p>\n<p>Como sab\u00e9is, nuestro centro este curso escolar ha emprendido un proyecto bonito y sobre todo muy ecol\u00f3gico. Estamos inmersos en el Programa de Escuelas Sostenibles de la Comunidad de Madrid. El programa exige formaci\u00f3n del profesorado, elaboraci\u00f3n de \u00a0un plan de acci\u00f3n ambiental para el centro y participaci\u00f3n por parte del alumnado y las familias. Un grupo de maestros del centro ya estamos con la formaci\u00f3n y muy ilusionados y comprometidos con el programa, el cual dura tres a\u00f1os, tras completarlos podemos formar parte y tener el t\u00edtulo de ESCUELA SOSTENIBLE DE LA COMUNIDAD DE MADRID.\u00a0 Y lo m\u00e1s importante, colaborar con el cuidado del medio ambiente y ense\u00f1ar a\u00a0 que nuestros alumnos ayuden a hacer un mundo mejor.<\/p>\n<p>En el programa participa toda la comunidad escolar, hay un comit\u00e9 medio ambiental formado por un grupo de maestros, una madre, un conserje y dos alumnos del centro. El primer paso ha sido realizar una auditor\u00eda a trav\u00e9s de unas encuestas para valorar necesidades y hacer propuestas de mejora. Hay que tratar varios temas, este curso hemos empezado a trabajar con: RESIDUOS Y CONSUMO RESPONSABLE.<\/p>\n<p>Os queremos mantener informados ya que es un proyecto en el que todos participamos , as\u00ed que os mostramos el resultado de\u00a0 las encuestas realizadas a los maestros, \u00a0a los alumnos y familias de 1\u00ba, 2\u00ba y 3\u00ba de primaria (nos ped\u00edan estos curso como muestra).<\/p>\n<p>\u00a0<\/p>\n<p>*Adjuntamos archivo con la recogida de datos y la representaci\u00f3n en las gr\u00e1ficas.<\/p>\n<p>Os mandamos tambi\u00e9n las conclusiones realizadas tras la auditor\u00eda medioambiental, y las propuestas de mejora que proponemos.<\/p>\n<p>Estamos abiertos a nuevas propuestas y a cualquier tipo de colaboraci\u00f3n para mejorar el centro, para mejorar, aunque sea un poquito, el mundo.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0CONCLUSIONES<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lo primero es destacar la buena participaci\u00f3n de padres, alumnos y profesores, y sobre todo la implicaci\u00f3n de los mismos en el tema propuesto, la preocupaci\u00f3n por el reciclaje y la necesidad de saber m\u00e1s sobre el mismo para poder realizar una buena labor.<\/p>\n<p>\u00a0<\/p>\n<p>Valorando el resultado de la auditor\u00eda se ve la necesidad por parte de todos los participantes de la realizaci\u00f3n de unas jornadas y campa\u00f1as en el centro escolar sobre residuos y cuidado del entorno.<\/p>\n<p>Los datos de alumnos y familias coinciden en que hay una mayor\u00eda que recicla en casa y que trata de tirar los residuos en las papeleras adecuadas, aun as\u00ed se observa, e incluso se plasma en las encuestas, que el lugar con m\u00e1s residuos en el centro escolar, es el patio del colegio.<\/p>\n<p>\u00a0<\/p>\n<p>En cuanto al n\u00famero de papeleras y contenedores se han contado unas 90 en todo el centro. Aun as\u00ed observamos que no son bien utilizadas en el patio, que en las aulas no todas tienen dos papeleras y que en el comedor s\u00f3lo hay una papelera d\u00f3nde depositamos todo tipo de residuos. En cuanto a contenedores s\u00f3lo tenemos el contenedor de papel.<\/p>\n<p>La comunidad escolar ve\u00a0 la dificultad de usar materiales y papeles reciclados ya que el coste de los mismos es\u00a0 bastante superior y no siempre f\u00e1cil de encontrar.<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0PROPUESTAS DE MEJORA<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Valorando los datos anteriores presentamos las siguientes propuestas de mejora:<\/p>\n<p>\u00a0<\/p>\n<p>1.- Se ve la necesidad de organizar charlas de <strong>informaci\u00f3n para saber el destino final de cada uno de los residuos<\/strong>, pensamos que cuando la gente est\u00e1 m\u00e1s informada, la realizaci\u00f3n de la actividad tiene m\u00e1s sentido y se hace con m\u00e1s entusiasmo. Por ejemplo, en el punto limpio de Aranjuez se pueden llevar cosas para que otras personas las reutilicen.<\/p>\n<p>\u00a0<\/p>\n<p>2.- Conseguir <strong>m\u00e1s papeleras para las aulas<\/strong>, m\u00e1s contenedores para diferentes residuos, por ejemplo \u00a0<strong>contenedores amarillos<\/strong>, diferentes papeleras en el <strong>comedor.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>3.- Poner en <strong>cada aula una caja<\/strong> d\u00f3nde los alumnos tiren el papel, al final de la semana un encargado vac\u00eda la caja en el contenedor azul que tenemos en el centro.<\/p>\n<p>\u00a0<\/p>\n<p>4.- Realizar una campa\u00f1a con los alumnos sobre la importancia de la <strong>limpieza de las puertas de los ba\u00f1os<\/strong>, no se debe pintar en ellas. Realizar campa\u00f1a de limpieza de las mismas con los alumnos.<\/p>\n<p>\u00a0<\/p>\n<p>5.-Para mejorar el tema de los residuos en el patio realizamos las siguientes propuestas:<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211;<strong>Cambiar la ubicaci\u00f3n<\/strong> de las papeleras en el patio.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 -Promover\u00a0 la <strong>reducci\u00f3n y recogida de papel de aluminio<\/strong> de los desayunos.<\/p>\n<p>Aconsejar que los ni\u00f1os traigan los desayunos en envases de pl\u00e1stico, facilitando nosotros unas cajas en el recreo, con el nombre de cada clase d\u00f3nde los ni\u00f1os despu\u00e9s puedan dejar ah\u00ed sus envases y llevarlos a casa para volver a ser utilizados.<\/p>\n<p>Tener en el aula o en el patio cajas exclusivas para depositar el papel de aluminio y poder utilizarlo luego para hacer manualidades, o una manualidad de todo el centro.<\/p>\n<p>\u00a0<\/p>\n<p>-Implicar seriamente a los alumnos, padres y monitores que utilizan el patio del colegio y otras instalaciones para las <strong>actividades extraescolares<\/strong>, para que lo mantengan\u00a0 limpio.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Comit\u00e9 del \u00a0Proyecto Escuelas Sostenibles<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.naturdelsigloxxi.com\/modificacion%202013\/foto07.jpg\" alt=\"\" \/><\/p>\n<p>Como sab\u00e9is, nuestro centro este curso escolar ha emprendido un proyecto bonito y sobre todo muy ecol\u00f3gico. Estamos inmersos en el Programa de Escuelas Sostenibles de la Comunidad de Madrid. El programa exige formaci\u00f3n del profesorado, elaboraci\u00f3n de \u00a0un plan de acci\u00f3n ambiental para el centro y participaci\u00f3n por parte del alumnado y las familias. Un grupo de maestros del centro ya estamos con la formaci\u00f3n y muy ilusionados y comprometidos con el programa, el cual dura tres a\u00f1os, tras completarlos podemos formar parte y tener el t\u00edtulo de ESCUELA SOSTENIBLE DE LA COMUNIDAD DE MADRID.\u00a0 Y lo m\u00e1s importante, colaborar con el cuidado del medio ambiente y ense\u00f1ar a\u00a0 que nuestros alumnos ayuden a hacer un mundo mejor.<\/p>\n<p>En el programa participa toda la comunidad escolar, hay un comit\u00e9 medio ambiental formado por un grupo de maestros, una madre, un conserje y dos alumnos del centro. El primer paso ha sido realizar una auditor\u00eda a trav\u00e9s de unas encuestas para valorar necesidades y hacer propuestas de mejora. Hay que tratar varios temas, este curso hemos empezado a trabajar con: RESIDUOS Y CONSUMO RESPONSABLE.<\/p>\n<p>Os queremos mantener informados ya que es un proyecto en el que todos participamos , as\u00ed que os mostramos el resultado de\u00a0 las encuestas realizadas a los maestros, \u00a0a los alumnos y familias de 1\u00ba, 2\u00ba y 3\u00ba de primaria (nos ped\u00edan estos curso como muestra).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"post_folder":[],"class_list":["post-784","post","type-post","status-publish","format-standard","hentry","category-experiencias-educativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/experiencias-educativas\/\" rel=\"category tag\">Proyectos Educativos<\/a>","rttpg_excerpt":"Como sab\u00e9is, nuestro centro este curso escolar ha emprendido un proyecto bonito y sobre todo muy ecol\u00f3gico. Estamos inmersos en el Programa de Escuelas Sostenibles de la Comunidad de Madrid. El programa exige formaci\u00f3n del profesorado, elaboraci\u00f3n de \u00a0un plan de acci\u00f3n ambiental para el centro y participaci\u00f3n por parte del alumnado y las familias.&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=784"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/784\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=784"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}