{"id":7985,"date":"2020-09-12T14:11:32","date_gmt":"2020-09-12T14:11:32","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=7985"},"modified":"2020-09-12T14:11:32","modified_gmt":"2020-09-12T14:11:32","slug":"2o-primaria_listado-de-material-curso-2020-2021","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/12\/2o-primaria_listado-de-material-curso-2020-2021\/","title":{"rendered":"2\u00ba PRIMARIA_LISTADO DE MATERIAL CURSO 2020-2021"},"content":{"rendered":"<p>Las tutoras de 2\u00b0 Primaria os damos la bienvenida al nuevo curso y os comunicamos los materiales que tienen que traer.<\/p>\n<p><strong>Rogamos que todo el material tenga el nombre del alumno\/a escrito.<\/strong><br \/>\n+ Un estuche (que no sea de lat\u00f3n) que contenga:<br \/>\n+ Dos lapiceros 2HB (Staedtler o similar), un sacapuntas, un borrador, una regla peque\u00f1a, unas tijeras de uso escolar de punta redonda, una barra de pegamento, una pintura bicolor roja -azul y unas pinturas de madera de 12 colores.\u00a0 \u00a0 &#8211; 2 cuadernos cuadrov\u00eda Lamela de 4mm la pauta (de espiral tama\u00f1o cuartilla). Uno de ellos de portada de color rojo.<br \/>\n&#8211; Agenda escolar con espiral, que tenga una p\u00e1gina para cada d\u00eda.<\/p>\n<p>Los libros deber\u00e1n estar FORRADOS Y CON EL NOMBRE, APELLIDOS Y CURSO en la portada.<br \/>\n<strong>Se les informar\u00e1 del d\u00eda en que deber\u00e1n traer los libros (primer trimestre) y cuadernos a clase, ya que \u00e9stos ir\u00e1n y volver\u00e1n diariamente a casa. El primer d\u00eda de clase solo es necesario traer el estuche.<\/strong><\/p>\n<p>Os recordamos que cada alumno\/a deber\u00e1 traer su ri\u00f1onera COVID, como inform\u00f3 el centro en su comunicado de inicio de curso.<\/p>\n<p>Gracias.<\/p>\n<p>Atentamente,<\/p>\n<p>Las tutoras\u00a0 de 2\u00ba de Primaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tutoras de 2\u00b0 Primaria os damos la bienvenida al nuevo curso y os comunicamos los materiales que tienen que traer. Rogamos que todo el material tenga el nombre del alumno\/a escrito. + Un estuche (que no sea de lat\u00f3n) que contenga: + Dos lapiceros 2HB (Staedtler o similar), un sacapuntas, un borrador, una regla &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/12\/2o-primaria_listado-de-material-curso-2020-2021\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab2\u00ba PRIMARIA_LISTADO DE MATERIAL CURSO 2020-2021\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,77],"tags":[],"post_folder":[],"class_list":["post-7985","post","type-post","status-publish","format-standard","hentry","category-2o-ciclo","category-libros-de-texto-y-materiales"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/2o-ciclo\/\" rel=\"category tag\">2\u00ba Ciclo<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/secretaria\/libros-de-texto-y-materiales\/\" rel=\"category tag\">LIBROS DE TEXTO Y MATERIALES<\/a>","rttpg_excerpt":"Las tutoras de 2\u00b0 Primaria os damos la bienvenida al nuevo curso y os comunicamos los materiales que tienen que traer. Rogamos que todo el material tenga el nombre del alumno\/a escrito. + Un estuche (que no sea de lat\u00f3n) que contenga: + Dos lapiceros 2HB (Staedtler o similar), un sacapuntas, un borrador, una regla&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=7985"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/7985\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=7985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=7985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=7985"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=7985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}