{"id":8053,"date":"2020-09-15T20:08:26","date_gmt":"2020-09-15T20:08:26","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8053"},"modified":"2020-09-15T20:08:26","modified_gmt":"2020-09-15T20:08:26","slug":"comunicado-entradas-y-salidas-en-dias-de-lluvia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/15\/comunicado-entradas-y-salidas-en-dias-de-lluvia\/","title":{"rendered":"COMUNICADO: ENTRADAS Y SALIDAS EN D\u00cdAS DE LLUVIA"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Con motivo de encontrarnos en el Escenario 2 por COVID19, nos disponemos a informarles de la organizaci\u00f3n de las entradas y salidas del alumnado en d\u00edas de lluvia:<\/p>\n<p><strong>ENTRADAS<\/strong><\/p>\n<ul>\n<li><strong>El alumnado no har\u00e1 filas en el exterior por lo que ir\u00e1n accediendo al Centro, para entrar en el edificio y dirigirse a sus aulas, respetando el horario de acceso al Centro que a continuaci\u00f3n detallaremos y utilizando sus puertas correspondientes de acceso al edificio:<\/strong><\/li>\n<\/ul>\n<p><strong>PUERTA CALLE JUNTA CENTRAL SUPREMA:<\/strong><\/p>\n<ul>\n<li>5\u00ba y 6\u00ba E. PRIMARIA. 09:00 horas<\/li>\n<li>3\u00ba y 4\u00ba E. PRIMARIA. 09:05 horas<\/li>\n<li>1\u00ba y 2\u00ba E. PRIMARIA. 09:10 horas<\/li>\n<\/ul>\n<p><strong>PUERTA CALLE JULIO VALDE\u00d3N:<\/strong><\/p>\n<ul>\n<li>INFANTIL 5 A\u00d1OS. 09:00 horas<\/li>\n<li>INFANTIL 4 A\u00d1OS. 09:05 horas<\/li>\n<\/ul>\n<p><strong>GLORIETA CA\u00cdDOS DEL 2 DE MAYO:<\/strong><\/p>\n<ul>\n<li>INFANTIL 3 A\u00d1OS. 09:10 horas.<\/li>\n<\/ul>\n<p>(El alumnado acompa\u00f1ado de un s\u00f3lo familiar, entrar\u00e1 hasta el patio interior asfaltado, utilizando para la subida la parte derecha del camino, guardando la distancia de seguridad y medidas de higiene. MUY IMPORTANTE: UNA VEZ ENTREGADO EL\/LA ALUMNO\/A DEBER\u00c1 ABANDONAR ESA ZONA DE INMEDIATO, PARA SALIR DEL CENTRO POR LA MISMA PUERTA, BAJANDO POR LA PARTE CONTRARIA A LA DE SUBIDA, EVITANDO AS\u00cd AGLOMERACIONES EN CUALQUIER PUNTO DEL TRAYECTO.)<\/p>\n<p><strong>SALIDAS<\/strong><\/p>\n<p><strong>PUERTA CALLE JUNTA CENTRAL SUPREMA: (todos saldr\u00e1n por orden de aulas, a trav\u00e9s de puerta de cristales patio de 1\u00ba y 2\u00ba, para acortar recorrido, utilizando el lado de la salida que usan siempre, siguiendo indicaciones del Auxiliar de control de puerta)<\/strong><\/p>\n<ul>\n<li>5\u00ba y 6\u00ba E. PRIMARIA. 13:00 horas (septiembre y junio) 14:00 horas (octubre-mayo)<\/li>\n<li>3\u00ba y 4\u00ba E. PRIMARIA. 13:05 horas (septiembre y junio) 14:05 horas (octubre-mayo)<\/li>\n<li>1\u00ba y 2\u00ba E. PRIMARIA. 13:10 horas (septiembre y junio) 14:10 horas (octubre-mayo)<\/li>\n<\/ul>\n<p><strong>PUERTA CALLE JULIO VALDE\u00d3N: (todos saldr\u00e1n por orden de aulas, puerta peque\u00f1a infantil. Un s\u00f3lo familiar por orden de aula, entrar\u00e1 a por el alumno por la parte derecha de la puerta y saldr\u00e1 por la parte izquierda de la puerta, siguiendo indicaciones del Auxiliar de control de puerta)<\/strong><\/p>\n<ul>\n<li>INFANTIL 4 A\u00d1OS. 12:50 horas. (septiembre y junio) 13:50 horas (octubre-mayo)<\/li>\n<li>INFANTIL 5 A\u00d1OS. 12:55 horas. (septiembre y junio) 13:55 horas (octubre-mayo)<\/li>\n<\/ul>\n<p><strong>GLORIETA CA\u00cdDOS DEL 2 DE MAYO: <\/strong><strong>(S\u00f3lo un familiar acceder\u00e1 al patio asfaltado, para recoger al alumnado que saldr\u00e1 por orden de aulas, despejando inmediatamente la zona, para salir del centro, evitando aglomeraciones)<\/strong><\/p>\n<ul>\n<li>INFANTIL 3 A\u00d1OS. 12:45 horas. (septiembre y junio) 13:45 horas (octubre-mayo).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>EQUIPO DIRECTIVO.<\/p>\n<p>Nota: Rogamos que el alumnado de Primaria vaya provisto de chubasquero o paraguas en los d\u00edas de lluvia, para que su recogida por las familias sea lo m\u00e1s fluida posible, despejando de inmediato la puerta de salida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Con motivo de encontrarnos en el Escenario 2 por COVID19, nos disponemos a informarles de la organizaci\u00f3n de las entradas y salidas del alumnado en d\u00edas de lluvia: ENTRADAS El alumnado no har\u00e1 filas en el exterior por lo que ir\u00e1n accediendo al Centro, para entrar en el edificio y dirigirse a sus &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/15\/comunicado-entradas-y-salidas-en-dias-de-lluvia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO: ENTRADAS Y SALIDAS EN D\u00cdAS DE LLUVIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,58,5,21,29],"tags":[],"post_folder":[],"class_list":["post-8053","post","type-post","status-publish","format-standard","hentry","category-1-tramo","category-2-tramo","category-alumnos","category-infantil","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/1-tramo\/\" rel=\"category tag\">1\u00ba Tramo<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/2-tramo\/\" rel=\"category tag\">2\u00ba Tramo<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/\" rel=\"category tag\">Alumnos<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Estimadas familias: Con motivo de encontrarnos en el Escenario 2 por COVID19, nos disponemos a informarles de la organizaci\u00f3n de las entradas y salidas del alumnado en d\u00edas de lluvia: ENTRADAS El alumnado no har\u00e1 filas en el exterior por lo que ir\u00e1n accediendo al Centro, para entrar en el edificio y dirigirse a sus&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8053"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8053\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8053"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}