{"id":8057,"date":"2020-09-16T10:04:38","date_gmt":"2020-09-16T10:04:38","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8057"},"modified":"2020-09-16T10:04:38","modified_gmt":"2020-09-16T10:04:38","slug":"5o-primaria-listado-de-materiales-curso-2020-2021","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/16\/5o-primaria-listado-de-materiales-curso-2020-2021\/","title":{"rendered":"5\u00ba PRIMARIA: LISTADO DE MATERIALES CURSO 2020-2021"},"content":{"rendered":"<ul>\n<li>L\u00e1piz, borrador, sacapuntas y bol\u00edgrafos azul y rojo.<\/li>\n<li>Caja de l\u00e1pices de colores y rotuladores.<\/li>\n<li>Diccionario de lengua espa\u00f1ola (*)<\/li>\n<li>Diccionario de ingl\u00e9s-espa\u00f1ol, espa\u00f1ol-ingl\u00e9s. (*)<\/li>\n<li>Agenda tama\u00f1o cuartilla con una hoja para cada d\u00eda.<\/li>\n<li>Regla r\u00edgida y numerada de 30 cms.<\/li>\n<li>Solamente para el 3er trimestre: comp\u00e1s, escuadra, cartab\u00f3n y transportador.<\/li>\n<li>2 cuadernos grandes de cuadritos (4 mil\u00edmetros) de 100 hojas con espiral (tama\u00f1o folio A4, con margen, que no tengan hojas perforadas o troqueladas).<\/li>\n<li>Carpeta de gomas tama\u00f1o folio con 10 fundas de pl\u00e1stico multitaladro.<\/li>\n<li>Pegamento de barra y tijeras sin punta (*)<\/li>\n<li>Cuaderno de pentagramas (*)<\/li>\n<li>Rotulador azul para pizarra Veleda y gamuza limpiagafas para borrar.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>LOS ALUMNOS PUEDEN REUTILIZAR LOS MATERIALES MARCADOS CON UN (*) QUE TENGAN DE CURSOS ANTERIORES, siempre y cuando est\u00e9n en buenas condiciones.<\/p>\n<p>&nbsp;<\/p>\n<p>TODO EL MATERIAL DEBE ESTAR IDENTIFICADO CON NOMBRE Y APELLIDOS.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutoras y tutores de 5\u00ba de Primaria<\/p>\n<p>&nbsp;<\/p>\n<p>Os dejamos el documento en PDF por si quer\u00e9is descargarlo.<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/09\/5o-PRIMARIA-LISTADO-DE-MATERIAL.pdf\">5\u00ba PRIMARIA LISTADO DE MATERIAL<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e1piz, borrador, sacapuntas y bol\u00edgrafos azul y rojo. Caja de l\u00e1pices de colores y rotuladores. Diccionario de lengua espa\u00f1ola (*) Diccionario de ingl\u00e9s-espa\u00f1ol, espa\u00f1ol-ingl\u00e9s. (*) Agenda tama\u00f1o cuartilla con una hoja para cada d\u00eda. Regla r\u00edgida y numerada de 30 cms. Solamente para el 3er trimestre: comp\u00e1s, escuadra, cartab\u00f3n y transportador. 2 cuadernos grandes de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/16\/5o-primaria-listado-de-materiales-curso-2020-2021\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab5\u00ba PRIMARIA: LISTADO DE MATERIALES CURSO 2020-2021\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,77],"tags":[],"post_folder":[],"class_list":["post-8057","post","type-post","status-publish","format-standard","hentry","category-5-primaria","category-libros-de-texto-y-materiales"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/5-primaria\/\" rel=\"category tag\">5\u00ba Primaria<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/secretaria\/libros-de-texto-y-materiales\/\" rel=\"category tag\">LIBROS DE TEXTO Y MATERIALES<\/a>","rttpg_excerpt":"L\u00e1piz, borrador, sacapuntas y bol\u00edgrafos azul y rojo. Caja de l\u00e1pices de colores y rotuladores. Diccionario de lengua espa\u00f1ola (*) Diccionario de ingl\u00e9s-espa\u00f1ol, espa\u00f1ol-ingl\u00e9s. (*) Agenda tama\u00f1o cuartilla con una hoja para cada d\u00eda. Regla r\u00edgida y numerada de 30 cms. Solamente para el 3er trimestre: comp\u00e1s, escuadra, cartab\u00f3n y transportador. 2 cuadernos grandes de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8057"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8057\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8057"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}