{"id":8114,"date":"2020-09-25T07:48:41","date_gmt":"2020-09-25T07:48:41","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8114"},"modified":"2020-09-25T07:48:41","modified_gmt":"2020-09-25T07:48:41","slug":"6o-primaria-autorizaciones-impresos-y-correos-de-maestros-as","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/25\/6o-primaria-autorizaciones-impresos-y-correos-de-maestros-as\/","title":{"rendered":"6\u00ba PRIMARIA: AUTORIZACIONES, IMPRESOS Y CORREOS DE MAESTROS\/AS"},"content":{"rendered":"<p>Aranjuez, 25 de septiembre de 2020<\/p>\n<p>Estimadas familias<\/p>\n<p>Nos ponemos en contacto con ustedes, tras estos primeros d\u00edas de clase, con la finalidad de comenzar los contactos personales con las familias, tambi\u00e9n queremos haceros llegar los distintos modelos de <span class=\"marktdgcq1h2s\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">autorizaciones<\/span> e impresos del Centro, ten\u00e9is que rellenarlos y enviarlos al correo personal de cada tutora (indicar en el asunto el nombre y apellidos de alumno\/a), lo antes posible, todas aquellas personas que no puedan entregar los documentos pueden hacerlo en papel.<\/p>\n<p>&nbsp;<\/p>\n<p>Recordamos que los documentos oficiales deben ir firmados por padre y madre o tutor\/es legales.<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/09\/FICHA-DE-DATOS-REGISTRO-DEL-ALUMNADO-CURSO-2020-2021-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">FICHA DE DATOS REGISTRO DEL ALUMNADO CURSO 2020-2021<\/a>\u00a0( a rellenar por todos los alumnos\/as).<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/01\/CONSENTIMIENTO-IMAGENES-DATOS-UTILIZ.CENTRO-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">CONSENTIMIENTO IM\u00c1GENES Y\/O DATOS PERSONALES UTILIZACI\u00d3N CENTRO<\/a>\u00a0(a rellenar por todos los alumnos\/as).<\/p>\n<p>&nbsp;<\/p>\n<p>Rellenar y enviar los siguientes impresos y\u00a0<span class=\"marktdgcq1h2s\" data-markjs=\"true\" data-ogac=\"\" data-ogab=\"\" data-ogsc=\"\" data-ogsb=\"\">autorizaciones<\/span>\u00a0\u00fanicamente si fuera necesario:<\/p>\n<p><a href=\"https:\/\/colegiocarlosiii.com\/wp-content\/uploads\/2020\/09\/AUTORIZACI%C3%93N-SALIDA-SOLOS-5%C2%BA-y-6%C2%BA-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">AUTORIZACI\u00d3N SALIDA SOLOS 5\u00ba y 6\u00ba<\/a><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/01\/IMPRESO-COMEDOR-ESCOLAR.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">IMPRESO COMEDOR ESCOLAR<\/a><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/09\/RECOGIDA-DEL-ALUMNO-POR-OTRAS-PERSONAS-1-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">RECOGIDA DEL ALUMNO\/A POR OTRAS PERSONAS<\/a>\u00a0(necesario fotocopia del DNI de la persona)<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/09\/JUSTIFICANTE-FALTA-ASISTENCIA-ALUMNO.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">JUSTIFICANTE FALTA ASISTENCIA ALUMNO\/A<\/a><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2020\/09\/SOLICITUD-DE-DUPLICIDAD-DE-DOCUMENTOS-1-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">SOLICITUD DE DUPLICIDAD DE DOCUMENTOS<\/a><\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n<p>Tutores\/as de 6\u00ba de Primaria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 25 de septiembre de 2020 Estimadas familias Nos ponemos en contacto con ustedes, tras estos primeros d\u00edas de clase, con la finalidad de comenzar los contactos personales con las familias, tambi\u00e9n queremos haceros llegar los distintos modelos de autorizaciones e impresos del Centro, ten\u00e9is que rellenarlos y enviarlos al correo personal de cada tutora &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/09\/25\/6o-primaria-autorizaciones-impresos-y-correos-de-maestros-as\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab6\u00ba PRIMARIA: AUTORIZACIONES, IMPRESOS Y CORREOS DE MAESTROS\/AS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-8114","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Aranjuez, 25 de septiembre de 2020 Estimadas familias Nos ponemos en contacto con ustedes, tras estos primeros d\u00edas de clase, con la finalidad de comenzar los contactos personales con las familias, tambi\u00e9n queremos haceros llegar los distintos modelos de autorizaciones e impresos del Centro, ten\u00e9is que rellenarlos y enviarlos al correo personal de cada tutora&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8114"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8114\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8114"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}