{"id":816,"date":"2016-01-27T10:56:31","date_gmt":"2016-01-27T10:56:31","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=816"},"modified":"2016-01-27T10:56:31","modified_gmt":"2016-01-27T10:56:31","slug":"jornadas-de-atletismo-escolar-seleccion-del-colegio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/01\/27\/jornadas-de-atletismo-escolar-seleccion-del-colegio\/","title":{"rendered":"JORNADAS DE ATLETISMO ESCOLAR: SELECCI\u00d3N DEL COLEGIO"},"content":{"rendered":"<p><strong>CAMPEONATO ESCOLAR DE ATLETISMO 2016<\/strong><\/p>\n<p>El martes 2 de febrero, durante la hora de recreo (12:00 a 12:30), los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria que quieran, puede acudir al pabell\u00f3n para participar en las pruebas de selecci\u00f3n del equipo de\u00a0 atletismo del Colegio, que competir\u00e1 en el Campeonato Escolar de Atletismo los s\u00e1bados 5 y 12 de marzo, por la tarde, en el Estadio Municipal del Deleite.\u00a0Las pruebas de los alevines (5\u00ba y 6\u00ba de Primaria) son 60 metros, 600 metros, salto de longitud, salto de altura, lanzamiento de peso y relevos 4&#215;60.<\/p>\n<p>\u00a0<\/p>\n<p>El jueves 4 de febrero, durante la hora de recreo (12:00 a 12:30), los alumnos y alumnas de 3\u00ba y 4\u00ba de Primaria que quieran, puede acudir al pabell\u00f3n para participar en las pruebas de selecci\u00f3n del equipo de\u00a0 atletismo del Colegio, que competir\u00e1 en el Campeonato Escolar de Atletismo los s\u00e1bados 5 y 12 de marzo, por la tarde, en el Estadio Municipal del Deleite.\u00a0Las pruebas de los benjamines (3\u00ba y 4\u00ba de Primaria) son 60 metros, 600 metros, salto de longitud y relevos 4&#215;60.<\/p>\n<p>\u00a0<\/p>\n<p>Los mejores alumnos\/as de cada prueba ser\u00e1n elegidos para representar al colegio en el Deleite. Todos los elegidos deben confirmar su disponibilidad para esos s\u00e1bados de marzo y acudir a los entrenamientos que se desarrollar\u00e1n durante los recreos, en caso negativo se seleccionar\u00e1 al siguiente alumno\/a.<\/p>\n<p>S\u00f3lo podr\u00e1n permanecer en el gimnasio durante los entrenamientos y selecci\u00f3n, los ni\u00f1os y ni\u00f1as que vayan a participar en las pruebas, y una vez concluida su intervenci\u00f3n deber\u00e1n salir al recreo.<\/p>\n<p>Los d\u00edas de entrenamiento de los alumnos\/as seleccionados, ser\u00e1n expuestos en los tablones de deportes, alumnos y en la puerta del gimnasio.<\/p>\n<p>\u00a0<\/p>\n<p>DESCUBRE LO DIVERTIDO QUE ES EL ATLETISMO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAMPEONATO ESCOLAR DE ATLETISMO 2016 El martes 2 de febrero, durante la hora de recreo (12:00 a 12:30), los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria que quieran, puede acudir al pabell\u00f3n para participar en las pruebas de selecci\u00f3n del equipo de\u00a0 atletismo del Colegio, que competir\u00e1 en el Campeonato Escolar de Atletismo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/01\/27\/jornadas-de-atletismo-escolar-seleccion-del-colegio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abJORNADAS DE ATLETISMO ESCOLAR: SELECCI\u00d3N DEL COLEGIO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-816","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"CAMPEONATO ESCOLAR DE ATLETISMO 2016 El martes 2 de febrero, durante la hora de recreo (12:00 a 12:30), los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria que quieran, puede acudir al pabell\u00f3n para participar en las pruebas de selecci\u00f3n del equipo de\u00a0 atletismo del Colegio, que competir\u00e1 en el Campeonato Escolar de Atletismo&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=816"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}