{"id":827,"date":"2016-02-04T10:01:34","date_gmt":"2016-02-04T10:01:34","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=827"},"modified":"2016-02-04T10:01:34","modified_gmt":"2016-02-04T10:01:34","slug":"contenidos-y-vocabulario-de-natural-de-natural-and-social-science-de-este-trimestre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/02\/04\/contenidos-y-vocabulario-de-natural-de-natural-and-social-science-de-este-trimestre\/","title":{"rendered":"CONTENIDOS Y VOCABULARIO DE NATURAL DE NATURAL AND SOCIAL SCIENCE DE ESTE TRIMESTRE"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>A continuaci\u00f3n les detallamos informaci\u00f3n sobre los temas \u00a0de ciencias naturales y ciencias sociales que su hijo\/ hija va a estudiar en este trimestre.<\/p>\n<p>Os adjuntamos el vocabulario m\u00e1s importante que aprender\u00e1 a lo largo de cada una de las\u00a0 unidades.<\/p>\n<p>Quisi\u00e9ramos animaros a que ayud\u00e9is a vuestro hijo\/a a interiorizar los contenidos \u00a0utilizando los recursos del CD, el libro de cuentos y la Plus Zone.<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline; font-size: 14pt;\"><strong>CIENCIAS NATURALES (NATURAL SCIENCE)<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Unidad 3 : Animals\u00a0 <\/strong><strong>(\u201cAnimales\u201d), y en ella aprender\u00e1:<\/strong><\/span><\/p>\n<ul>\n<li>Las tres funciones vitales de todo ser vivo: nutrici\u00f3n, reproducci\u00f3n y relaci\u00f3n.<\/li>\n<li>La clasificaci\u00f3n de los seres vivos en plantas y animales.<\/li>\n<li>La clasificaci\u00f3n de los animales en vertebrados e invertebrados.<\/li>\n<li>Los distintos tipos de animales vertebrados.<\/li>\n<li>Los distintos tipos de animales invertebrados.<\/li>\n<li>Los tipos de animales seg\u00fan su alimentaci\u00f3n: carn\u00edvoros, herb\u00edvoros y omn\u00edvoros.<\/li>\n<\/ul>\n<p>\u00a0\u00a0<\/p>\n<p><strong>Unit 3: Animals\u00a0(Animales)<\/strong><\/p>\n<p><strong>Lista de vocabulario<\/strong><\/p>\n<p>Living thing = ser vivo<\/p>\n<p>Non-living thing = ser inerte<\/p>\n<p>Animal Kingdom = reino animal<\/p>\n<p>Plant Kingdom = reino de las plantas<\/p>\n<p>Vertebrate = vertebrado<\/p>\n<p>Invertebrate = invertebrado<\/p>\n<p>Reptile = reptil<\/p>\n<p>Fish = pez<\/p>\n<p>Mammal = mam\u00edfero<\/p>\n<p>amphibian = anfibio<\/p>\n<p>bird = p\u00e1jaro<\/p>\n<p>feather = pluma<\/p>\n<p>wet skin = piel h\u00fameda<\/p>\n<p>scale = escama<\/p>\n<p>fin = garra<\/p>\n<p>viviparous = viv\u00edparo<\/p>\n<p>backbone = columna vertebral<\/p>\n<p>mollusc = molusco<\/p>\n<p>arthropod = artr\u00f3podo<\/p>\n<p>worm = gusano<\/p>\n<p>carnivore = carn\u00edvoro<\/p>\n<p>herbivore = herb\u00edvoro<\/p>\n<p>omnivore = omn\u00edvoro<\/p>\n<p>\u00a0\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Unidad 4 : Plants\u00a0 <\/strong><strong>(\u201cPlantas\u201d), y en ella aprender\u00e1:<\/strong><\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">\u00a0<\/span><\/p>\n<ul>\n<li>Las partes de una planta y qu\u00e9 necesitan para vivir.<\/li>\n<li>La funci\u00f3n de cada parte de la planta.<\/li>\n<li>Los tres tipos principales de plantas.<\/li>\n<li>Las plantas perennes y caducas.<\/li>\n<li>Las partes de la flor.<\/li>\n<li>El papel de la fruta en la reproducci\u00f3n de la planta.<\/li>\n<li>Las plantas sin flor.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p><strong>Unit 4: Plants\u00a0(Plantas)<\/strong><\/p>\n<p>Lista de vocabulario<\/p>\n<p>\u00a0root = ra\u00edz<\/p>\n<p>\u00a0stem = tallo<\/p>\n<p>\u00a0leaf\/leaves = hoja\/hojas<\/p>\n<p>\u00a0flower = flor<\/p>\n<p>\u00a0water = agua<\/p>\n<p>\u00a0sunlight = luz solar<\/p>\n<p>\u00a0air = aire<\/p>\n<p>\u00a0hold up = sostener, mantener en pie<\/p>\n<p>\u00a0colourful = de colores<\/p>\n<p>\u00a0seed = semilla<\/p>\n<p>\u00a0tree = \u00e1rbol<\/p>\n<p>\u00a0bush = arbusto<\/p>\n<p>\u00a0grass = hierba<\/p>\n<p>\u00a0trunk = tronco<\/p>\n<p>\u00a0deciduous = caduca<\/p>\n<p>\u00a0evergreen = perenne<\/p>\n<p>\u00a0branch = rama<\/p>\n<p>\u00a0stamen = estambre<\/p>\n<p>\u00a0petal = p\u00e9talo<\/p>\n<p>\u00a0pistil = pistilo<\/p>\n<p>\u00a0sepal = s\u00e9palo<\/p>\n<p>\u00a0non-flowering plant = planta\u00a0 sin flor<\/p>\n<p>\u00a0moss = musgo<\/p>\n<p>\u00a0fern = helecho<\/p>\n<p>\u00a0spore = espora<\/p>\n<p>\u00a0shade = sombra<\/p>\n<p>\u00a0wood = madera<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p><span style=\"text-decoration: underline; font-size: 14pt;\"><strong>CIENCIAS SOCIALES (SOCIAL SCIENCE)<\/strong><\/span><\/p>\n<p>\u00a0\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Unidad 3 : Weather (\u201cTiempo\u201d), y en ella aprender\u00e1:<\/strong><\/span><\/p>\n<ul>\n<li>Los instrumentos que utilizamos para pronosticar el tiempo.<\/li>\n<li>La distinci\u00f3n entre tiempo y clima. Las condiciones clim\u00e1ticas que puede haber en diferentes regiones.<\/li>\n<li>La importancia de proteger la atm\u00f3sfera. Las capas en que est\u00e1 dividida.<\/li>\n<\/ul>\n<p>Quisiera animaros a que ayud\u00e9is a vuestro hijo\/a a interiorizar los contenidos utilizando las audiciones y canciones de la unidad, la presentaci\u00f3n powerpoint y las actividades de Let\u2019s play! ubicados en la Plus Zone. Asimismo, os invitamos a recopilar informaci\u00f3n con vuestros hijos acerca de los s\u00edmbolos empleados en los mapas para pronosticar el tiempo.<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Weather (Tiempo) \u00a0 \u00a0Unidad 3<\/strong><\/span><\/p>\n<p><strong>Lista de vocabulario<\/strong><\/p>\n<p>\u00a0atmosphere = atm\u00f3sfera<\/p>\n<p>average temperature = temperatura media<\/p>\n<p>barometer = bar\u00f3metro<\/p>\n<p>climate = clima<\/p>\n<p>cloudy = nublado<\/p>\n<p>dry = seco<\/p>\n<p>foggy = nublado, brumoso<\/p>\n<p>hail = granizo<\/p>\n<p>hurricane = hurac\u00e1n<\/p>\n<p>lighting = iluminaci\u00f3n<\/p>\n<p>mesosphere = mesosfera<\/p>\n<p>rain gauge = pluvi\u00f3metro\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>rainy = lluvioso<\/p>\n<p>snowy = nevado<\/p>\n<p>stormy = tormentoso<\/p>\n<p>stratosphere = estratosfera<\/p>\n<p>sunny = soleado<\/p>\n<p>thermometer\u00a0 = term\u00f3metro<\/p>\n<p>tornado = tornado<\/p>\n<p>troposphere = troposfera<\/p>\n<p>weather conditions = condiciones clim\u00e1ticas<\/p>\n<p>weather map = mapa del tiempo<\/p>\n<p>wet = h\u00famedo<\/p>\n<p>wind vane = veleta<\/p>\n<p>\u00a0windy = ventoso, con viento<\/p>\n<p>\u00a0<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Unidad 4 :Landscapes (\u201cPaisajes\u201d), y en ella aprender\u00e1:<\/span><\/strong><\/p>\n<ul>\n<li>Los accidentes geogr\u00e1ficos que encontramos en la Pen\u00ednsula Ib\u00e9rica.<\/li>\n<li>La diferencia entre paisajes rurales y urbanos.<\/li>\n<li>La importancia de proteger el medio ambiente y los paisajes que nos rodean.<\/li>\n<\/ul>\n<p>Os adjunto el vocabulario m\u00e1s importante que aprender\u00e1 a lo largo de la unidad.<\/p>\n<p>Quisiera animaros a que ayud\u00e9is a vuestro hijo\/a a interiorizar los contenidos utilizando las audiciones y canciones de la unidad, la presentaci\u00f3n powerpoint y las actividades de Let\u2019s play! ubicados en la Plus Zone. Asimismo, os invitamos \u00a0a comentar con vuestros hijos los diferentes paisajes rurales y urbanos que hay\u00e1is visitado, as\u00ed como la importancia de preservarlos limpios y cuidados para nuestra herencia cultural.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Lista de vocabulario<\/strong><\/p>\n<p>\u00a0archipelago = archipi\u00e9lago<\/p>\n<p>beach = playa<\/p>\n<p>buildings = edificios<\/p>\n<p>cape = cabo<\/p>\n<p>coastal landscape = paisaje costero<\/p>\n<p>farm animals = animales de granja<\/p>\n<p>flat landscape = paisaje llano<\/p>\n<p>gulf = golfo<\/p>\n<p>island = isla<\/p>\n<p>landform = accidente geogr\u00e1fico<\/p>\n<p>man-made = artificial<\/p>\n<p>mountain landscape = paisaje monta\u00f1oso<\/p>\n<p>mountain range = coordillera\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>peninsula = pen\u00ednsula<\/p>\n<p>plain = llanura<\/p>\n<p>plants = plantas<\/p>\n<p>port = puerto mar\u00edtimo<\/p>\n<p>preserve = preservar<\/p>\n<p>recycle = reciclar<\/p>\n<p>reduce = reducir<\/p>\n<p>reuse = reutilizar<\/p>\n<p>sea = mar<\/p>\n<p>sheep = ovejas<\/p>\n<p>traffic lights = sem\u00e1foros<\/p>\n<p>valley = valle<\/p>\n<p><strong>Sin duda, vuestra colaboraci\u00f3n ayudar\u00e1 a que vuestro hijo\/a aprenda y se divierta. <\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Saludos,<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Las profesoras de 2\u00ba de Primaria<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Boney e Irma<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias:<\/p>\n<p>A continuaci\u00f3n les detallamos informaci\u00f3n sobre los temas \u00a0de ciencias naturales y ciencias sociales que su hijo\/ hija va a estudiar en este trimestre.<\/p>\n<p>Os adjuntamos el vocabulario m\u00e1s importante que aprender\u00e1 a lo largo de cada una de las\u00a0 unidades.<\/p>\n<p>Quisi\u00e9ramos animaros a que ayud\u00e9is a vuestro hijo\/a a interiorizar los contenidos \u00a0utilizando los recursos del CD, el libro de cuentos y la Plus Zone.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"post_folder":[],"class_list":["post-827","post","type-post","status-publish","format-standard","hentry","category-2-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/2-primaria\/\" rel=\"category tag\">2\u00ba Primaria<\/a>","rttpg_excerpt":"Estimadas familias: A continuaci\u00f3n les detallamos informaci\u00f3n sobre los temas \u00a0de ciencias naturales y ciencias sociales que su hijo\/ hija va a estudiar en este trimestre. Os adjuntamos el vocabulario m\u00e1s importante que aprender\u00e1 a lo largo de cada una de las\u00a0 unidades. Quisi\u00e9ramos animaros a que ayud\u00e9is a vuestro hijo\/a a interiorizar los contenidos&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/827\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=827"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}