{"id":8361,"date":"2020-10-30T06:03:49","date_gmt":"2020-10-30T06:03:49","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8361"},"modified":"2020-10-30T06:03:49","modified_gmt":"2020-10-30T06:03:49","slug":"descubrimos-el-universo-con-la-ayuda-de-un-astronauta-perdido","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/10\/30\/descubrimos-el-universo-con-la-ayuda-de-un-astronauta-perdido\/","title":{"rendered":"DESCUBRIMOS EL UNIVERSO CON LA AYUDA DE UN ASTRONAUTA PERDIDO"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Las clases de Infantil 5 a\u00f1os se <\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">han encontrado en el patio <\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\"> un astronauta de la NASA, <\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">estaba un poco desorientado, juntos han empezado a descubrir cosas del Universo.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Elab2u4X0AE1Ms2?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/ElZ2oPfWMAE5IDM?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"154\" height=\"206\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/Elab4ZFXgAA5XmL?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"514\" height=\"290\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las clases de Infantil 5 a\u00f1os se han encontrado en el patio un astronauta de la NASA, estaba un poco desorientado, juntos han empezado a descubrir cosas del Universo. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-8361","post","type-post","status-publish","format-standard","hentry","category-5-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/5-anos\/\" rel=\"category tag\">5 A\u00f1os<\/a>","rttpg_excerpt":"Las clases de Infantil 5 a\u00f1os se han encontrado en el patio un astronauta de la NASA, estaba un poco desorientado, juntos han empezado a descubrir cosas del Universo. &nbsp;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8361"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8361\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8361"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}