{"id":8373,"date":"2020-11-02T14:58:26","date_gmt":"2020-11-02T14:58:26","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8373"},"modified":"2020-11-02T14:58:26","modified_gmt":"2020-11-02T14:58:26","slug":"sofia-pequena-artista-y-disenora-de-interiores","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2020\/11\/02\/sofia-pequena-artista-y-disenora-de-interiores\/","title":{"rendered":"SOF\u00cdA, PEQUE\u00d1A ARQUITECTA Y DISE\u00d1ORA DE INTERIORES"},"content":{"rendered":"<p><span data-offset-key=\"9c25o-0-0\">Sof\u00eda, alumna de 6\u00ba de Primaria, esta semana pasada quiso compartir con su clase la fabulosa casa que cre\u00f3 durante el c<\/span><span data-offset-key=\"9c25o-1-0\">ofinamiento<\/span><span data-offset-key=\"9c25o-2-0\"> \u00abpara pasar el rato\u00bb, felicidades peque\u00f1a arquitecta y dise\u00f1adora de interiores.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/El04pnaXYAIwfMR?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/El04po4X0AAK6Hc?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/El04pteWkAIA1uP?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/El04ptvXgAQVnib?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"474\" height=\"356\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sof\u00eda, alumna de 6\u00ba de Primaria, esta semana pasada quiso compartir con su clase la fabulosa casa que cre\u00f3 durante el cofinamiento \u00abpara pasar el rato\u00bb, felicidades peque\u00f1a arquitecta y dise\u00f1adora de interiores.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-8373","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Sof\u00eda, alumna de 6\u00ba de Primaria, esta semana pasada quiso compartir con su clase la fabulosa casa que cre\u00f3 durante el cofinamiento \u00abpara pasar el rato\u00bb, felicidades peque\u00f1a arquitecta y dise\u00f1adora de interiores.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8373"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8373\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8373"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}