{"id":865,"date":"2016-02-26T14:56:50","date_gmt":"2016-02-26T14:56:50","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=865"},"modified":"2016-02-26T14:56:50","modified_gmt":"2016-02-26T14:56:50","slug":"revisiones-examenes-3-e-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/02\/26\/revisiones-examenes-3-e-primaria\/","title":{"rendered":"REVISIONES EX\u00c1MENES 3\u00ba E.PRIMARIA"},"content":{"rendered":"<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Estimadas familias:<\/span><\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">En los grupos del nivel de 3\u00ba Primaria se llevar\u00e1 a cabo la revisi\u00f3n de ex\u00e1menes los 1\u00bas Martes de mes, coincidiendo la pr\u00f3xima revisi\u00f3n con el martes 01 de marzo de 2016.<\/span><\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">La informaci\u00f3n sobre los mismos, se realizar\u00e1 en las Aulas de las Tutor\u00edas.<\/span><\/p>\n<p><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Un saludo afectuoso.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LAS\/LOS TUTORES\/AS.<\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: En los grupos del nivel de 3\u00ba Primaria se llevar\u00e1 a cabo la revisi\u00f3n de ex\u00e1menes los 1\u00bas Martes de mes, coincidiendo la pr\u00f3xima revisi\u00f3n con el martes 01 de marzo de 2016. La informaci\u00f3n sobre los mismos, se realizar\u00e1 en las Aulas de las Tutor\u00edas. Un saludo afectuoso.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LAS\/LOS TUTORES\/AS. \u00a0 \u00a0 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/02\/26\/revisiones-examenes-3-e-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abREVISIONES EX\u00c1MENES 3\u00ba E.PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"post_folder":[],"class_list":["post-865","post","type-post","status-publish","format-standard","hentry","category-3-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3-primaria\/\" rel=\"category tag\">3\u00ba Primaria<\/a>","rttpg_excerpt":"Estimadas familias: En los grupos del nivel de 3\u00ba Primaria se llevar\u00e1 a cabo la revisi\u00f3n de ex\u00e1menes los 1\u00bas Martes de mes, coincidiendo la pr\u00f3xima revisi\u00f3n con el martes 01 de marzo de 2016. La informaci\u00f3n sobre los mismos, se realizar\u00e1 en las Aulas de las Tutor\u00edas. Un saludo afectuoso.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LAS\/LOS TUTORES\/AS. \u00a0 \u00a0&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/865\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=865"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}