{"id":874,"date":"2016-03-02T10:00:40","date_gmt":"2016-03-02T10:00:40","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=874"},"modified":"2016-03-02T10:00:40","modified_gmt":"2016-03-02T10:00:40","slug":"taller-de-educacion-para-la-salud","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/03\/02\/taller-de-educacion-para-la-salud\/","title":{"rendered":"TALLER DE EDUCACI\u00d3N PARA LA SALUD"},"content":{"rendered":"<p>Durante las pr\u00f3ximas semanas, todos los alumnos y alumnas desde 5 a\u00f1os hasta 6\u00ba de Primaria del centro, van a realizar un taller para aprender a evitar ciertos accidentes, tener buenos h\u00e1bitos higi\u00e9nicos y saber manejar situaciones de emergencia con seguridad y de forma adecuada.<\/p>\n<p>Los talleres se realizar\u00e1n por clases, en una \u00fanica sesi\u00f3n y los impartir\u00e1 la Enfermera Escolar del centro, Lara Guiti\u00e9rrez Lav\u00edn.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Los contenidos que se van a trabajar en cada nivel son los siguientes:<\/p>\n<p>5 a\u00f1os: Prevenci\u00f3n de accidentes en casa y en el colegio.<\/p>\n<p>1\u00ba, 2\u00ba y 3\u00ba de Primaria: H\u00e1bitos de higiene.<\/p>\n<p>4\u00ba, 5\u00ba y 6\u00ba de Primaria: Iniciaci\u00f3n a los primeros auxilios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante las pr\u00f3ximas semanas, todos los alumnos y alumnas desde 5 a\u00f1os hasta 6\u00ba de Primaria del centro, van a realizar un taller para aprender a evitar ciertos accidentes, tener buenos h\u00e1bitos higi\u00e9nicos y saber manejar situaciones de emergencia con seguridad y de forma adecuada. Los talleres se realizar\u00e1n por clases, en una \u00fanica sesi\u00f3n &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/03\/02\/taller-de-educacion-para-la-salud\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTALLER DE EDUCACI\u00d3N PARA LA SALUD\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-874","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Durante las pr\u00f3ximas semanas, todos los alumnos y alumnas desde 5 a\u00f1os hasta 6\u00ba de Primaria del centro, van a realizar un taller para aprender a evitar ciertos accidentes, tener buenos h\u00e1bitos higi\u00e9nicos y saber manejar situaciones de emergencia con seguridad y de forma adecuada. Los talleres se realizar\u00e1n por clases, en una \u00fanica sesi\u00f3n&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=874"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/874\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=874"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}