{"id":8774,"date":"2021-02-03T13:35:50","date_gmt":"2021-02-03T13:35:50","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=8774"},"modified":"2021-02-03T13:35:50","modified_gmt":"2021-02-03T13:35:50","slug":"juntos-aprendimos-juntos-disfrutamos-de-tu-musica","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/02\/03\/juntos-aprendimos-juntos-disfrutamos-de-tu-musica\/","title":{"rendered":"JUNTOS APRENDIMOS, JUNTOS DISFRUTAMOS DE T\u00da M\u00daSICA"},"content":{"rendered":"<h6><strong>Uno de nuestros antiguos alumnos el 29 de enero de 2021, lanz\u00f3 su primer videoclip \u00abVETE\u00bb, queremos compartir con toda la Comunidad Educativa sus proyectos, sue\u00f1os e ilusiones y apoyar su proyecto. Felicidades David.<\/strong><\/p>\n<p><strong>A continuaci\u00f3n os dejamos el videoclip e informaci\u00f3n referente sobre \u00e9l.\u00a0<\/strong><\/h6>\n<h6 class=\"wsite-content-title\">\u00bfQui\u00e9n soy?<\/h6>\n<div class=\"paragraph\">\u00a1Hola! Me llamo David Di\u00e9guez, tengo 20 a\u00f1os y soy un cantautor madrile\u00f1o. Ya que est\u00e1s leyendo esto, me gustar\u00eda presentarte mi proyecto y contarte qu\u00e9 puedo ofrecer como artista para que me conozcas un poco m\u00e1s. En primer lugar, llevo cerca de cuatro a\u00f1os subiendo covers a redes sociales a guitarra y voz, cuento con 16.500 seguidores actualmente en Instagram (@davidieguezmusic), todos ellos reales, y con un p\u00fablico comprometido con cada cosa que hago. Algunos de mis v\u00eddeos han llegado a las 50.000 reproducciones (<a href=\"https:\/\/www.instagram.com\/p\/Br76FszovqI\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/p\/Br76FszovqI\/<\/a>) o (<a href=\"https:\/\/www.instagram.com\/p\/B-klG69lvEj\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/p\/B-klG69lvEj\/<\/a>). Durante la cuarentena tuve la suerte de tener\u00a0<em>RePosts<\/em>\u00a0de artistas como David Otero, Sof\u00eda Ellar, Orozco, Bisbal, Roi M\u00e9ndez, Dani Mart\u00edn o Sinsinati. Adem\u00e1s, particip\u00e9 en 2018 en un concurso organizado por Dvicio en el que finalic\u00e9 en cuarto lugar (<a href=\"https:\/\/www.instagram.com\/p\/BfRfoOqFR8b\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/p\/BfRfoOqFR8b\/<\/a>). Tambi\u00e9n sal\u00ed en TVEMOS, programa de La 1 de TVE (<a href=\"https:\/\/www.instagram.com\/stories\/highlights\/18037599520107781\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/stories\/highlights\/18037599520107781\/<\/a>).<br \/>\n\u200b<\/p>\n<p>Acabo de lanzar al mercado mi primer single, \u201cSin M\u00e1s\u201d, una balada Pop que trata de reflejar desde el coraz\u00f3n una experiencia personal, con toda la sinceridad posible, como cada cosa que escribo. Se ha lanzado de manera independiente, es una canci\u00f3n escrita e interpretada por m\u00ed, y grabada, producida y masterizada en un estudio tambi\u00e9n independiente en Madrid\u00a0<a href=\"https:\/\/www.emusiclab.net\/\">(@emusiclab.spain).<\/a>\u00a0Me encuentro muy c\u00f3modo en el Pop mel\u00f3dico en espa\u00f1ol, escribo temas cada d\u00eda y mi objetivo es que la gente viva historias diferentes a trav\u00e9s de mis temas. Actualmente estoy trabajando en la confecci\u00f3n de mi primer EP, adem\u00e1s de en la grabaci\u00f3n del videoclip de mi segundo single, \u201cVete\u201d, que ver\u00e1 la luz a finales de a\u00f1o. Me apasiona la m\u00fasica, aprend\u00ed de forma autodidacta con 14 a\u00f1os a tocar la guitarra y creo que tengo facilidad para crear historias. \u00a1Gracias por valorar mi trabajo, echa un vistazo a mis redes!<\/div>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"David Di\u00e9guez - Vete (Videoclip Oficial)\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/1xO2AuceZbE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de nuestros antiguos alumnos el 29 de enero de 2021, lanz\u00f3 su primer videoclip \u00abVETE\u00bb, queremos compartir con toda la Comunidad Educativa sus proyectos, sue\u00f1os e ilusiones y apoyar su proyecto. Felicidades David. A continuaci\u00f3n os dejamos el videoclip e informaci\u00f3n referente sobre \u00e9l.\u00a0 \u00bfQui\u00e9n soy? \u00a1Hola! Me llamo David Di\u00e9guez, tengo 20 a\u00f1os &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/02\/03\/juntos-aprendimos-juntos-disfrutamos-de-tu-musica\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abJUNTOS APRENDIMOS, JUNTOS DISFRUTAMOS DE T\u00da M\u00daSICA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66,68,10,19],"tags":[],"post_folder":[],"class_list":["post-8774","post","type-post","status-publish","format-standard","hentry","category-6-primaria","category-actividades-noticias","category-centro","category-ex-alumnos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/ex-alumnos\/\" rel=\"category tag\">Ex-Alumnos<\/a>","rttpg_excerpt":"Uno de nuestros antiguos alumnos el 29 de enero de 2021, lanz\u00f3 su primer videoclip \u00abVETE\u00bb, queremos compartir con toda la Comunidad Educativa sus proyectos, sue\u00f1os e ilusiones y apoyar su proyecto. Felicidades David. A continuaci\u00f3n os dejamos el videoclip e informaci\u00f3n referente sobre \u00e9l.\u00a0 \u00bfQui\u00e9n soy? \u00a1Hola! Me llamo David Di\u00e9guez, tengo 20 a\u00f1os&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=8774"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/8774\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=8774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=8774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=8774"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=8774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}