{"id":900,"date":"2016-03-31T08:57:59","date_gmt":"2016-03-31T08:57:59","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=900"},"modified":"2016-03-31T08:57:59","modified_gmt":"2016-03-31T08:57:59","slug":"las-canciones-del-mes-de-abril","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/03\/31\/las-canciones-del-mes-de-abril\/","title":{"rendered":"LAS CANCIONES DEL MES DE ABRIL"},"content":{"rendered":"<p>Este mes de abril, hemos seleccionado como temas de la m\u00fasica de mi cole, la Naturaleza y los Libros, dado que el 22 de abril es el D\u00eda Internacional de la Madre Tierra y el 23 de abril es el D\u00eda Mundial del Libro.<\/p>\n<p>En el tabl\u00f3n de anuncios de alumnos\/as (en el piso de arriba, junto a la sala de inform\u00e1tica) hay una lista para que podamos escribir las canciones relacionadas con el tema del mes y Sarah Dj designar\u00e1 que canci\u00f3n escucharemos cada d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mes de abril, hemos seleccionado como temas de la m\u00fasica de mi cole, la Naturaleza y los Libros, dado que el 22 de abril es el D\u00eda Internacional de la Madre Tierra y el 23 de abril es el D\u00eda Mundial del Libro. En el tabl\u00f3n de anuncios de alumnos\/as (en el piso de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/03\/31\/las-canciones-del-mes-de-abril\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLAS CANCIONES DEL MES DE ABRIL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"post_folder":[],"class_list":["post-900","post","type-post","status-publish","format-standard","hentry","category-la-musica-de-mi-cole"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/la-musica-de-mi-cole\/\" rel=\"category tag\">La m\u00fasica de mi cole<\/a>","rttpg_excerpt":"Este mes de abril, hemos seleccionado como temas de la m\u00fasica de mi cole, la Naturaleza y los Libros, dado que el 22 de abril es el D\u00eda Internacional de la Madre Tierra y el 23 de abril es el D\u00eda Mundial del Libro. En el tabl\u00f3n de anuncios de alumnos\/as (en el piso de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/900\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=900"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}