{"id":9010,"date":"2021-04-12T13:13:01","date_gmt":"2021-04-12T13:13:01","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9010"},"modified":"2021-04-12T13:13:01","modified_gmt":"2021-04-12T13:13:01","slug":"que-hacen-los-masmadrugadores-as-del-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/04\/12\/que-hacen-los-masmadrugadores-as-del-carlos-iii\/","title":{"rendered":"\u00bfQU\u00c9 HACEN LOS M\u00c1SMADRUGADORES\/AS DEL CARLOS III?"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Los m\u00e1s madrugadores\/as del Colegio Carlos III<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\"> aprovechan los Primeros del Cole p<\/span><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">ara jugar, pintar, repasar, hacer la tarea y convivir por Grupos Burbujas.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/pbs.twimg.com\/media\/EyWk8LeXIAAbHiD?format=jpg&amp;name=360x360\" alt=\"Imagen\" width=\"199\" height=\"264\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EyWk9DKXEAEK4Z5?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00e1s madrugadores\/as del Colegio Carlos III aprovechan los Primeros del Cole para jugar, pintar, repasar, hacer la tarea y convivir por Grupos Burbujas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-9010","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Los m\u00e1s madrugadores\/as del Colegio Carlos III aprovechan los Primeros del Cole para jugar, pintar, repasar, hacer la tarea y convivir por Grupos Burbujas.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9010"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9010\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9010"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}