{"id":9079,"date":"2021-04-26T18:35:50","date_gmt":"2021-04-26T16:35:50","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9079"},"modified":"2021-04-26T18:35:50","modified_gmt":"2021-04-26T16:35:50","slug":"comunicado-pruebas-externas-3o-primaria-curso-2020-2021","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/04\/26\/comunicado-pruebas-externas-3o-primaria-curso-2020-2021\/","title":{"rendered":"COMUNICADO PRUEBAS EXTERNAS 3\u00ba PRIMARIA (CURSO 2020-2021)"},"content":{"rendered":"<p style=\"text-align: right;\">Aranjuez, 26 de abril de 2021.<\/p>\n<p style=\"text-align: justify;\">Estimadas familias:<\/p>\n<p style=\"text-align: justify;\">Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria de la Comunidad de Madrid, va a participar en la Evaluaci\u00f3n individualizada de 3\u00ba de Primaria seg\u00fan\u00a0 <strong><em>RESOLUCI\u00d3N de 16 de marzo de 2021, de las Viceconsejer\u00edas de Pol\u00edtica Educativa \u00a0y de Organizaci\u00f3n Educativa, por la que se dictan instrucciones para la celebraci\u00f3n de las pruebas correspondientes a la evaluaci\u00f3n individualizada de los alumnos de tercer curso de Educaci\u00f3n Primaria de la Comunidad de Madrid, en el curso acad\u00e9mico 2020-2021<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Esta Evaluaci\u00f3n tendr\u00e1 lugar en las siguientes <strong>fechas<\/strong>:<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>06 de mayo, evaluaci\u00f3n de la competencia ling\u00fc\u00edstica en lengua espa\u00f1ola: <\/strong>\n<ol>\n<li>Expresi\u00f3n escrita en lengua espa\u00f1ola. (25 min. duraci\u00f3n)<\/li>\n<li>Comprensi\u00f3n oral y escrita. (50 min. Duraci\u00f3n)<\/li>\n<\/ol>\n<\/li>\n<li><strong>07\u00a0 de mayo, evaluaci\u00f3n de la competencia matem\u00e1tica: <\/strong>desarrollada en dos partes. (40 min. cada una)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong><em>finalidad<\/em><\/strong> de esta prueba es la comprobaci\u00f3n del grado de adquisici\u00f3n de la competencia en comunicaci\u00f3n ling\u00fc\u00edstica y de la competencia matem\u00e1tica.<\/p>\n<p style=\"text-align: justify;\">Los resultados de la evaluaci\u00f3n de 3\u00ba de Educaci\u00f3n Primaria ofrecer\u00e1n al centro, a trav\u00e9s del Claustro y el Consejo Escolar, la informaci\u00f3n necesaria para analizar, valorar y adoptar internamente, si procede, las medidas y propuestas de mejora que se consideren necesarias a aplicar sobre el proceso de ense\u00f1anza-aprendizaje del alumnado y que revertir\u00e1n en la elaboraci\u00f3n de planes de mejora de los resultados. De igual manera, proporcionar\u00e1 a las familias informaci\u00f3n sobre el progreso de sus hijos en el sistema educativo.<\/p>\n<p style=\"text-align: justify;\">\u00a0Esta informaci\u00f3n constar\u00e1 en el expediente y el historial acad\u00e9mico, pero no condicionar\u00e1 la promoci\u00f3n al curso siguiente.<\/p>\n<p style=\"text-align: justify;\">A trav\u00e9s de la presente carta les agradecemos su participaci\u00f3n en estas evaluaciones.<\/p>\n<p style=\"text-align: justify;\">Reciban un cordial saludo.<\/p>\n<p style=\"text-align: right;\">EQUIPO DIRECTIVO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 26 de abril de 2021. Estimadas familias: Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria de la Comunidad de Madrid, va a participar en la Evaluaci\u00f3n individualizada de 3\u00ba de Primaria seg\u00fan\u00a0 RESOLUCI\u00d3N de 16 de marzo de 2021, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/04\/26\/comunicado-pruebas-externas-3o-primaria-curso-2020-2021\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO PRUEBAS EXTERNAS 3\u00ba PRIMARIA (CURSO 2020-2021)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,29],"tags":[],"post_folder":[],"class_list":["post-9079","post","type-post","status-publish","format-standard","hentry","category-3-primaria","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3-primaria\/\" rel=\"category tag\">3\u00ba Primaria<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Aranjuez, 26 de abril de 2021. Estimadas familias: Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria de la Comunidad de Madrid, va a participar en la Evaluaci\u00f3n individualizada de 3\u00ba de Primaria seg\u00fan\u00a0 RESOLUCI\u00d3N de 16 de marzo de 2021,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9079"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9079\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9079"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}