{"id":9332,"date":"2021-07-04T17:18:49","date_gmt":"2021-07-04T15:18:49","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9332"},"modified":"2021-07-04T17:18:49","modified_gmt":"2021-07-04T15:18:49","slug":"propuesta-extraescolares-curso-2021-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/07\/04\/propuesta-extraescolares-curso-2021-2022\/","title":{"rendered":"PROPUESTA EXTRAESCOLARES CURSO 2021-2022 (AGOSTO 2021)"},"content":{"rendered":"<div>A continuaci\u00f3n os remitimos toda la informaci\u00f3n relativa a las actividades extraescolares del cursos 2021-2022. Surgida de numerosas reuniones con la Delegaci\u00f3n de Educaci\u00f3n del Ayuntamiento de Aranjuez, Junta Directiva del AMPA, monitores\/responsables\/coordinadores de entidades que imparten actividades socieducativas en el Colegio, coordinadora local de la empresa Getting Better.<\/div>\n<div><\/div>\n<div>Lanzamos la propuesta con el fin de que las familias teng\u00e1is lo antes posible la propuesta de actividades que se van a realizar en el Colegio de vuestros hijos\/as, iremos completando, suprimiendo y modificando dicha propuesta teniendo en cuenta las medidas sanitarias y educativas que se vayan adoptando para hacer frente al COVID-19, apertura de grupos y\/o circunstancias extraordinarias que pudieran suceder.<\/div>\n<div><\/div>\n<div>Las actividades comenzar\u00e1n siempre que haya al menos 5 personas inscritas en la actividad, os informamos que hay dos tipos de actividades:<\/div>\n<div>&#8211; Gestionadas por la Delegaci\u00f3n de Educaci\u00f3n del Ayuntamiento Aranjuez, a trav\u00e9s de la empresa Getting Better (color amarillo en el cuadro resumen que aparece a continuaci\u00f3n).<\/div>\n<div>&#8211; Organizadas por el AMPA del Centro (color azul en el cuadro resumen que aparece a continuaci\u00f3n).<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9414\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-2.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-2.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-2-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-2-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9437 size-full\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva1-3.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva1-3.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva1-3-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva1-3-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/div>\n<div>En los siguientes enlaces os los dejamos en PDF por si quer\u00e9is descargar las propuestas de actividades de este curso, tanto para Infantil como para Primaria:<\/div>\n<div><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/PROPUESTA-DE-ACTIVIDADES-EXTRAESCOLARES-21-22-INFANTIL-Y-PRIMARIA-28-DE-AGOSTO-1.pdf\">PROPUESTA DE ACTIVIDADES EXTRAESCOLARES 21-22 INFANTIL Y PRIMARIA (AGOSTO 2021)<\/a><\/div>\n<div><\/div>\n<div>Para los alumnos\/as de Primaria, el AMPA oferta la posibilidad de formar parte en los equipos de f\u00fatbol y baloncesto del Colegio, con aproximadamente dos horas de entrenamiento semanal y participar en los Juegos Escolares o en partidos con otros Centros Escolares.<\/div>\n<div><\/div>\n<div>Todas las actividades extraescolares que se realicen en el Centro, al igual del curso pasado, se adaptar\u00e1n a las medidas Covid-19, adoptadas por el Centro. En los pr\u00f3ximos d\u00edas iremos informando de los objetivos y el contenido de las distintas actividades que se proponen para este curso.<\/div>\n<div><\/div>\n<div>\n<p>Desde la empresa Getting Better nos transmiten la siguiente informaci\u00f3n:<\/p>\n<p><em>Los programas de conciliaci\u00f3n municipal Los Primeros del Cole, Las Tardes en mi Cole y Actividades Extraescolares, les informamos que desde el 1 de Agosto de 2021 est\u00e1n abiertos los plazos de inscripci\u00f3n a los mismos, a trav\u00e9s de la web municipal. Les recordamos que no existe reserva de plaza para los\/las participantes del curso anterior, de tal forma que la inscripci\u00f3n en los mencionados programas debe realizarse de forma obligatoria.<\/em><\/p>\n<p><em>Indicarles as\u00ed mismo que, para aquellas familias que no dispongan de acceso a internet, podr\u00e1n hacer la inscripci\u00f3n presencialmente del 1-15 de Septiembre.<\/em><\/p>\n<p><em>El plazo de inscripci\u00f3n para las actividades extraescolares finaliza el 24 de Septiembre.<\/em><\/p>\n<p><em>Pod\u00e9is acceder al formulario en el siguiente enlace:<\/em><\/p>\n<p><a href=\"https:\/\/www.aranjuez.es\/educacion\/#\">ht<\/a><a href=\"https:\/\/www.aranjuez.es\/educacion\/#\">tps:\/\/www.aranjuez.es\/educacion\/#<\/a>\u00a0 \u00a0(MUY IMPORTANTE: D\u00cdAS LECTIVOS 2021-2022)<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div class=\"x_v1default-style\">Desde el Departamento de Educaci\u00f3n nos remiten las Actividades Municipales Socioeducativas en d\u00edas lectivo para el siguiente curso escolar 2021-2022, para su difusi\u00f3n.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9333\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva1-1.jpg\" alt=\"\" width=\"720\" height=\"960\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9334\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2.jpg\" alt=\"\" width=\"720\" height=\"960\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2.jpg 720w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/07\/Diapositiva2-300x400.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/div>\n<div>Iremos informando seg\u00fan nos vayan llegando nuevas informaciones sobre las actividades extraescolares del curso 2021-2022.<\/div>\n<div><\/div>\n<div>Un saludo.<\/div>\n<div>Gracias por vuestra colaboraci\u00f3n.<\/div>\n<div>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0COORDINADOR DE ACTIVIDADES EXTRAESCOLARES<\/div>\n<div><\/div>\n<div><\/div>\n<div>NOTA: cualquier sugerencia, comentario, consulta o aportaci\u00f3n que quer\u00e1is realizar sobre las actividades extraescolares que se desarrollan en el Centro, pod\u00e9is realizarlo a trav\u00e9s del correo del Centro cp.carostercero.aranjuez@educa.madrid.org (asunto: extraescolares).<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n os remitimos toda la informaci\u00f3n relativa a las actividades extraescolares del cursos 2021-2022. Surgida de numerosas reuniones con la Delegaci\u00f3n de Educaci\u00f3n del Ayuntamiento de Aranjuez, Junta Directiva del AMPA, monitores\/responsables\/coordinadores de entidades que imparten actividades socieducativas en el Colegio, coordinadora local de la empresa Getting Better. Lanzamos la propuesta con el fin &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/07\/04\/propuesta-extraescolares-curso-2021-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPROPUESTA EXTRAESCOLARES CURSO 2021-2022 (AGOSTO 2021)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,68,30],"tags":[],"post_folder":[],"class_list":["post-9332","post","type-post","status-publish","format-standard","hentry","category-actividades","category-actividades-noticias","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"A continuaci\u00f3n os remitimos toda la informaci\u00f3n relativa a las actividades extraescolares del cursos 2021-2022. Surgida de numerosas reuniones con la Delegaci\u00f3n de Educaci\u00f3n del Ayuntamiento de Aranjuez, Junta Directiva del AMPA, monitores\/responsables\/coordinadores de entidades que imparten actividades socieducativas en el Colegio, coordinadora local de la empresa Getting Better. Lanzamos la propuesta con el fin&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9332"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9332\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9332"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}