{"id":947,"date":"2016-04-26T08:51:39","date_gmt":"2016-04-26T08:51:39","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=947"},"modified":"2016-04-26T08:51:39","modified_gmt":"2016-04-26T08:51:39","slug":"ayudantes-para-jornadas-deportivas-en-infantil-3-de-mayo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/04\/26\/ayudantes-para-jornadas-deportivas-en-infantil-3-de-mayo\/","title":{"rendered":"AYUDANTES PARA JORNADAS DEPORTIVAS EN INFANTIL (3 de mayo)"},"content":{"rendered":"<p>Estimadas familias de Infantil:<\/p>\n<p>El martes 3 de mayo tendr\u00e1 lugar las Jornadas Deportivas en Infantil. Para su preparaci\u00f3n y desarrollo necesitamos un padre o madre por clase. Los interesados, por favor, poneros en contacto con el tutor\/a de su hijo\/a hasta el mi\u00e9rcoles 27 de abril. En caso de haber m\u00e1s de un padre o madre se realizar\u00e1 un sorteo\u00a0 el jueves 28 de abril.<\/p>\n<p>Muchas gracias por vuestra colaboraci\u00f3n. Un saludo.<\/p>\n<p>El equipo de Infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias de Infantil: El martes 3 de mayo tendr\u00e1 lugar las Jornadas Deportivas en Infantil. Para su preparaci\u00f3n y desarrollo necesitamos un padre o madre por clase. Los interesados, por favor, poneros en contacto con el tutor\/a de su hijo\/a hasta el mi\u00e9rcoles 27 de abril. En caso de haber m\u00e1s de un padre &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/04\/26\/ayudantes-para-jornadas-deportivas-en-infantil-3-de-mayo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abAYUDANTES PARA JORNADAS DEPORTIVAS EN INFANTIL (3 de mayo)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"post_folder":[],"class_list":["post-947","post","type-post","status-publish","format-standard","hentry","category-infantil"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a>","rttpg_excerpt":"Estimadas familias de Infantil: El martes 3 de mayo tendr\u00e1 lugar las Jornadas Deportivas en Infantil. Para su preparaci\u00f3n y desarrollo necesitamos un padre o madre por clase. Los interesados, por favor, poneros en contacto con el tutor\/a de su hijo\/a hasta el mi\u00e9rcoles 27 de abril. En caso de haber m\u00e1s de un padre&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=947"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}