{"id":9633,"date":"2021-09-12T15:49:35","date_gmt":"2021-09-12T13:49:35","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9633"},"modified":"2021-09-12T15:49:35","modified_gmt":"2021-09-12T13:49:35","slug":"comunicado-ampa-inicio-de-curso-2021-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/09\/12\/comunicado-ampa-inicio-de-curso-2021-2022\/","title":{"rendered":"COMUNICADO AMPA INICIO DE CURSO 2021-2022 (INSCRIPCI\u00d3N AMPA, EXTRAESCOLARES Y JUNTA DIRECTIVA)"},"content":{"rendered":"<p>A continuaci\u00f3n os transmitimos el comunicado del AMPA \u00abInicio de Curso 2021-2022\u00bb:<\/p>\n<p style=\"text-align: right;\">Aranjuez, 12 de septiembre de 2021<\/p>\n<p>Hola familias:<\/p>\n<p>Bienvenidos al nuevo curso escolar 2021-2022.<\/p>\n<p>Como ya sab\u00e9is, debido al COVID19, los dos \u00faltimos cursos escolares, no hemos podido funcionar al 100%. Este a\u00f1o, la Junta Directiva,\u00a0 hemos decidido empezar los antes posible con nuestras actividades extraescolares y deportivas,\u00a0 y tambi\u00e9n queremos continuar con proyectos ya iniciados \u00abProyecto Patio\u00bb, colaboraci\u00f3n con el profesorado y el equipo directivo y proponeros nuevos y viejos proyectos e ideas.<\/p>\n<p>En los documentos que os adjuntamos, a continuaci\u00f3n, est\u00e1n la hoja de inscripci\u00f3n al AMPA, el formulario para apuntar a vuestros hijos\/as en las actividades extraescolares y un tr\u00edptico informativo, para que ve\u00e1is la colaboraci\u00f3n del AMPA, durante todos estos a\u00f1os.<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/INSCRIPCION-SOCIOS-AMPA.pdf\">INSCRIPCI\u00d3N SOCIOS AMPA<\/a><\/p>\n<p>Para poner en marcha cada una de las actividades extraescolares que os hemos propuesto, necesitamos un m\u00ednimo de 5 alumnos\/as por actividad. El plazo de inscripci\u00f3n finaliza el lunes 27 de septiembre, para que las actividades con el m\u00ednimo de alumnos\/as establecidos comiencen a partir del 1 de octubre, finalizar\u00e1n en mayo, en los horarios que detallamos a continuaci\u00f3n:<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/INSCRIPCION-ACTIVIDADES-EXTRAESCOLARES-AMPA-2021-2022-1-1.pdf\">INSCRIPCI\u00d3N ACTIVIDADES EXTRAESCOLARES AMPA 2021-2022<\/a><\/p>\n<p>Con la finalidad de poder formar los equipos que representen a nuestro colegio, en los Juegos Escolares 2021-2022, organizados, para los ni\u00f1os y ni\u00f1as de Primaria, por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez, desde el AMPA del CEIP Carlos III, os invitamos a que apunt\u00e9is a vuestros hijos\/as al deporte que le guste de los que ofertamos. Tan solo ten\u00e9is que rellenar la parte inferior de la hoja de inscripci\u00f3n deportes y entregarla en el AMPA o en la Secretar\u00eda del Centro (cajet\u00edn del ampa) en el horario establecido. Deber\u00e9is adjuntar una fotograf\u00eda, con el nombre del ni\u00f1o\/a y el curso por detr\u00e1s. Importante rellenar todos los datos. A propuesta de los entrenadores\/as (f\u00fatbol y baloncesto) con el fin de que cada equipo pueda disponer de balones, red, petos, botiqu\u00edn\u2026. Habr\u00e1 una cuota anual de 10 \u20ac para los NO Socios del AMPA y 5\u20ac para los Socios. Es muy importante que os apunt\u00e1is lo antes posible, para realizar la inscripci\u00f3n de los equipos en los Juegos Escolares y poder adquirir las equipaciones para el inicio de los partidos (fecha l\u00edmite 27 de septiembre de 2021). A continuaci\u00f3n, os indicamos los horarios de entrenamiento (PROVISIONALES, quedando sujetos a modificaciones acorde con las actividades extraescolares o a petici\u00f3n de la mayor\u00eda de los alumnos del equipo):<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/HOJA-DE-INSCRIPCION-DEPORTES-2021-2022.pdf\">HOJA DE INSCRIPCI\u00d3N DEPORTES 2021-2022<\/a><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/TRIPTICO-INFORMATIVO-AMPA-CARLOS-III.pdf\">TR\u00cdPTICO INFORMATIVO AMPA CARLOS III<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9638\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/TRIPTICO-INFORMATIVO-AMPA-CARLOS-III-PORTADA.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/TRIPTICO-INFORMATIVO-AMPA-CARLOS-III-PORTADA.jpg 960w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/TRIPTICO-INFORMATIVO-AMPA-CARLOS-III-PORTADA-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/09\/TRIPTICO-INFORMATIVO-AMPA-CARLOS-III-PORTADA-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Como bien sab\u00e9is, debido a la pandemia, a\u00fan no podemos hacer reuniones con los socios, no obstante, os invitamos a participar en el AMPA, de forma voluntaria en las diversas actividades que os iremos comunicando (pintura y creaci\u00f3n de juegos y elementos educativos en los patios, que pretendemos se reanude pronto, otra forma de participar es formar parte de Junta Directiva del AMPA.<br \/>\nLo principal en nuestro AMPA es hacer part\u00edcipe a todos\/as y escuchar las necesidades de todos los cursos, por lo que ser\u00eda ideal que hubiera al menos una persona por nivel, para poder distribuir el trabajo y ver necesidades, sugerencias e ideas de los distintos niveles,\u00a0 todos juntos podremos emprender nuevos proyectos y mejor el Colegio de nuestros hijos\/as. Es muy importante la implicaci\u00f3n del mayor n\u00famero de familias del Carlos III, para que nuestros hijos e hijas tengan la mejor educaci\u00f3n posible.<br \/>\nToda aquella persona interesada, en formar parte de la Junta Directiva, debe enviar un mail con vuestros datos (nombre, apellidos, tel\u00e9fono y curso) a ampacarlosiii@hotmail.es o llamadnos al tel\u00e9fono\u2026.<\/p>\n<p>Y por \u00faltimo os presentamos una peque\u00f1a explicaci\u00f3n de las actividades extraescolares propuesta por AMPA Carlos III para este curso 2021-2022:<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-circo-infantil-y-primaria-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-zumba-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-judo-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/show-musical-juega-canta-baila-y-actua-2\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-cocinillas-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-costura-creativa-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-patinaje-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-tenis-colegio-carlos-iii\/<\/p>\n<p>https:\/\/colegiocarlosiii.com\/escuela-de-pequenos-directores-colegio-carlos-iii\/<\/p>\n<p>Juntos hacemos colegio.<\/p>\n<p>\u00a1\u00a1\u00a1\u00a1Por ellos y por ellas. Porque nuestros hijos e hijas se lo merecen!!!!<\/p>\n<p style=\"text-align: right;\">JUNTA DIRECTIVA AMPA COLEGIO CARLOS III<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n os transmitimos el comunicado del AMPA \u00abInicio de Curso 2021-2022\u00bb: Aranjuez, 12 de septiembre de 2021 Hola familias: Bienvenidos al nuevo curso escolar 2021-2022. Como ya sab\u00e9is, debido al COVID19, los dos \u00faltimos cursos escolares, no hemos podido funcionar al 100%. Este a\u00f1o, la Junta Directiva,\u00a0 hemos decidido empezar los antes posible con &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/09\/12\/comunicado-ampa-inicio-de-curso-2021-2022\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO AMPA INICIO DE CURSO 2021-2022 (INSCRIPCI\u00d3N AMPA, EXTRAESCOLARES Y JUNTA DIRECTIVA)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,30],"tags":[],"post_folder":[],"class_list":["post-9633","post","type-post","status-publish","format-standard","hentry","category-ampa","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"A continuaci\u00f3n os transmitimos el comunicado del AMPA \u00abInicio de Curso 2021-2022\u00bb: Aranjuez, 12 de septiembre de 2021 Hola familias: Bienvenidos al nuevo curso escolar 2021-2022. Como ya sab\u00e9is, debido al COVID19, los dos \u00faltimos cursos escolares, no hemos podido funcionar al 100%. Este a\u00f1o, la Junta Directiva,\u00a0 hemos decidido empezar los antes posible con&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9633"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9633\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9633"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}