{"id":981,"date":"2016-05-12T13:40:13","date_gmt":"2016-05-12T13:40:13","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=981"},"modified":"2016-05-12T13:40:13","modified_gmt":"2016-05-12T13:40:13","slug":"vii-cross-escolar-urbano-colegio-carlos-iii-sabado-14-de-mayo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/05\/12\/vii-cross-escolar-urbano-colegio-carlos-iii-sabado-14-de-mayo\/","title":{"rendered":"VII CROSS ESCOLAR URBANO COLEGIO CARLOS III (s\u00e1bado 14 de mayo)"},"content":{"rendered":"<p>Tras el aplazamiento del Cross, el domingo 8 de mayo, por lluvia; este s\u00e1bado 14 de mayo (y despu\u00e9s de una semana m\u00e1s de entrenamiento y preparaci\u00f3n) se va a celebrar el VII Cross Escolar Urbano del \u00abColegio Carlos III\u00bb. La Asociaic\u00f3n de Madres y Padres de Alumnos Colegio Carlos III invita a todas las familias (ni\u00f1os, ni\u00f1as, padres, madres, abuelos, abuelas, t\u00edos, t\u00edas, &#8230;&#8230;..) del Centro y a todas las familias de Aranjuez y alrededores a participar en este evento deportivo y cultural<\/p>\n<p>El viernes 13 de mayo, se har\u00e1 entrega de los dorsales (en horario escolar) a todos los alumnos\/as que hayan entregado la hoja de inscripci\u00f3n. Para los mayores de 16 a\u00f1os (categor\u00eda OPEN) y menores de 3 a\u00f1os (categor\u00eda MINI-CARLITOS), la inscripci\u00f3n y la entrega de dorsales se har\u00e1 el mismo d\u00eda de la carrera, 30 minutos antes de que se comienza su prueba, en la mesa de inscripci\u00f3n (situada junta a la puerta de entrada del Colegio).\u00a0Tambi\u00e9n podr\u00e1n apuntarse, ese mismo d\u00eda, todas aquellas personas que por cualquier motivo no tengan dorsal, acudiendo al lugar indicado con 30 minutos de antelaci\u00f3n. \u00a0<\/p>\n<p>Recordamos que habr\u00e1 trofeo para los 3 primeros clasificados de cada prueba, medallas del 4\u00ba al 15\u00ba, premios (bolsa del corredor) donados por los patrocinadores del Cross, para todos los que participen; los participantes de la categor\u00eda CARLITOS, CARLI\u00d1OS, CARLOTES y POR LA INCLUSI\u00d3N tendr\u00e1n medallas todos; para la categor\u00eda MINI-CARLITOS habr\u00e1 un obsequio y un diploma.<\/p>\n<p>A continuaci\u00f3n pod\u00e9is ver un cuadro resumen con el HORARIO Y las CATEGOR\u00cdAS de la prueba.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent.fmad3-1.fna.fbcdn.net\/v\/t1.0-9\/13165969_1112273272163688_3874765371583578357_n.jpg?oh=059cca82d9f9c1e9dc33a721bd3999d2&amp;oe=57AD7E09\" alt=\"\" width=\"680\" height=\"337\" \/>\u00a0<\/p>\n<p>Agradecemos a nuestro patrocinadores una vez m\u00e1s su esfuerzo, para hacer realidad nuestro Cross.<\/p>\n<p>Gracias \u00d3ptica Lohade, Imprimizia, empresa de comedor Serunion, Centro Infantil Baby-Ling\u00fce, Asociaci\u00f3n S\u00famate A, Intersport, McDonalds, Cl\u00ednica Milenium Dental, Senoble Schreiber, Joma, Uniformes Anna, Restaurante San Marun, Cl\u00ednica Novofisio, Viajes Marbel, Diario Deportivo Campeones de Aranjuez y Psiclog\u00eda Teresa Hernando.<\/p>\n<p>\u00a1ANIMOS A TODOS\/AS A PARTICIPAR EN NUESTRO VII CROSS!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el aplazamiento del Cross, el domingo 8 de mayo, por lluvia; este s\u00e1bado 14 de mayo (y despu\u00e9s de una semana m\u00e1s de entrenamiento y preparaci\u00f3n) se va a celebrar el VII Cross Escolar Urbano del \u00abColegio Carlos III\u00bb. La Asociaic\u00f3n de Madres y Padres de Alumnos Colegio Carlos III invita a todas las &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/05\/12\/vii-cross-escolar-urbano-colegio-carlos-iii-sabado-14-de-mayo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVII CROSS ESCOLAR URBANO COLEGIO CARLOS III (s\u00e1bado 14 de mayo)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-981","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Tras el aplazamiento del Cross, el domingo 8 de mayo, por lluvia; este s\u00e1bado 14 de mayo (y despu\u00e9s de una semana m\u00e1s de entrenamiento y preparaci\u00f3n) se va a celebrar el VII Cross Escolar Urbano del \u00abColegio Carlos III\u00bb. La Asociaic\u00f3n de Madres y Padres de Alumnos Colegio Carlos III invita a todas las&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=981"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}