{"id":9873,"date":"2021-10-28T18:51:53","date_gmt":"2021-10-28T16:51:53","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9873"},"modified":"2021-10-28T18:51:53","modified_gmt":"2021-10-28T16:51:53","slug":"crosses-escolares-temporada-2021-22","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/10\/28\/crosses-escolares-temporada-2021-22\/","title":{"rendered":"CROSSES ESCOLARES \u00a0TEMPORADA 2021-22\u00a0"},"content":{"rendered":"<p class=\"x_MsoNormal\">Os informamos de las fechas y normas de los Crosses Escolares de oto\u00f1o.<\/p>\n<p class=\"x_MsoNormal\">Las fechas son:<\/p>\n<table class=\"x_MsoTableGrid\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"207\">\n<p class=\"x_MsoNormal\" align=\"center\"><b>FECHA\u00a0<\/b><\/p>\n<\/td>\n<td valign=\"top\" width=\"248\">\n<p class=\"x_MsoNormal\" align=\"center\"><b>CROSS\u00a0<\/b><\/p>\n<\/td>\n<td valign=\"top\" width=\"243\">\n<p class=\"x_MsoNormal\" align=\"center\"><b>LUGAR\u00a0<\/b><\/p>\n<\/td>\n<td valign=\"top\" width=\"151\">\n<p class=\"x_MsoNormal\" align=\"center\"><b>HORARIO\u00a0<\/b><\/p>\n<\/td>\n<td valign=\"top\" width=\"283\">\n<p class=\"x_MsoNormal\" align=\"center\"><b>ORGANIZADOR\u00a0<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"207\">\n<p class=\"x_MsoNormal\">S\u00e1bado 6 de noviembre<\/p>\n<\/td>\n<td valign=\"top\" width=\"248\">\n<p class=\"x_MsoNormal\">Loyola<\/p>\n<\/td>\n<td valign=\"top\" width=\"243\">\n<p class=\"x_MsoNormal\">Estadio El Deleite<\/p>\n<\/td>\n<td valign=\"top\" width=\"151\">\n<p class=\"x_MsoNormal\" align=\"center\">10:30<\/p>\n<\/td>\n<td valign=\"top\" width=\"283\">\n<p class=\"x_MsoNormal\">Colegio Salesiano Loyola y Delegaci\u00f3n de Deportes<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"207\">\n<p class=\"x_MsoNormal\">S\u00e1bado 13 de noviembre<\/p>\n<\/td>\n<td valign=\"top\" width=\"248\">\n<p class=\"x_MsoNormal\">Santiago<\/p>\n<\/td>\n<td valign=\"top\" width=\"243\">\n<p class=\"x_MsoNormal\">Estadio El Deleite<\/p>\n<\/td>\n<td valign=\"top\" width=\"151\">\n<p class=\"x_MsoNormal\" align=\"center\">10:30<\/p>\n<\/td>\n<td valign=\"top\" width=\"283\">\n<p class=\"x_MsoNormal\">Colegio Ap\u00f3stol Santiago<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"207\">\n<p class=\"x_MsoNormal\">S\u00e1bado 20 de noviembre<\/p>\n<\/td>\n<td valign=\"top\" width=\"248\">\n<p class=\"x_MsoNormal\">Raso de la Estrella<\/p>\n<\/td>\n<td valign=\"top\" width=\"243\">\n<p class=\"x_MsoNormal\">Raso de la Estrella<\/p>\n<\/td>\n<td valign=\"top\" width=\"151\">\n<p class=\"x_MsoNormal\" align=\"center\">10:30<\/p>\n<\/td>\n<td valign=\"top\" width=\"283\">\n<p class=\"x_MsoNormal\">Delegaci\u00f3n de Deportes<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La organizaci\u00f3n no ha facilitado horario. La prueba comienza a las 10:30 con los mayores. (Cadetes, alumnos\/as de 3\u00ba y 4\u00ba de ESO).<\/p>\n<p class=\"x_MsoNormal\"><b>Normas<\/b>:<\/p>\n<p class=\"x_MsoNormal\">En los Crosses realizados en el Estadio del Deleite, est\u00e1 permitida la asistencia de p\u00fablico. La entrada se realizar\u00e1 entre los intervalos de inicio de las diferentes disciplinas y categor\u00edas. Se debe respetar la distancia de seguridad una vez est\u00e9n ubicados en las gradas. Se recomienda el uso de mascarilla y tener las precauciones higi\u00e9nico-sanitarias recomendadas para el COVID-19.<\/p>\n<p class=\"x_MsoNormal\">En el Cross del Raso de la Estrella, el p\u00fablico deber\u00e1 mantener la distancia de seguridad, se recomienda el uso de la mascarilla y tener las precauciones higi\u00e9nico-sanitarias recomendadas para el COVID-19.<\/p>\n<p class=\"x_MsoNormal\"><b>Entrega de medallas<\/b>:<\/p>\n<p class=\"x_MsoNormal\">Se dar\u00e1n\u00a0<b>medallas<\/b>\u00a0a los\u00a0<b>12 primeros<\/b>\u00a0por carrera y ser\u00e1n entregadas a medida que los participantes vayan\u00a0<b>cruzando la l\u00ednea de meta<\/b>. (No se realizar\u00e1 ceremonia final de entrega de medallas).<\/p>\n<p class=\"x_MsoNormal\"><b>Inscripciones<\/b>:<\/p>\n<p class=\"x_MsoNormal\">Podr\u00e1n inscribirse los alumnos\/as nacidos desde el a\u00f1o 2015 en adelante (solo Educaci\u00f3n Primaria, Educaci\u00f3n infantil no), hay que enviar el <b>nombre y apellidos del alumno<\/b>\u00a0y el\u00a0<b>curso<\/b>\u00a0al mail\u00a0<a href=\"mailto:ampacarlosiii@hotmail.es\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">ampacarlosiii@hotmail.es<\/a><\/p>\n<p class=\"x_MsoNormal\">El dorsal se entregar\u00e1 el d\u00eda anterior a la carrera en el colegio y ser\u00e1 v\u00e1lido para las tres carreras.<\/p>\n<p class=\"x_MsoNormal\">Los recorridos de los 3 Cross ser\u00e1n los que adjuntamos en el correo.<\/p>\n<p class=\"x_MsoNormal\">\u00a1ANIMAROS Y PARTICIPAR!<\/p>\n<p>A continuaci\u00f3n os dejamos los recorridos, distancias y categor\u00edas de los Cross:<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/10\/cross-deleite-recorrido-LOYOLA-Y-SANTIAGO-1.pdf\">RECORRIDOS CROSS ESTADIO DELEITE (LOYOLA Y SANTIAGO) S\u00c1BADOS 6 Y 13 DE NOVIEMBRE<\/a><\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/10\/Recorridos-Raso-de-la-estrella-1.pdf\">RECORRIDOS RASO DE LA ESTRELLA 20 DE NOVIEMBRE<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Y por \u00faltimo os adjuntamos la normativa espec\u00edfica de los crosses escolares enviada por la Delegaci\u00f3n de Deportes del Ayuntamiento de Aranjuez:<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2021\/10\/NORMATIVA-ESPECIFICA-DE-LOS-CROSSES-ESCOLARES-DELEGACION-DE-DEPORTES-1.pdf\">NORMATIVA ESPEC\u00cdFICA DE LOS CROSSES ESCOLARES &#8211; DELEGACI\u00d3N DE DEPORTES<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os informamos de las fechas y normas de los Crosses Escolares de oto\u00f1o. Las fechas son: FECHA\u00a0 CROSS\u00a0 LUGAR\u00a0 HORARIO\u00a0 ORGANIZADOR\u00a0 S\u00e1bado 6 de noviembre Loyola Estadio El Deleite 10:30 Colegio Salesiano Loyola y Delegaci\u00f3n de Deportes S\u00e1bado 13 de noviembre Santiago Estadio El Deleite 10:30 Colegio Ap\u00f3stol Santiago S\u00e1bado 20 de noviembre Raso de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/10\/28\/crosses-escolares-temporada-2021-22\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCROSSES ESCOLARES \u00a0TEMPORADA 2021-22\u00a0\u00ab<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,14],"tags":[],"post_folder":[],"class_list":["post-9873","post","type-post","status-publish","format-standard","hentry","category-ampa","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/ampa\/\" rel=\"category tag\">AMPA<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Os informamos de las fechas y normas de los Crosses Escolares de oto\u00f1o. Las fechas son: FECHA\u00a0 CROSS\u00a0 LUGAR\u00a0 HORARIO\u00a0 ORGANIZADOR\u00a0 S\u00e1bado 6 de noviembre Loyola Estadio El Deleite 10:30 Colegio Salesiano Loyola y Delegaci\u00f3n de Deportes S\u00e1bado 13 de noviembre Santiago Estadio El Deleite 10:30 Colegio Ap\u00f3stol Santiago S\u00e1bado 20 de noviembre Raso de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9873"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9873\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9873"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}