{"id":994,"date":"2016-05-20T11:48:10","date_gmt":"2016-05-20T11:48:10","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=994"},"modified":"2016-05-20T11:48:10","modified_gmt":"2016-05-20T11:48:10","slug":"omnia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/05\/20\/omnia\/","title":{"rendered":"OMNIA"},"content":{"rendered":"<p>Omnia es un musical, que los ni\u00f1os y ni\u00f1as de 6\u00ba estamos organizando para nuestra graduaci\u00f3n. Es un representaci\u00f3n que habla de la naturaleza y de como cuidar el planeta. Se representar\u00e1 el 20 de junio a las 19:00 horas, en el colegio. Hay m\u00fasica en directo, bailes, teatro en vivo. Empezamos a ensayar en septiembre, es una obra para peque\u00f1os y mayores, con la queremos poner punto y final a nuestra estancia en el colegio y a la contaminaci\u00f3n.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/scontent.fmad3-1.fna.fbcdn.net\/v\/t1.0-9\/13244616_1117050951685920_2230208391573477769_n.jpg?oh=cd8b8f10cc7468c3431e3787d6a90e95&amp;oe=579CEA69\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Omnia es un musical, que los ni\u00f1os y ni\u00f1as de 6\u00ba estamos organizando para nuestra graduaci\u00f3n. Es un representaci\u00f3n que habla de la naturaleza y de como cuidar el planeta. Se representar\u00e1 el 20 de junio a las 19:00 horas, en el colegio. Hay m\u00fasica en directo, bailes, teatro en vivo. Empezamos a ensayar en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2016\/05\/20\/omnia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abOMNIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-994","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Omnia es un musical, que los ni\u00f1os y ni\u00f1as de 6\u00ba estamos organizando para nuestra graduaci\u00f3n. Es un representaci\u00f3n que habla de la naturaleza y de como cuidar el planeta. Se representar\u00e1 el 20 de junio a las 19:00 horas, en el colegio. Hay m\u00fasica en directo, bailes, teatro en vivo. Empezamos a ensayar en&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=994"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/994\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=994"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}