{"id":9961,"date":"2021-11-11T13:07:53","date_gmt":"2021-11-11T11:07:53","guid":{"rendered":"https:\/\/colegiocarlosiii.com\/?p=9961"},"modified":"2021-11-11T13:07:53","modified_gmt":"2021-11-11T11:07:53","slug":"convocatoria-4a-asamblea-pitufos-curso-2021-2022-17-de-noviembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/11\/11\/convocatoria-4a-asamblea-pitufos-curso-2021-2022-17-de-noviembre\/","title":{"rendered":"CONVOCATORIA 4\u00aa ASAMBLEA PITUFOS CURSO 2021-2022 (17 DE NOVIEMBRE)"},"content":{"rendered":"<p><strong>D\u00eda: mi\u00e9rcoles 17 de noviembre de 2021 Hora: 12:00 Lugar: <\/strong><\/p>\n<p><strong>Tronquitos (en caso de mal tiempo pabell\u00f3n)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Propuestas para Carlos III Happy Days.<\/li>\n<li>Recordatorio de medidas adoptadas por el Comit\u00e9 de Escuelas Sostenibles.<\/li>\n<li>Limpieza de patio y zonas comunes.<\/li>\n<li>Charlie Points: entrega de puntos y creaci\u00f3n de normas.<\/li>\n<li>Propuestas e ideas para la VI Semana de la Convivencia y d\u00eda de Navidad.<\/li>\n<li>Programaci\u00f3n XX Aniversario de la Declaraci\u00f3n de Aranjuez como Paisaje Cultural Patrimonio de la Humanidad.<\/li>\n<li>Ruegos y preguntas<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Es muy importante que los delegados\/as y representantes de las clases lleven sus aportaciones por escrito y consulten a sus compa\u00f1eros\/as los puntos que se van a tratar en la asamblea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00eda: mi\u00e9rcoles 17 de noviembre de 2021 Hora: 12:00 Lugar: Tronquitos (en caso de mal tiempo pabell\u00f3n) &nbsp; Propuestas para Carlos III Happy Days. Recordatorio de medidas adoptadas por el Comit\u00e9 de Escuelas Sostenibles. Limpieza de patio y zonas comunes. Charlie Points: entrega de puntos y creaci\u00f3n de normas. Propuestas e ideas para la VI &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2021\/11\/11\/convocatoria-4a-asamblea-pitufos-curso-2021-2022-17-de-noviembre\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCONVOCATORIA 4\u00aa ASAMBLEA PITUFOS CURSO 2021-2022 (17 DE NOVIEMBRE)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-9961","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"D\u00eda: mi\u00e9rcoles 17 de noviembre de 2021 Hora: 12:00 Lugar: Tronquitos (en caso de mal tiempo pabell\u00f3n) &nbsp; Propuestas para Carlos III Happy Days. Recordatorio de medidas adoptadas por el Comit\u00e9 de Escuelas Sostenibles. Limpieza de patio y zonas comunes. Charlie Points: entrega de puntos y creaci\u00f3n de normas. Propuestas e ideas para la VI&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=9961"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/9961\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=9961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=9961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=9961"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=9961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}