{"id":84,"count":168,"description":"","link":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/mec-category\/actividadenelcentro\/","name":"Actividad en el centro","slug":"actividadenelcentro","taxonomy":"mec_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/mec_category\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/mec_category"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/taxonomies\/mec_category"}],"wp:post_type":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/mec-events?mec_category=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}