{"id":5239,"date":"2024-05-30T14:10:08","date_gmt":"2024-05-30T12:10:08","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/?p=5239"},"modified":"2024-05-30T14:27:08","modified_gmt":"2024-05-30T12:27:08","slug":"menu-junio-2024","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/2024\/05\/30\/menu-junio-2024\/","title":{"rendered":"MEN\u00da JUNIO 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1024x724.jpg\" alt=\"\" class=\"wp-image-5241\" srcset=\"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1024x724.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-300x212.jpg 300w, https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-768x543.jpg 768w, https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1536x1086.jpg 1536w, https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon.jpg 1754w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Pincha en la imagen para ver las derivaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pincha en la imagen para ver las derivaciones.<\/p>\n","protected":false},"author":6,"featured_media":5242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[73],"post_folder":[],"class_list":["post-5239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacion","tag-menu"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",1754,1240,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",1754,1240,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",1754,1240,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-300x212.jpg",300,212,true],"large":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-1024x724.jpg",800,566,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",500,353,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-1536x1086.jpg",1536,1086,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",1754,1240,false],"onepress-blog-small":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-300x150.jpg",300,150,true],"onepress-small":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-480x300.jpg",480,300,true],"onepress-medium":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-640x400.jpg",640,400,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",360,255,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",339,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2024\/05\/Menu-junio-Cristobal-Colon-1.jpg",1754,1240,false]},"rttpg_author":{"display_name":"Secretaria cp cristobalcolon madrid","author_link":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/author\/cuenta_secretaria-cp-cristobalcolon-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/category\/alimentacion\/\" rel=\"category tag\">Alimentaci\u00f3n<\/a>","rttpg_excerpt":"Pincha en la imagen para ver las derivaciones.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=5239"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5239\/revisions"}],"predecessor-version":[{"id":5245,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5239\/revisions\/5245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/media\/5242"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=5239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=5239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=5239"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=5239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}