{"id":671,"date":"2015-10-23T19:39:00","date_gmt":"2015-10-23T19:39:00","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/?p=671"},"modified":"2020-07-22T19:50:39","modified_gmt":"2020-07-22T19:50:39","slug":"horario-de-atencion-a-familias","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/2015\/10\/23\/horario-de-atencion-a-familias\/","title":{"rendered":"Horario de atenci\u00f3n a familias"},"content":{"rendered":"\n<p>Les informamos que, durante el presente curso escolar, el horario de atenci\u00f3n a las familias se traslada a los<strong> martes (en horario de 12:30 h. a 13:30 h.)<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/img.freepik.com\/vector-gratis\/personajes-diseno-plano-que-gestionan-tiempo_23-2148274068.jpg?size=626&amp;ext=jpg&amp;ga=GA1.2.1050935372.1595446614\" alt=\"\" \/><figcaption><a href=\"https:\/\/www.freepik.es\/fotos-vectores-gratis\/calendario\">Vector de Calendario creado por freepik &#8211; www.freepik.es<\/a><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les informamos que, durante el presente curso escolar, el horario de atenci\u00f3n a las familias se traslada a los martes (en horario de 12:30 h. a 13:30 h.).<\/p>\n","protected":false},"author":2,"featured_media":675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[4],"post_folder":[],"class_list":["post-671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familias","tag-familias"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",2560,1707,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",2560,1707,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",2560,1707,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-300x200.jpg",300,200,true],"large":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-1024x683.jpg",800,534,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",300,200,false],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",500,333,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",474,316,false],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",391,260,false],"tileview":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",300,200,false],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-2048x1365.jpg",2048,1365,true],"onepress-blog-small":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-300x150.jpg",300,150,true],"onepress-small":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-480x300.jpg",480,300,true],"onepress-medium":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-640x400.jpg",640,400,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",272,182,false],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",360,240,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",360,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/\/wp-content\/uploads\/cp.cristobalcolon.madrid\/2020\/07\/2785427-scaled.jpg",2560,1707,false]},"rttpg_author":{"display_name":"Coordinador TIC CEIP Crist\u00f3bal Col\u00f3n","author_link":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/author\/cuenta_tic-cp-cristobalcolon-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/category\/familias\/\" rel=\"category tag\">Familias<\/a>","rttpg_excerpt":"Les informamos que, durante el presente curso escolar, el horario de atenci\u00f3n a las familias se traslada a los martes (en horario de 12:30 h. a 13:30 h.).","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=671"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/671\/revisions"}],"predecessor-version":[{"id":673,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/671\/revisions\/673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/media\/675"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=671"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.cristobalcolon.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}