{"id":637,"date":"2022-04-20T12:29:44","date_gmt":"2022-04-20T10:29:44","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/?p=637"},"modified":"2022-04-20T12:30:47","modified_gmt":"2022-04-20T10:30:47","slug":"revista-nuestro-barco-segundo-trimestre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/2022\/04\/20\/revista-nuestro-barco-segundo-trimestre\/","title":{"rendered":"Revista \u00abnuestro barco\u00bb- Segundo Trimestre"},"content":{"rendered":"<p>\u00a1Ya est\u00e1 disponible la revista \u00abNuestro Barco\u00bb del segundo trimestre! En ella pod\u00e9is ver todo lo que hemos hecho estos primero meses del 2022.<br \/>\u00a1Esperamos que la disfrut\u00e9is!<\/p>\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/mediateca.educa.madrid.org\/documentos\/at2av86eoz6duk1w\/fs\" width=\"100%\" height=\"387\" frameborder=\"0\" scrolling=\"no\" style=\"border:0;overflow:hidden\" allowfullscreen><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ya est\u00e1 disponible la revista \u00abNuestro Barco\u00bb del segundo trimestre!<\/p>\n","protected":false},"author":2,"featured_media":638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"post_folder":[],"class_list":["post-637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curso-2021-2022"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-300x169.jpg",300,169,true],"large":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",640,360,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",500,281,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",360,203,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",360,203,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/\/wp-content\/uploads\/cp.hermanospinzon.madrid\/2022\/04\/revista2trim2021.jpg",800,450,false]},"rttpg_author":{"display_name":"tic.cp.hermanospinzon.madrid","author_link":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/author\/cuenta_tic-cp-hermanospinzon-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/category\/curso-2021-2022\/\" rel=\"category tag\">Curso 2021-2022<\/a>","rttpg_excerpt":"\u00a1Ya est\u00e1 disponible la revista \"Nuestro Barco\" del segundo trimestre!","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=637"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/637\/revisions"}],"predecessor-version":[{"id":641,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/posts\/637\/revisions\/641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/media\/638"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=637"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanospinzon.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}