{"id":2233,"date":"2024-12-02T11:53:13","date_gmt":"2024-12-02T10:53:13","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/?p=2233"},"modified":"2024-12-02T11:53:13","modified_gmt":"2024-12-02T10:53:13","slug":"escolares-solidarios-recogida-de-alimentos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/2024\/12\/02\/escolares-solidarios-recogida-de-alimentos\/","title":{"rendered":"ESCOLARES SOLIDARIOS: Recogida de alimentos"},"content":{"rendered":"<p>Estimadas familias,<\/p>\n<p>Como cada a\u00f1o, colaboramos con el Ayuntamiento de Humanes de Madrid para la recogida de alimentos que ir\u00e1n destinados al Comedor Social del municipio y a C\u00e1ritas Humanes.<\/p>\n<p>Todo el que quiera colaborar podr\u00e1 traer su aportaci\u00f3n hasta el d\u00eda 13, en una bolsa que el alumnado depositar\u00e1 en las cajas que hemos colocado en los pabellones.<\/p>\n<p>Gracias de antemano por vuestra colaboraci\u00f3n.<a href=\"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/?attachment_id=2234\" rel=\"attachment wp-att-2234\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2234 aligncenter\" src=\"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled.jpg\" alt=\"\" width=\"595\" height=\"842\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias, Como cada a\u00f1o, colaboramos con el Ayuntamiento de Humanes de Madrid para la recogida de alimentos que ir\u00e1n destinados al Comedor Social del municipio y a C\u00e1ritas Humanes. &#8230;<\/p>\n","protected":false},"author":3,"featured_media":2234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienvenidos-al-c-e-i-p-hermanos-tora"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",799,629,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",799,629,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",799,629,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-300x236.jpg",300,236,true],"large":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-724x1024.jpg",724,1024,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-1086x1536.jpg",1086,1536,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-1448x2048.jpg",1448,2048,true],"onepress-blog-small":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-300x150.jpg",300,150,true],"onepress-small":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-480x300.jpg",480,300,true],"onepress-medium":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-640x400.jpg",640,400,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",360,283,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",305,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/\/wp-content\/uploads\/cp.hermanostora.humanes\/2024\/12\/escolares-solidarios-scaled-e1733136729738.jpg",799,629,false]},"rttpg_author":{"display_name":"cp.hermanostora.humanes","author_link":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/author\/cuenta_cp-hermanostora-humanes\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/category\/bienvenidos-al-c-e-i-p-hermanos-tora\/\" rel=\"category tag\">BIENVENIDOS AL C.E.I.P. HERMANOS TOR\u00c1<\/a>","rttpg_excerpt":"Estimadas familias, Como cada a\u00f1o, colaboramos con el Ayuntamiento de Humanes de Madrid para la recogida de alimentos que ir\u00e1n destinados al Comedor Social del municipio y a C\u00e1ritas Humanes. ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/posts\/2233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/comments?post=2233"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/posts\/2233\/revisions"}],"predecessor-version":[{"id":2236,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/posts\/2233\/revisions\/2236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/media\/2234"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/media?parent=2233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/categories?post=2233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/tags?post=2233"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.hermanostora.humanes\/index.php\/wp-json\/wp\/v2\/post_folder?post=2233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}