{"id":232,"date":"2020-10-27T10:31:47","date_gmt":"2020-10-27T10:31:47","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/?p=232"},"modified":"2021-03-08T07:58:09","modified_gmt":"2021-03-08T07:58:09","slug":"tablets","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/2020\/10\/27\/tablets\/","title":{"rendered":"FUTUROS CIENT\u00cdFICOS"},"content":{"rendered":"\n<p>El colegio apuesta por la promoci\u00f3n del inter\u00e9s hacia la investigaci\u00f3n de sus alumnos, con la celebraci\u00f3n de la Semana de la Ciencia. El principal objetivo es capacitar a los ni\u00f1os y ni\u00f1as para desenvolverse, ayudarle a pensar cr\u00edticamente, resolver problemas y entender mejor el mundo en el que viven.<\/p>\n\n\n\n<p>Es muy interesante descubrir c\u00f3mo ni\u00f1os tan peque\u00f1os, aplicando m\u00e9todos estrictamente experimentales, modifican sus ideas previas y adquieren una visi\u00f3n cient\u00edfica de la naturaleza.<\/p>\n\n\n\n<p>Durante una semana, \u00fanicamente dedicamos las clases a la investigaci\u00f3n. <\/p>\n\n\n\n<p>\u00bfQu\u00e9 es lo que investigamos? Tomando como tema principal el a\u00f1o internacional de la Unesco, buscamos informaci\u00f3n sobre el mismo, preparamos experimentos para llevar a cabo con nuestros alumnos y nos ponemos en contacto con distintas entidades especialistas en esta tem\u00e1tica para que realicen talleres y charlas de divulgaci\u00f3n cient\u00edfica con los ni\u00f1os, que son dirigidos por un cient\u00edfico o un especialista en la materia. Adem\u00e1s, analizamos los hechos hist\u00f3ricos ocurridos y los personajes m\u00e1s representativos que llevaron a cabo estos experimentos en el pasado o en el presente, creando una l\u00ednea del tiempo.<\/p>\n\n\n\n<p>Hay una frase del&nbsp;fil\u00f3sofo chino Confuncio que describe a la perfecci\u00f3n las ventajas de la aplicaci\u00f3n del m\u00e9todo cient\u00edfico al aprendizaje de cualquier disciplina:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong>\u201cMe lo contaron y lo olvid\u00e9. <\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong>Lo vi y lo entend\u00ed. Lo experiment\u00e9 y lo aprend\u00ed\u201d.<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"863\" height=\"554\" src=\"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2021\/03\/fotito.png\" alt=\"\" class=\"wp-image-365\" srcset=\"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2021\/03\/fotito.png 863w, https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2021\/03\/fotito-300x193.png 300w, https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2021\/03\/fotito-768x493.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El colegio apuesta por la promoci\u00f3n del inter\u00e9s hacia la investigaci\u00f3n de sus alumnos, con la celebraci\u00f3n de la Semana de la Ciencia. El principal objetivo es capacitar a los ni\u00f1os y ni\u00f1as para desenvolverse, ayudarle a pensar cr\u00edticamente, resolver problemas y entender mejor el mundo en el que viven. Es muy interesante descubrir c\u00f3mo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/2020\/10\/27\/tablets\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFUTUROS CIENT\u00cdFICOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"post_folder":[],"class_list":["post-232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slideshow-parte-inferior-de-slideshow"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"medium":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"large":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"tileview":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/\/wp-content\/uploads\/cp.mejico.madrid\/2020\/10\/3.png",64,64,false]},"rttpg_author":{"display_name":"tic.cp.mejico.madrid","author_link":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/author\/cuenta_tic-cp-mejico-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/category\/slideshow-parte-inferior-de-slideshow\/\" rel=\"category tag\">Slideshow (Parte Inferior de Slideshow)<\/a>","rttpg_excerpt":"El colegio apuesta por la promoci\u00f3n del inter\u00e9s hacia la investigaci\u00f3n de sus alumnos, con la celebraci\u00f3n de la Semana de la Ciencia. El principal objetivo es capacitar a los ni\u00f1os y ni\u00f1as para desenvolverse, ayudarle a pensar cr\u00edticamente, resolver problemas y entender mejor el mundo en el que viven. Es muy interesante descubrir c\u00f3mo&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"predecessor-version":[{"id":367,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/posts\/232\/revisions\/367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/media\/226"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=232"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.mejico.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}