{"id":748,"date":"2021-03-03T09:32:30","date_gmt":"2021-03-03T09:32:30","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/?p=748"},"modified":"2021-03-04T07:42:27","modified_gmt":"2021-03-04T07:42:27","slug":"programa-de-cooperacion-territorial-proa-20-21","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/2021\/03\/03\/programa-de-cooperacion-territorial-proa-20-21\/","title":{"rendered":"Programa de Cooperaci\u00f3n Territorial PROA+ 20-21"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center\">Nuestro centro ha sido seleccionado para participar en este Programa de Cooperaci\u00f3n Territorial, lo cual supondr\u00e1 una dotaci\u00f3n econ\u00f3mica que ayudar\u00e1 a compensar las carencias educativas y socioafectivas ocasionadas por la pandemia del Covid.<\/p>\n\n\n\n<p>Estos fondos ser\u00e1n destinados a la las siguientes actuaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>ACTUACIONES CON ALUMNOS:<ul><li>Talleres Medidas AntiCovid<\/li><li>Talleres de Seguridad en redes sociales e internet<\/li><li>Talleres de recuperaci\u00f3n emocional<\/li><li>Talleres de T\u00e9cnicas de relajaci\u00f3n<\/li><\/ul><\/li><li>ACTUACIONES PARA EL IMPULSO DE COMPETENCIAS DOCENTES<ul><li>Ponencias sobre recuperaci\u00f3n emocional<\/li><li>Ponencias Medidas AntiCovid<\/li><\/ul><\/li><li>ACTUACIONES DE ACOMPA\u00d1AMIENTO Y REFUERZO ESCOLAR<ul><li>Dos grupos de refuerzo por las tardes de marzo a junio<\/li><li>Un monitor de refuerzo en horario escolar de marzo a junio<\/li><\/ul><\/li><li>ACTUACIONES DE IMPULSO A LA IMPLICACI\u00d3N Y COLABORACI\u00d3N DE LAS FAMILIAS<ul><li>Talleres de Formaci\u00f3n en nuevas tecnolog\u00edas<\/li><li>Talleres de educaci\u00f3n emocional aplicada al cuidado de hij@s<\/li><li>Taller de aprendizaje de la lengua Castellana<\/li><li>Ponencias de medidas antiCovid<\/li><li>Ponencias sobre Redes Sociales y Ciberseguridad<\/li><\/ul><\/li><\/ul>\n<\/div><\/div>\n\n\n\n<p>Pincha en la imagen para acceder a toda la informaci\u00f3n en la web de la CAM.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.comunidad.madrid\/servicios\/educacion\/programa-cooperacion-territorial-proa-20-21\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"273\" src=\"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/\/wp-content\/uploads\/cp.miguelhernandez.fuenlabrada\/2021\/03\/image-1024x273.png\" alt=\"\" class=\"wp-image-750\" srcset=\"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/\/wp-content\/uploads\/cp.miguelhernandez.fuenlabrada\/2021\/03\/image-1024x273.png 1024w, https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/\/wp-content\/uploads\/cp.miguelhernandez.fuenlabrada\/2021\/03\/image-300x80.png 300w, https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/\/wp-content\/uploads\/cp.miguelhernandez.fuenlabrada\/2021\/03\/image-768x205.png 768w, https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/\/wp-content\/uploads\/cp.miguelhernandez.fuenlabrada\/2021\/03\/image.png 1338w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.comunidad.madrid\/sites\/default\/files\/img\/logos-simbolos\/imagen_ministerio_proa.jpg\" alt=\"Ministerio de Educaci\u00f3n y FP\" width=\"194\" height=\"83\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.comunidad.madrid\/sites\/default\/files\/doc\/servicios-sociales\/logo_comunidad_de_madrid_1.jpg\" alt=\"Logo Comunidad de Madrid para cooperaci\u00f3n\" width=\"70\" height=\"95\"\/><\/figure><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-group__inner-container\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro centro ha sido seleccionado para participar en este Programa de Cooperaci\u00f3n Territorial, lo cual supondr\u00e1 una dotaci\u00f3n econ\u00f3mica que ayudar\u00e1 a compensar las carencias educativas y socioafectivas ocasionadas por la pandemia del Covid. Estos fondos ser\u00e1n destinados a la las siguientes actuaciones: ACTUACIONES CON ALUMNOS: Talleres Medidas AntiCovid Talleres de Seguridad en redes sociales [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-748","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.miguelhernandez.fuenlabrada","author_link":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/author\/cuenta_cp-miguelhernandez-fuenlabrada\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Nuestro centro ha sido seleccionado para participar en este Programa de Cooperaci\u00f3n Territorial, lo cual supondr\u00e1 una dotaci\u00f3n econ\u00f3mica que ayudar\u00e1 a compensar las carencias educativas y socioafectivas ocasionadas por la pandemia del Covid. Estos fondos ser\u00e1n destinados a la las siguientes actuaciones: ACTUACIONES CON ALUMNOS: Talleres Medidas AntiCovid Talleres de Seguridad en redes sociales&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/posts\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/comments?post=748"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/posts\/748\/revisions"}],"predecessor-version":[{"id":752,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/posts\/748\/revisions\/752"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/media?parent=748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/categories?post=748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/tags?post=748"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.miguelhernandez.fuenlabrada\/index.php\/wp-json\/wp\/v2\/post_folder?post=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}