{"id":1747,"date":"2023-10-04T20:15:01","date_gmt":"2023-10-04T18:15:01","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/?p=1747"},"modified":"2025-01-17T09:34:04","modified_gmt":"2025-01-17T08:34:04","slug":"criterios-de-valoracion-para-elegir-la-empresa-de-comedor-para-el-curso-2023-24","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/2023\/10\/04\/criterios-de-valoracion-para-elegir-la-empresa-de-comedor-para-el-curso-2023-24\/","title":{"rendered":"Criterios de valoraci\u00f3n para elegir la empresa de comedor para el curso 2023\/24"},"content":{"rendered":"<div id=\"pl-1747\"  class=\"panel-layout\" ><div id=\"pg-1747-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><div dir=\"auto\">Hola, familias.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Esta ma\u00f1ana hemos tenido Consejo Escolar para valorar el sobre de la valoraci\u00f3n de las empresas que se presentan a la gesti\u00f3n del comedor durante el a\u00f1o escolar.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Sabemos que esto es algo que concierne a muchas familias pues la alimentaci\u00f3n es una parte importante del desarrollo de vuestros hijos e hijas. Por ello, os hacemos llegar informaci\u00f3n sobre los diferentes puntos que facilita la Consejer\u00eda de Educaci\u00f3n para que el equipo directivo del centro realice la valoraci\u00f3n pertinente.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Pod\u00e9is consultar los puntos en el archivo que encontrar\u00e9is haciendo clic sobre estas palabras.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><h3 class=\"widget-title\">1. Plan de coordinaci\u00f3n del personal de la empresa con la direcci\u00f3n del centro.<\/h3>\t\t\t<div class=\"textwidget\"><\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-2-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"2\" ><h3 class=\"widget-title\">Apartado<\/h3>\t\t\t<div class=\"textwidget\"><p>1.1. Grado de adecuaci\u00f3n del Plan de Coordinaci\u00f3n (m\u00e1ximo 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-2-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"3\" ><h3 class=\"widget-title\">Criterio de valoraci\u00f3n<\/h3>\t\t\t<div class=\"textwidget\"><p>Valoraci\u00f3n de la estructura, presentaci\u00f3n y contenido del Plan de Coordinaci\u00f3n. (Hasta 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-3-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"4\" >\t\t\t<div class=\"textwidget\"><p>1.2.\u00a0 Descripci\u00f3n de indicadores: previsi\u00f3n de reuniones de seguimiento y coordinaci\u00f3n entre la empresa y el centro, existencia o previsi\u00f3n de coordinador espec\u00edfico para cada centro por parte de la empresa,\u00a0 protocolos de recogida de informaci\u00f3n de los distintos tipos de incidencias, liquidaci\u00f3n y facturaci\u00f3n econ\u00f3mica, calendario y entrega de suministros. (M\u00e1ximo 2 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-3-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"5\" >\t\t\t<div class=\"textwidget\"><p>Previsi\u00f3n en el Plan de Coordinaci\u00f3n de reuniones de seguimiento y coordinaci\u00f3n empresa \/centro. (Hasta 0,25 puntos)<\/p>\n<p>Existencia de una propuesta de calendario concreto de dicho seguimiento. (Hasta 0,25 puntos)<\/p>\n<p>Previsi\u00f3n de la figura de coordinador espec\u00edfico para el centro. (Hasta 0,5 puntos)<\/p>\n<p>Existencia de protocolos de recogida de informaci\u00f3n. (Hasta 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-4-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"6\" ><h3 class=\"widget-title\">2. Propuesta de actividades en los periodos anterior y posterior a la comida y aportaci\u00f3n, en su caso, de material de apoyo necesario para su desarrollo.<\/h3>\t\t\t<div class=\"textwidget\"><\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-5\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-5-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"7\" ><h3 class=\"widget-title\">Apartado<\/h3>\t\t\t<div class=\"textwidget\"><p>2.1. Propuesta de actividades de recreo, juego y tiempo libre orientadas a la mejora de la convivencia. Se presentar\u00e1, al menos, una programaci\u00f3n b\u00e1sica trimestral. (M\u00e1ximo 8 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-5-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-5-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"8\" ><h3 class=\"widget-title\">Criterio de valoraci\u00f3n<\/h3>\t\t\t<div class=\"textwidget\"><p>Evaluaci\u00f3n de la programaci\u00f3n trimestral de actividades: estructura, presentaci\u00f3n, definici\u00f3n de objetivos, viabilidad. (Hasta 6 puntos)<\/p>\n<p>Existencia de actividades que promuevan la convivencia. (Hasta 1 punto)<\/p>\n<p>Existencia de actividades que promuevan la convivencia medioambiental. (Hasta 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-6\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-6-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"9\" >\t\t\t<div class=\"textwidget\"><p>2.2. Calidad, variedad y adecuaci\u00f3n de las actividades a las distintas edades y a los alumnos con necesidades espec\u00edficas de apoyo educativo. (M\u00e1ximo 8 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-6-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-6-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"10\" >\t\t\t<div class=\"textwidget\"><p>Evaluaci\u00f3n de la calidad de las actividades. (Hasta 2 puntos)<\/p>\n<p>Adaptaci\u00f3n de las actividades a las distintas edades. Indicaci\u00f3n de edad recomendada para cada actividad o adaptaci\u00f3n de cada actividad seg\u00fan las distintas edades. (Hasta 2 puntos)<\/p>\n<p>Variedad de las actividades: deportivas, art\u00edsticas, medioambientales\u2026tanto al aire libre como en el interior. (Hasta 2 puntos)<\/p>\n<p>Inclusi\u00f3n en las actividades de los alumnos NEE. (Hasta 2 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-7\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-7-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"11\" >\t\t\t<div class=\"textwidget\"><p>2.3. Aportaci\u00f3n de material, en su caso, cuando sea necesario para todas o para algunas de las actividades propuestas. (Se presentar\u00e1, adem\u00e1s en cada ficha o propuesta de actividad, un resumen del material agrupado por su tipolog\u00eda y coste estimado por a\u00f1o). (M\u00e1ximo 4 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-7-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-7-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"12\" >\t\t\t<div class=\"textwidget\"><p>Indicaci\u00f3n del material necesario en cada una de las actividades propuestas. (Hasta 1 punto)<\/p>\n<p>Compromiso por parte de la empresa de aportaci\u00f3n de dicho material. (Hasta 1 punto)<\/p>\n<p>Presentaci\u00f3n de documentaci\u00f3n de la estimaci\u00f3n del coste del material. (Hasta 1 punto, seg\u00fan coste)<\/p>\n<p>Utilizaci\u00f3n de materiales sostenibles y ecol\u00f3gicos. (Hasta 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-8\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-8-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"13\" ><h3 class=\"widget-title\">3. Mejoras en la prestaci\u00f3n del servicio.<\/h3>\t\t\t<div class=\"textwidget\"><\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-9\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-9-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-9-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"14\" ><h3 class=\"widget-title\">Apartado<\/h3>\t\t\t<div class=\"textwidget\"><p>3.1. Oferta de men\u00fas singulares por\u00a0 h\u00e1bitos culturales y\/o religiosos. (M\u00e1ximo 2 puntos)<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-9-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-9-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"15\" ><h3 class=\"widget-title\">Criterio de valoraci\u00f3n<\/h3>\t\t\t<div class=\"textwidget\"><p>Presentaci\u00f3n por parte de la empresa de una propuesta de men\u00fas para los diferentes h\u00e1bitos culturales y\/o religiosos. (Hasta 1 punto)<\/p>\n<p>Valoraci\u00f3n de la diversidad de la propuesta y adecuaci\u00f3n de la oferta presentada a la diversidad de necesidades del centro. (Hasta 1 punto)<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-10\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-10-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-10-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"16\" >\t\t\t<div class=\"textwidget\"><p>3.2. Plan de gesti\u00f3n de residuos s\u00f3lidos urbanos adaptado a la realidad del centro. (M\u00e1ximo 2 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-10-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-10-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"17\" >\t\t\t<div class=\"textwidget\"><p>Evaluaci\u00f3n del plan de residuos presentado por la empresa. Se debe valorar positivamente que contenga actuaciones para: eliminar la totalidad de residuos generados, reducir la cantidad de residuos y reducir el\u00a0 impacto medioambiental. (Hasta 1,5 puntos)<\/p>\n<p>Valoraci\u00f3n de la propuesta para adaptar ese plan a las circunstancias concretas del centro. (Hasta 0,5 puntos)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-11\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-11-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-11-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"18\" >\t\t\t<div class=\"textwidget\"><p>3.3. Jornada anual de puertas abiertas para las familias del centro. (M\u00e1ximo 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-1747-11-1\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-11-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"19\" >\t\t\t<div class=\"textwidget\"><p>Evaluaci\u00f3n de la planificaci\u00f3n de esta actividad presentada por la empresa. (Hasta 1 punto)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-1747-12\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1747-12-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1747-12-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"20\" >\t\t\t<div class=\"textwidget\"><p>El pr\u00f3ximo d\u00eda 16 de octubre tenemos un nuevo Consejo Escolar en el que valoraremos el sobre 2. Os seguiremos informando.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Hola, familias. Esta ma\u00f1ana hemos tenido Consejo Escolar para valorar el sobre de la valoraci\u00f3n de las empresas que se presentan a la gesti\u00f3n del comedor durante el a\u00f1o escolar. Sabemos que esto es algo que concierne a muchas familias pues la alimentaci\u00f3n es una parte importante del desarrollo de vuestros hijos e hijas. Por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,11,6],"tags":[],"post_folder":[],"class_list":["post-1747","post","type-post","status-publish","format-standard","hentry","category-funcionamiento-del-cole","category-secretaria","category-tablon-de-anuncios"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"tic.cp.montelindo.bustarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/author\/cuenta_tic-cp-montelindo-bustarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/category\/informacion-util\/funcionamiento-del-cole\/\" rel=\"category tag\">Funcionamiento del cole<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/category\/secretaria\/\" rel=\"category tag\">Secretar\u00eda<\/a> <a href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/category\/tablon-de-anuncios\/\" rel=\"category tag\">Tabl\u00f3n de anuncios<\/a>","rttpg_excerpt":"Hola, familias. Esta ma\u00f1ana hemos tenido Consejo Escolar para valorar el sobre de la valoraci\u00f3n de las empresas que se presentan a la gesti\u00f3n del comedor durante el a\u00f1o escolar. Sabemos que esto es algo que concierne a muchas familias pues la alimentaci\u00f3n es una parte importante del desarrollo de vuestros hijos e hijas. Por&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=1747"}],"version-history":[{"count":8,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1747\/revisions"}],"predecessor-version":[{"id":1755,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1747\/revisions\/1755"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=1747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=1747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=1747"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=1747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}