{"id":2120,"date":"2024-05-23T12:20:13","date_gmt":"2024-05-23T10:20:13","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/?p=2120"},"modified":"2025-01-17T08:56:12","modified_gmt":"2025-01-17T07:56:12","slug":"ludoteca-mes-de-junio","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/2024\/05\/23\/ludoteca-mes-de-junio\/","title":{"rendered":"Ludoteca mes de junio"},"content":{"rendered":"\n<p>Hola, familias.<\/p>\n\n\n\n<p>Como bien sab\u00e9is, en el mes de junio las clases terminan a las 13:00 y el servicio de comedor, a las 15:00. Desde la AMPA han gestionado que durante este mes las familias que necesit\u00e9is servicio de ampliaci\u00f3n horaria por la tarde (ludoteca) pod\u00e1is disponer de \u00e9l.<\/p>\n\n\n\n<p>El precio ser\u00e1 de <strong>30\u20ac al mes en horario de 15:00 a 16:00<\/strong> y es necesario que apunt\u00e9is a vuestr@s hij@s antes del pr\u00f3ximo 24 de mayo. :&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/forms.gle\/hmLaQG2Z82Vp2dKF6\" target=\"_blank\">https:\/\/forms.gle\/hmLaQG2Z82Vp2dKF6<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSegqpd0Y1g2HjKMi4HkqSK8hEFV_t2JbxH_uSm6todM9RkL3Q\/viewform\" target=\"_blank\" rel=\"noreferrer noopener\">Inscr\u00edbele aqu\u00ed ANTES del 24 de mayo<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>NO PODREIS APUNTAR A VUESTRXS HIJXS AL SERVICIO MENSUAL DESPU\u00c9S DEL 24 DE MAYO.<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Asimismo, tambi\u00e9n se podr\u00e1 disfrutar del servicio por <strong>d\u00edas sueltos<\/strong>, teniendo estos un coste de <strong>5\u20ac previo pago en efectivo a la monitora<\/strong>. Ser\u00e1 necesario que llev\u00e9is el dinero justo porque la monitora no dispone de cambio. <\/p>\n\n\n\n<p>Para poder prestar el servicio es necesario un m\u00ednimo de 15 usuari@s. <\/p>\n\n\n\n<p>Tambi\u00e9n es necesario cumplir con los horarios: los peques que se queden a comedor tendr\u00e1n que ser <strong>recogidos antes de las 15:00<\/strong>, de lo contrario tendr\u00e1n que abonar los 5\u20ac del d\u00eda de ludoteca. Asimismo, los peques que vayan a ludoteca deben <strong>ser recogidos puntualmente<\/strong>.<\/p>\n\n\n\n<p>Ante cualquier duda pod\u00e9is dirigiros a Sandra, monitora del servicio.<\/p>\n\n\n\n<p>Os dejamos <a rel=\"noreferrer noopener\" href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/\/wp-content\/uploads\/cp.montelindo.bustarviejo\/2024\/05\/NORMAS-MONTELINDO-2023-2024-1.pdf\" target=\"_blank\">un documento con las normas de uso de la ludoteca<\/a>.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/\/wp-content\/uploads\/cp.montelindo.bustarviejo\/2024\/05\/NORMAS-MONTELINDO-2023-2024-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:689px\" aria-label=\"Incrustado de NORMAS MONTELINDO 2023 2024 (1).\"><\/object><a id=\"wp-block-file--media-cb4e1d90-e9b1-40ec-8860-1251322dc4c6\" href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/\/wp-content\/uploads\/cp.montelindo.bustarviejo\/2024\/05\/NORMAS-MONTELINDO-2023-2024-1.pdf\">NORMAS MONTELINDO 2023 2024 (1)<\/a><a href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/\/wp-content\/uploads\/cp.montelindo.bustarviejo\/2024\/05\/NORMAS-MONTELINDO-2023-2024-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-cb4e1d90-e9b1-40ec-8860-1251322dc4c6\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hola, familias. Como bien sab\u00e9is, en el mes de junio las clases terminan a las 13:00 y el servicio de comedor, a las 15:00. Desde la AMPA han gestionado que durante este mes las familias que necesit\u00e9is servicio de ampliaci\u00f3n horaria por la tarde (ludoteca) pod\u00e1is disponer de \u00e9l. El precio ser\u00e1 de 30\u20ac al [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"post_folder":[],"class_list":["post-2120","post","type-post","status-publish","format-standard","hentry","category-secretaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"tic.cp.montelindo.bustarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/author\/cuenta_tic-cp-montelindo-bustarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/category\/secretaria\/\" rel=\"category tag\">Secretar\u00eda<\/a>","rttpg_excerpt":"Hola, familias. Como bien sab\u00e9is, en el mes de junio las clases terminan a las 13:00 y el servicio de comedor, a las 15:00. Desde la AMPA han gestionado que durante este mes las familias que necesit\u00e9is servicio de ampliaci\u00f3n horaria por la tarde (ludoteca) pod\u00e1is disponer de \u00e9l. El precio ser\u00e1 de 30\u20ac al&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=2120"}],"version-history":[{"count":5,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2120\/revisions"}],"predecessor-version":[{"id":2126,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2120\/revisions\/2126"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=2120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=2120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=2120"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.montelindo.bustarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=2120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}