{"id":2219,"date":"2024-02-05T09:40:57","date_gmt":"2024-02-05T08:40:57","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/?p=2219"},"modified":"2024-06-14T10:26:04","modified_gmt":"2024-06-14T08:26:04","slug":"campana-solidaria-a-favor-de-la-casa-de-misericordia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/2024\/02\/05\/campana-solidaria-a-favor-de-la-casa-de-misericordia\/","title":{"rendered":"Campa\u00f1a solidaria a favor de la Casa de Misericordia"},"content":{"rendered":"<p>Los alumnos de 6\u00ba C han querido llevar a cabo un Proyecto de ayuda solidaria a favor de \u00abLa Casa de Misericordia\u00bb de nuestro municipio, sita en la Avda. de Madrid. Como sab\u00e9is\u2026<\/p>\n<ul>\n<li><a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/comunicando\/galeria-de-fotos\/\" target=\"_blank\" rel=\"noopener\">Enlace a la Galer\u00eda.<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de 6\u00ba C han querido llevar a cabo un Proyecto de ayuda solidaria a favor de \u00abLa Casa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"post_folder":[],"class_list":["post-2219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todos-los-cursos"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-300x150.jpg",300,150,true],"large":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",500,250,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",550,275,false],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",230,115,false],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",350,175,false],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",480,240,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",360,180,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",360,180,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/02\/campana.jpg",850,425,false]},"rttpg_author":{"display_name":"cp.navalazarza.sanagustin","author_link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/author\/cuenta_cp-navalazarza-sanagustin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/category\/todos-los-cursos\/\" rel=\"category tag\">Todos los cursos<\/a>","rttpg_excerpt":"Los alumnos de 6\u00ba C han querido llevar a cabo un Proyecto de ayuda solidaria a favor de \u00abLa Casa [&hellip;]","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/2219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/comments?post=2219"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/2219\/revisions"}],"predecessor-version":[{"id":2342,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/2219\/revisions\/2342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media\/2220"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media?parent=2219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/categories?post=2219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/tags?post=2219"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/post_folder?post=2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}